{"id":2480,"date":"2009-02-26T13:47:00","date_gmt":"2009-02-26T12:47:00","guid":{"rendered":"http:\/\/lyonelkaufmann.tumblr.com\/post\/81683284"},"modified":"2009-02-26T13:47:00","modified_gmt":"2009-02-26T12:47:00","slug":"wikipedia-via-lupe-der-satire-blog-crazy-houses-big","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/Blog\/2009\/02\/26\/wikipedia-via-lupe-der-satire-blog-crazy-houses-big\/","title":{"rendered":"wikipedia (via Lupe, der Satire-Blog: Crazy Houses (Big&#8230;"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/data.tumblr.com\/ogQbgaahckez6cevgmFqrdIao1_400.jpg\" \/><\/p>\n<p>wikipedia (via <a href=\"http:\/\/swiss-lupe.blogspot.com\/2009\/02\/crazy-houses-big-buildings-20-pics.html\">Lupe, der Satire-Blog: Crazy Houses (Big Buildings, 20 Pics)<\/a>)<\/p>\n<p>Photo du Stata center de F.Gehry (Merci \u00e0\u00a0<a href=\"http:\/\/twitter.com\/marco1003\">Marco Catroni<\/a> pour la r\u00e9f\u00e9rence)<\/p>\n","protected":false},"excerpt":{"rendered":"<p><img \/><\/p>\n<p>wikipedia (via <a href=\"http:\/\/swiss-lupe.blogspot.com\/2009\/02\/crazy-houses-big-buildings-20-pics.html\" target=\"_blank\">Lupe, der Satire-Blog: Crazy Houses (Big Buildings, 20 Pics)<\/a>)<\/p>\n<p>Photo du Stata center de F.Gehry (Merci \u00e0\u00a0<a href=\"http:\/\/twitter.com\/marco1003\" target=\"_blank\">Marco Catroni<\/a> pour la r\u00e9f\u00e9rence)<\/p>\n","protected":false},"author":1,"featured_media":13639,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"aside","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":3,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"fullscreen","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-2480","post","type-post","status-publish","format-aside","has-post-thumbnail","category-blogcafe-2","post_format-post-format-aside","entry"],"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/ogQbgaahckez6cevgmFqrdIao1_400.jpg?resize=400%2C304&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/ogQbgaahckez6cevgmFqrdIao1_400.jpg?resize=400%2C304&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/Blog\/author\/lyonelk\/"},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1qtF4-E0","jetpack-related-posts":[{"id":1475,"url":"https:\/\/lyonelkaufmann.ch\/Blog\/2008\/11\/21\/the-closest-thing-to-crazy-katie-melua\/","url_meta":{"origin":2480,"position":0},"title":"The Closest Thing To Crazy \u2013 Katie Melua","author":"Lyonel Kaufmann","date":"21 novembre 2008","format":"aside","excerpt":"Plus qu'une agr\u00e9able berceuse pour insomniaque, c'est Morph\u00e9e qui surgit. Que personne ne me r\u00e9veille, je veux aller au bout du r\u00eave\u2026 Related posts:Image du jour (04.11.2008) J\u2019adooooore ! En plus, elle vise en plein dans...Reportage photo: 40e Anniversaire du Blonay-Chamby Hier avait lieu la journ\u00e9e officielle du 40e anniversaire\u2026","rel":"","context":"Dans &quot;Blogcaf\u00e9&quot;","block_context":{"text":"Blogcaf\u00e9","link":"https:\/\/lyonelkaufmann.ch\/Blog\/category\/blogcafe-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/053.jpg?fit=480%2C360&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6934,"url":"https:\/\/lyonelkaufmann.ch\/Blog\/2013\/04\/12\/wikipedia-indispensable-outil-de-mise-en-reseau-de-la-connaissance-martin-grandjean\/","url_meta":{"origin":2480,"position":1},"title":"Wikip\u00e9dia, indispensable outil de mise en r\u00e9seau de la connaissance ? | Martin Grandjean","author":"Lyonel Kaufmann","date":"12 avril 2013","format":false,"excerpt":"Pour Martin Grandjean, historien \u00e0 l'Universit\u00e9 de Lausanne, Wikip\u00e9dia est un outil incontournable de sa vie professionnelle. Dans un entretien avec le tr\u00e8s wikip\u00e9dien Ludovic P\u00e9ron, il explique que Wikip\u00e9dia, bien que ne pouvant pas servir de caution scientifique \u00e0 une recherche, permet de gagner un temps tr\u00e8s pr\u00e9cieux par\u2026","rel":"","context":"Dans &quot;histoire&quot;","block_context":{"text":"histoire","link":"https:\/\/lyonelkaufmann.ch\/Blog\/category\/histoire-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/WikipediaDesktop.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/WikipediaDesktop.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/WikipediaDesktop.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/WikipediaDesktop.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/WikipediaDesktop.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":7596,"url":"https:\/\/lyonelkaufmann.ch\/Blog\/2012\/11\/01\/au-revoir-quebec-photo-du-jour\/","url_meta":{"origin":2480,"position":2},"title":"(Au) revoir Qu\u00e9bec |\u00a0Photo du jour","author":"Lyonel Kaufmann","date":"1 novembre 2012","format":"image","excerpt":"Ainsi, donc, lundi 29 octobre 2012, notre avion a d\u00e9coll\u00e9 de Montr\u00e9al \u00e0 18h10 pour Francfort. Encore une fois, la lune nous accompagne. La semaine a \u00e9t\u00e9 forte en \u00e9motion et en rencontres. Je me souviens\u00a0de ce pays si loin, si proche aux paysages format XXL, \u00e0 la lumi\u00e8re si\u2026","rel":"","context":"Dans &quot;Photo du jour&quot;","block_context":{"text":"Photo du jour","link":"https:\/\/lyonelkaufmann.ch\/Blog\/category\/photo-du-jour\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/DSC01060.jpg?fit=600%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/DSC01060.jpg?fit=600%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/DSC01060.jpg?fit=600%2C600&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":4198,"url":"https:\/\/lyonelkaufmann.ch\/Blog\/2010\/11\/07\/teachers-please-stop-prohibiting-the-use-of-wikipedia-zdnet\/","url_meta":{"origin":2480,"position":3},"title":"Teachers: Please stop prohibiting the use of Wikipedia | ZDNet","author":"Lyonel Kaufmann","date":"7 novembre 2010","format":"aside","excerpt":"However, Wikipedia deserves the same place in most modern assignments that Britannica did in most of ours. It was a starting point and a collection of additional references for our research. It gave us the general background we needed to dig further. Wikipedia does the same, with remarkable reliability given\u2026","rel":"","context":"Dans &quot;L'Expresso&quot;","block_context":{"text":"L'Expresso","link":"https:\/\/lyonelkaufmann.ch\/Blog\/category\/breves\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":15200,"url":"https:\/\/lyonelkaufmann.ch\/Blog\/2015\/09\/24\/lecture-le-printemps-des-barbares-de-jonas-luscher\/","url_meta":{"origin":2480,"position":4},"title":"Lecture : \u00ab Le Printemps des barbares \u00bb, de Jonas L\u00fcscher","author":"Lyonel Kaufmann","date":"24 septembre 2015","format":false,"excerpt":"Une autre proposition all\u00e9chante cette semaine de la s\u00e9lection du Monde des Livres. Le\u00a0livre\u00a0est disponible sous format broch\u00e9 ou pour votre liseuse (Kindle). A suivre\u2026 Roman. \u00ab\u00a0Le Printemps des barbares\u00a0\u00bb, de Jonas L\u00fcscher De jeunes financiers de la City f\u00eatent un mariage en Tunisie, avant la \u00ab\u00a0r\u00e9volution du jasmin\u00a0\u00bb, dans\u2026","rel":"","context":"Dans &quot;Blogcaf\u00e9&quot;","block_context":{"text":"Blogcaf\u00e9","link":"https:\/\/lyonelkaufmann.ch\/Blog\/category\/blogcafe-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/09\/4769210_6_1ab4_2015-09-23-e1cf49c-26559-1qxjuep_8b8446d2b52ecb15a06c6d98addd3167.jpg?fit=770%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/09\/4769210_6_1ab4_2015-09-23-e1cf49c-26559-1qxjuep_8b8446d2b52ecb15a06c6d98addd3167.jpg?fit=770%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/09\/4769210_6_1ab4_2015-09-23-e1cf49c-26559-1qxjuep_8b8446d2b52ecb15a06c6d98addd3167.jpg?fit=770%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/09\/4769210_6_1ab4_2015-09-23-e1cf49c-26559-1qxjuep_8b8446d2b52ecb15a06c6d98addd3167.jpg?fit=770%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":7017,"url":"https:\/\/lyonelkaufmann.ch\/Blog\/2013\/04\/21\/le-mont-rushmore-et-la-revanche-des-sioux-a-la-maison-blanche\/","url_meta":{"origin":2480,"position":5},"title":"Le Mont Rushmore et la revanche des Sioux | \u00c0 la Maison-Blanche","author":"Lyonel Kaufmann","date":"21 avril 2013","format":false,"excerpt":"En 1927, \u00e9merge, du granite du mont Rushmore, les visages de quatre des pr\u00e9sidents les plus implacables lors de ce qu\u2019on a appel\u00e9 les \u00ab Guerres Indiennes \u00bb. Pour les si\u00e8cles \u00e0 venir, au c\u0153ur m\u00eame des terres sacr\u00e9es du peuple sioux, les visages de George Washington, Thomas Jefferson, Abraham\u2026","rel":"","context":"Dans &quot;histoire&quot;","block_context":{"text":"histoire","link":"https:\/\/lyonelkaufmann.ch\/Blog\/category\/histoire-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/Sans-titre3.jpg?fit=431%2C262&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/ogQbgaahckez6cevgmFqrdIao1_400.jpg?fit=400%2C304&ssl=1","_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/posts\/2480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/comments?post=2480"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/posts\/2480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/media\/13639"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/media?parent=2480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/categories?post=2480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/tags?post=2480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}