{"id":2736,"date":"2010-04-21T08:15:30","date_gmt":"2010-04-21T07:15:30","guid":{"rendered":"http:\/\/lyonelkaufmann.ch\/histoire\/?p=2736"},"modified":"2010-04-21T08:15:30","modified_gmt":"2010-04-21T07:15:30","slug":"lhistoire-au-prisme-de-limage-mardi-27-avril-2010","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/Blog\/2010\/04\/21\/lhistoire-au-prisme-de-limage-mardi-27-avril-2010\/","title":{"rendered":"L&rsquo;histoire au prisme de l&rsquo;image (mardi 27 avril 2010)"},"content":{"rendered":"<p>Dans le cadre des deux modules destin\u00e9s aux \u00e9tudiant-e-s en histoire (Secondaire I et II) de la HEP Lausanne, nous organisons une demi-journ\u00e9e avec des intervenants ext\u00e9rieurs en relation avec la questions de l&rsquo;utilisation des images en histoire dans une perspective acad\u00e9mique et sous l&rsquo;angle de la recherche. Chacune des  interventions de 45 minutes \u00e0 1 heure  sera suivie d\u2019un  \u00e9change avec les  \u00e9tudiant-e-s.<\/p>\n<p>Cette demi-journ\u00e9e aura lieu dans les locaux de la HEP Lausanne, Av. de Cour 33, salle C33-720 de 8h15 \u00e0 11h45<\/p>\n<p>8h15 : Accueil<\/p>\n<p>8h20-9h45 : <em>La place de l\u2019archive dans le cin\u00e9ma de  fiction : \u00e9tude  de films sur le g\u00e9nocide juif<\/em> par R\u00e9my Besson de  l\u2019Ecole des hautes  \u00e9tudes en sciences sociales (EHESS) Paris<\/p>\n<p><em><a href=\"https:\/\/i0.wp.com\/farm4.static.flickr.com\/3031\/2633211339_aa7625df26_m.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"R\u00e9my Besson\" src=\"https:\/\/i0.wp.com\/farm4.static.flickr.com\/3031\/2633211339_aa7625df26_m.jpg?resize=184%2C120\" alt=\"\" width=\"184\" height=\"120\" \/><\/a>R\u00e9my  Besson intervient notamment dans le cadre du Laboratoire  d\u2019histoire  visuelle contemporaine (Lhivic ) de l&rsquo;\u00c9cole des hautes  \u00e9tudes en  sciences sociales (EHESS) \u00e0 Paris.\u00a0 Dans le cadre de cette  matin\u00e9e, sa  conf\u00e9rence se rapporte \u00e0 la question des enjeux de la  narrativit\u00e9 dans  le cin\u00e9ma dit documentaire. R\u00e9f\u00e9rence: le blog de  l\u2019atelier du Lhivic (<a href=\"http:\/\/culturevisuelle.org\/cinemadoc\/\" target=\"_blank\">http:\/\/culturevisuelle.org\/cinemadoc\/<\/a>)<\/em><\/p>\n<p>9h45-10h15 : Pause<\/p>\n<p>10h15-11h45 : <em>Photographie et histoire: R\u00e9alit\u00e9 et  interpr\u00e9tations,  les conflits de v\u00e9rit\u00e9<\/em> par Daniel Girardin,  Conservateur au Mus\u00e9e  de l\u2019Elys\u00e9e \u00e0 Lausanne<\/p>\n<p><em><a href=\"https:\/\/i0.wp.com\/farm4.static.flickr.com\/3204\/2535955648_8789195037_m.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"Daniel Girardin\" src=\"https:\/\/i0.wp.com\/farm4.static.flickr.com\/3204\/2535955648_8789195037_m.jpg?resize=184%2C123\" alt=\"\" width=\"184\" height=\"123\" \/><\/a>Daniel Girardin est Conservateur au Mus\u00e9e de  l\u2019Elys\u00e9e \u00e0 Lausanne. Il  est le concepteur notamment de l\u2019exposition et  du livre <\/em>Controverses,  une histoire juridique et \u00e9thique de la  photographie<em>. Sa conf\u00e9rence se  centrera sur l\u2019utilisation de la  photographie comme source historique.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre des deux modules destin\u00e9s aux \u00e9tudiant-e-s en histoire (Secondaire I et II) de la HEP Lausanne, nous organisons une demi-journ\u00e9e avec des intervenants ext\u00e9rieurs en relation avec la questions de l&rsquo;utilisation des images en histoire dans une perspective acad\u00e9mique et sous l&rsquo;angle de la recherche. Chacune des interventions de 45 minutes \u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13681,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":3,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"fullscreen","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[517,518,345,20,377,519,244],"class_list":{"0":"post-2736","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-histoire-2","8":"tag-conferences","9":"tag-daniel-girardin","10":"tag-film","11":"tag-histoire","12":"tag-photographie","13":"tag-remy-besson","14":"tag-sources","15":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/2633211339_aa7625df26_m.jpg?resize=240%2C160&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/2633211339_aa7625df26_m.jpg?resize=240%2C160&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/Blog\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/2633211339_aa7625df26_m.jpg?fit=240%2C160&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1qtF4-I8","jetpack-related-posts":[{"id":2879,"url":"https:\/\/lyonelkaufmann.ch\/Blog\/2010\/06\/19\/lhistorien-le-film-et-lanachronique-pierre-sorlin-cinemadoc\/","url_meta":{"origin":2736,"position":0},"title":"L\u2019historien, le film et l\u2019anachronique \u2013 Pierre Sorlin | Cin\u00e9madoc","author":"Lyonel Kaufmann","date":"19 juin 2010","format":false,"excerpt":"\"Nous arrivons ainsi \u00e0 une premi\u00e8re proposition : le film historique serait, davantage que beaucoup d\u2019autres, un film situ\u00e9, \u00e9troitement d\u00e9pendant d\u2019un contexte en dehors duquel il n\u2019aurait pas de sens. Il serait, d\u2019autre part, sous un v\u00eatement d\u2019emprunt, consacr\u00e9 d\u2019abord et avant tout aux questions contemporaines ; par une\u2026","rel":"","context":"Dans &quot;histoire&quot;","block_context":{"text":"histoire","link":"https:\/\/lyonelkaufmann.ch\/Blog\/category\/histoire-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":6755,"url":"https:\/\/lyonelkaufmann.ch\/Blog\/2013\/01\/29\/la-mise-en-scene-du-passe-sens-public\/","url_meta":{"origin":2736,"position":1},"title":"La mise en sc\u00e8ne du pass\u00e9 | Sens Public","author":"Lyonel Kaufmann","date":"29 janvier 2013","format":false,"excerpt":"Compte-rendu par R\u00e9my Besson de l'ouvrage de\u00a0St\u00e9phane Haffemayer, Beno\u00eet Marpeau et Julie Verlaine (dir.), Le spectacle de l\u2019histoire, Rennes, Presses Universitaires de Rennes, 2012. Articul\u00e9 autour d\u2019une vingtaine d\u2019\u00e9tudes de cas et adoptant une approche r\u00e9solument culturaliste, Le spectacle de l\u2019histoire est un ouvrage collectif portant sur la mani\u00e8re dont\u2026","rel":"","context":"Dans &quot;histoire&quot;","block_context":{"text":"histoire","link":"https:\/\/lyonelkaufmann.ch\/Blog\/category\/histoire-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2942,"url":"https:\/\/lyonelkaufmann.ch\/Blog\/2010\/06\/29\/limprevu-cinematographique-laurent-veray-cinemadoc\/","url_meta":{"origin":2736,"position":2},"title":"L\u2019impr\u00e9vu cin\u00e9matographique \u2013 Laurent V\u00e9ray | Cin\u00e9madoc","author":"Lyonel Kaufmann","date":"29 juin 2010","format":false,"excerpt":"\u201cLa reconstitution du pass\u00e9 n\u2019est plus la seule motivation, ni le seul centre d\u2019int\u00e9r\u00eat. Pas plus que les historiens, ces cin\u00e9astes ne cherchent \u00e0 reconstituer la r\u00e9alit\u00e9 d\u2019hier \u00e0 l\u2019\u00e9tat brute. Ils interrogent au contraire la trompeuse \u00e9vidence des images qu\u2019ils utilisent, remettent en question leur pr\u00e9tendue objectivit\u00e9, proposent d\u2019autres\u2026","rel":"","context":"Dans &quot;histoire&quot;","block_context":{"text":"histoire","link":"https:\/\/lyonelkaufmann.ch\/Blog\/category\/histoire-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":7208,"url":"https:\/\/lyonelkaufmann.ch\/Blog\/2013\/07\/15\/revue-de-presse-shoah-entre-impression-de-reel-et-recit-realiste-cinemadoc\/","url_meta":{"origin":2736,"position":3},"title":"Revue de presse : Shoah, entre impression de r\u00e9el et r\u00e9cit r\u00e9aliste | Cin\u00e9madoc","author":"Lyonel Kaufmann","date":"15 juillet 2013","format":false,"excerpt":"La recherche de R\u00e9my Besson sur le film Shoah permet d\u2019\u00e9tablir que le r\u00e9gime de v\u00e9rit\u00e9 dont Shoah rel\u00e8ve n\u2019est pas celui de l\u2019histoire orale, mais bien de celui d\u2019un film de cin\u00e9ma extr\u00eamement construit, aussi bien lors du tournage que lors du montage. Seul un travail en archive permet\u2026","rel":"","context":"Dans &quot;histoire&quot;","block_context":{"text":"histoire","link":"https:\/\/lyonelkaufmann.ch\/Blog\/category\/histoire-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3768,"url":"https:\/\/lyonelkaufmann.ch\/Blog\/2011\/05\/27\/etudes-photo-n27-le-rapport-karski-cinemadoc\/","url_meta":{"origin":2736,"position":4},"title":"Etudes Photo n\u00b027 \u2013 Le Rapport Karski | Cin\u00e9madoc","author":"Lyonel Kaufmann","date":"27 mai 2011","format":false,"excerpt":"En 1977, Claude Lanzmann et son \u00e9quipe ont retrouv\u00e9 le r\u00e9sistant polonais Jan Karski. Fin 1978, apr\u00e8s plus de trente ann\u00e9es de silence, Karski accepte d\u2019\u00eatre film\u00e9 \u00e0 son domicile pendant deux jours. Dans Shoah (1985), Claude Lanzmann octroie trente-neuf minutes \u00e0 ce t\u00e9moignage. En 2010, le r\u00e9alisateur a repris\u2026","rel":"","context":"Dans &quot;histoire&quot;","block_context":{"text":"histoire","link":"https:\/\/lyonelkaufmann.ch\/Blog\/category\/histoire-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/224616_185673904817315_182286505156055_523552_6681366_n.jpg?fit=470%2C720&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3294,"url":"https:\/\/lyonelkaufmann.ch\/Blog\/2010\/05\/19\/flickr-photo-download-p012599-jpg\/","url_meta":{"origin":2736,"position":5},"title":"Photos Normandie","author":"Lyonel Kaufmann","date":"19 mai 2010","format":"aside","excerpt":"En clin d'oeil au film Robin des Bois et pour R\u00e9my Besson -sans oublier Patrick Peccatte\u2014 suite \u00e0 notre \u00e9change sur Facebook\u2026 La photo a tr\u00e8s certainement \u00e0 Weymouth Portland Harbour \u00e0 l'embarquement d\u00e9but juin 1944. Robert Capa a fait des photos semblables au m\u00eame endroit \u00e0 la m\u00eame \u00e9poque\u2026","rel":"","context":"Dans &quot;Blogcaf\u00e9&quot;","block_context":{"text":"Blogcaf\u00e9","link":"https:\/\/lyonelkaufmann.ch\/Blog\/category\/blogcafe-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/4269438584_4953fe427f.jpg?fit=500%2C351&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/posts\/2736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/comments?post=2736"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/posts\/2736\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/media\/13681"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/media?parent=2736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/categories?post=2736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/tags?post=2736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}