{"id":794,"date":"2008-12-24T01:04:36","date_gmt":"2008-12-24T00:04:36","guid":{"rendered":"http:\/\/histoire.tumblr.com\/post\/66492419"},"modified":"2008-12-24T01:04:36","modified_gmt":"2008-12-24T00:04:36","slug":"le-mythe-lacustre-a-encore-de-beaux-jours-devant-lui","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/Blog\/2008\/12\/24\/le-mythe-lacustre-a-encore-de-beaux-jours-devant-lui\/","title":{"rendered":"Le mythe lacustre a encore de beaux jours devant lui"},"content":{"rendered":"<p>A Neuch\u00e2tel, le Mus\u00e9e cantonal d\u2019arch\u00e9ologie pr\u00e9sente une exposition temporaire consacr\u00e9e \u00e0 \u00abL\u2019imaginaire lacustre: Vision d\u2019une civilisation engloutie\u00bb.<\/p>\n<p>Depuis le XIXe si\u00e8cle, les lacustres font partie, sur le plan symbolique, de l\u2019histoire nationale suisse ainsi que de l\u2019histoire culturelle europ\u00e9enne. Les arch\u00e9ologues d\u00e9couvrant alors peu d\u2019armes,<\/p>\n<blockquote><p><em>\u00abOn en d\u00e9duit que ces communaut\u00e9s sont pacifiques. Et qu\u2019elles se mettent \u00e0 l\u2019abri des dangers en vivant sur des plates-formes dominant un lac\u00bb<\/em><\/p><\/blockquote>\n<p>explique Marc-Antoine Kaeser, conservateur du Laetenium.<\/p>\n<p>Si aujourd\u2019hui nous savons que les lacustres n\u2019ont jamais v\u00e9cu sur l\u2019eau, le mythe est tr\u00e8s puissant et, dans l\u2019imaginaire collectif, les lacustres vivent toujours sur l\u2019eau. En ce d\u00e9but du XXIe si\u00e8cle, ce mythe se pare de nouveaux atours post-modernes. Ainsi, Marc-Antoine Kaeser indique avoir observ\u00e9 que<\/p>\n<blockquote><p><em>\u00abce qui parle, entre autre, au public \u2018altermondialiste\u2019 dans le village lacustre, c\u2019est qu\u2019on peut y jouir de toutes les qualit\u00e9s du monde post-moderne. Et qu\u2019en m\u00eame temps, il est une sorte de refuge contre les angoisses de notre soci\u00e9t\u00e9.\u00bb<\/em><\/p><\/blockquote>\n<p>L\u2019exposition est \u00e0 voir jusqu\u2019au 7 juin 2009 au\u00a0Lat\u00e9nium, Espace Paul Vouga. Hauterive.<a href=\"http:\/\/www.latenium.ch\/\" target=\"_blank\"><\/a><a href=\"http:\/\/www.latenium.ch\/\" target=\"_blank\">www.latenium.ch<\/a><\/p>\n<p><strong>Source:<\/strong> <a href=\"http:\/\/www.lecourrier.ch\/index.php?name=News&amp;file=article&amp;sid=441246\" target=\"_blank\">La pr\u00e9histoire id\u00e9alis\u00e9e mod\u00e8le notre imaginaire :: Le Courrier :: Quotidien suisse ind\u00e9pendant<\/a><\/p>\n<p><strong>Mise \u00a0\u00e0 jour (samedi 9 mai 2009):<\/strong><\/p>\n<figure style=\"width: 393px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/motsdimages.ch\/local\/cache-vignettes\/L393xH328\/group393-840d1.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" title=\"Figurants d\u2019un cort\u00e8ge historique \u00e0 Neuch\u00e2tel (1882) - Lat\u00e9nium\" src=\"https:\/\/i0.wp.com\/motsdimages.ch\/local\/cache-vignettes\/L393xH328\/group393-840d1.jpg?resize=393%2C328\" alt=\"Figurants d\u2019un cort\u00e8ge historique \u00e0 Neuch\u00e2tel (1882) - Lat\u00e9nium\" width=\"393\" height=\"328\" \/><\/a><figcaption class=\"wp-caption-text\">Figurants d\u2019un cort\u00e8ge historique \u00e0 Neuch\u00e2tel (1882) - Lat\u00e9nium<\/figcaption><\/figure>\n<p>On lira avec int\u00e9r\u00eat le compte-rendu que l&rsquo;excellent blog helv\u00e9tique<a href=\"http:\/\/motsdimages.ch\"> Mots d&rsquo;images<\/a> consacre \u00e0 cette exposition. Compte-rendu agr\u00e9ment\u00e9 d&rsquo;images relatives \u00e0 ce mythe. Le compte-rendu:\u00a0<a href=\"http:\/\/motsdimages.ch\/Construction-d-un-mythe-par-l.html\">Construction d&rsquo;un mythe par l&rsquo;image<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Neuch\u00e2tel, le Mus\u00e9e cantonal d\u2019arch\u00e9ologie pr\u00e9sente une exposition temporaire consacr\u00e9e \u00e0&#8230;<\/p>\n","protected":false},"author":1,"featured_media":5742,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":3,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"fullscreen","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[98,99,100,101,37],"class_list":["post-794","post","type-post","status-publish","format-standard","has-post-thumbnail","category-histoire-2","tag-lacustres","tag-mythe-national","tag-neuchatel","tag-prehistoire","tag-suisse","entry"],"jetpack_publicize_connections":[],"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/Blog\/author\/lyonelk\/"},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1qtF4-cO","jetpack-related-posts":[{"id":3844,"url":"https:\/\/lyonelkaufmann.ch\/Blog\/2011\/06\/27\/les-sites-palafittiques-suisses-inscrits-au-patrimoine-tsrinfo-ch\/","url_meta":{"origin":794,"position":0},"title":"Les sites palafittiques suisses inscrits au patrimoine de l&rsquo;Unesco | tsrinfo.ch","author":"Lyonel Kaufmann","date":"27 juin 2011","format":false,"excerpt":"Le site des trois lacs (ici Sutz-Lattrigen, lac de Bienne) fait partie de la liste d\u00e9pos\u00e9e \u00e0 l'UNESCO. [Keystone] La Suisse doit \u00e0 ses sites palafittiques, pr\u00e9sents sur son territoire depuis des mill\u00e9naires, son onzi\u00e8me lieu inscrit au patrimoine mondial de lUNESCO. Sit\u00f4t la d\u00e9cision rendue, lOffice f\u00e9d\u00e9ral de la\u2026","rel":"","context":"Dans &quot;histoire&quot;","block_context":{"text":"histoire","link":"https:\/\/lyonelkaufmann.ch\/Blog\/category\/histoire-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/20110627-114126.jpg?fit=480%2C270&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3095,"url":"https:\/\/lyonelkaufmann.ch\/Blog\/2010\/08\/08\/koblet-le-james-dean-suisse-deux-ou-trois-choses-vues-de-paris\/","url_meta":{"origin":794,"position":1},"title":"Koblet, le James Dean suisse | Deux ou trois choses vues de Paris","author":"Lyonel Kaufmann","date":"8 ao\u00fbt 2010","format":false,"excerpt":"La projection sur la Piazza Grande de Locarno du film de Daniel von Aarburg \u00abHugo Koblet, p\u00e9daleur de charme\u00bb donne l'occasion \u00e0 Andr\u00e9 Crettenand de r\u00e9pondre \u00e0 question : Qu'est-ce qu'un h\u00e9ros suisse? Dans ce cadre-l\u00e0, Hugo Koblet d\u00e9teint par rapport aux\u00a0h\u00e9ros magnifi\u00e9s au 19e si\u00e8cle pour, selon la jolie\u2026","rel":"","context":"Dans &quot;histoire&quot;","block_context":{"text":"histoire","link":"https:\/\/lyonelkaufmann.ch\/Blog\/category\/histoire-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/087.jpg?fit=480%2C360&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7879,"url":"https:\/\/lyonelkaufmann.ch\/Blog\/2013\/11\/07\/identite-suisse-mythe-ou-realite\/","url_meta":{"origin":794,"position":2},"title":"Identit\u00e9 suisse : mythe ou r\u00e9alit\u00e9 ?","author":"Lyonel Kaufmann","date":"7 novembre 2013","format":false,"excerpt":"Qu'est-ce qui fait la sp\u00e9cificit\u00e9 de la Suisse et des Suisses? Pourquoi Guillaume Tell est-il le symbole de notre ind\u00e9pendance? Dans le cadre du mois suisse de la SSR, la RTS proposait le 6 novembre une soir\u00e9e sp\u00e9ciale autour de notre identit\u00e9 nationale. Apr\u00e8s la diffusion d\u00e8s 20h15 du premier\u2026","rel":"","context":"Dans &quot;histoire&quot;","block_context":{"text":"histoire","link":"https:\/\/lyonelkaufmann.ch\/Blog\/category\/histoire-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":334,"url":"https:\/\/lyonelkaufmann.ch\/Blog\/2008\/08\/01\/histoire-suisse-et-si-le-pacte-de-1291-etait-un-faux\/","url_meta":{"origin":794,"position":3},"title":"Histoire suisse: Et si le Pacte de 1291 \u00e9tait un faux?","author":"Lyonel Kaufmann","date":"1 ao\u00fbt 2008","format":false,"excerpt":"Hier soir, c'\u00e9tait l'heure du cort\u00e8ge aux flambeaux \u00e0 La Tour-de-Peilz. Soudain, la question pos\u00e9e \u00e0 l'historien: que s'est-il pass\u00e9 le 1er ao\u00fbt 1291? que f\u00eate-t-on? Question \u00e9minement pi\u00e8ge entre la mythologie politique et la r\u00e9alit\u00e9 historique. D'autant que le journal Le Temps du 31.07.2008 se fait l'\u00e9cho des th\u00e8ses\u2026","rel":"","context":"Dans &quot;histoire&quot;","block_context":{"text":"histoire","link":"https:\/\/lyonelkaufmann.ch\/Blog\/category\/histoire-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2008\/08\/bundesbrief.gif?fit=296%2C267&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7134,"url":"https:\/\/lyonelkaufmann.ch\/Blog\/2013\/06\/11\/revue-de-presse-les-gaulois-au-dela-du-mythe-arte\/","url_meta":{"origin":794,"position":4},"title":"Revue de presse : Les Gaulois au-del\u00e0 du mythe | ARTE","author":"Lyonel Kaufmann","date":"11 juin 2013","format":false,"excerpt":"Parution de livres, dossiers sp\u00e9ciaux dans les magazines, expositions qui bousculent les id\u00e9es re\u00e7ues\u2026 : les Gaulois sont \u00e0 la mode. Mais qui sont-ils ? Un peuple insolite assur\u00e9ment, puisqu'il a su traverser les si\u00e8cles et se transformer en mythe alors que presque rien ne subsistait de lui. Les Gaulois\u2026","rel":"","context":"Dans &quot;histoire&quot;","block_context":{"text":"histoire","link":"https:\/\/lyonelkaufmann.ch\/Blog\/category\/histoire-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":6737,"url":"https:\/\/lyonelkaufmann.ch\/Blog\/2013\/01\/23\/revue-de-presse-le-citoyen-soldat-en-suisse-une-histoire-recente-peter-hug\/","url_meta":{"origin":794,"position":5},"title":"Revue de presse : Le citoyen soldat en Suisse, une histoire r\u00e9cente | Peter Hug","author":"Lyonel Kaufmann","date":"23 janvier 2013","format":false,"excerpt":"Peter Hug : Les racines de l'attachement tr\u00e8s profond des Suisses \u00e0 leur fusil s'ancrent dans une histoire assez r\u00e9cente. Ce n'est que dans la seconde moiti\u00e9 du XIXe si\u00e8cle, et non au Moyen Age, comme le croient certains, qu'a commenc\u00e9 \u00e0 s'imposer cette culture de l'armement. Ses premiers d\u00e9veloppements\u2026","rel":"","context":"Dans &quot;histoire&quot;","block_context":{"text":"histoire","link":"https:\/\/lyonelkaufmann.ch\/Blog\/category\/histoire-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/Blog\/wp-content\/uploads\/2015\/03\/blogcafe1.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/posts\/794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/comments?post=794"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/posts\/794\/revisions"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/media?parent=794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/categories?post=794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/Blog\/wp-json\/wp\/v2\/tags?post=794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}