{"id":10685,"date":"2015-11-28T19:38:18","date_gmt":"2015-11-28T18:38:18","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/?p=10685"},"modified":"2016-01-09T22:19:42","modified_gmt":"2016-01-09T21:19:42","slug":"putain-de-guerre-le-1er-conflit-mondial-en-instantanes-cases-dhistoire","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2015\/11\/28\/putain-de-guerre-le-1er-conflit-mondial-en-instantanes-cases-dhistoire\/","title":{"rendered":"Putain de Guerre ! Le 1er conflit mondial en instantan\u00e9s | Cases d&rsquo;Histoire"},"content":{"rendered":"<p><a href=\"http:\/\/casesdhistoire.com\/putain-de-guerre-le-1er-conflit-mondial-en-instantanes\/\">Putain de Guerre ! Le 1er conflit mondial en instantan\u00e9s | Cases d&rsquo;Histoire<\/a>:<\/p>\n<blockquote><p>C\u2019est un v\u00e9ritable almanach de l\u2019horreur que l\u2019on d\u00e9roule en lisant Putain de Guerre\u00a0! de Jacques Tardi et Jean-Pierre Verney. Plus de quatre ann\u00e9es d\u2019inhumanit\u00e9s presque au jour le jour et \u00e0 travers les yeux d\u2019un simple trouffion. Une reconstitution remarquable de pr\u00e9cision et d\u2019\u00e9motion qui est d\u00e9j\u00e0 un classique, seulement sept ans apr\u00e8s sa cr\u00e9ation.<\/p><\/blockquote>\n<p>(Via <a href=\"http:\/\/casesdhistoire.com\">casesdhistoire.com<\/a>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Putain de Guerre ! Le 1er conflit mondial en instantan\u00e9s | Cases d&rsquo;Histoire: C\u2019est un v\u00e9ritable almanach de l\u2019horreur que l\u2019on d\u00e9roule en lisant Putain de Guerre\u00a0! de Jacques Tardi et Jean-Pierre Verney. Plus de quatre ann\u00e9es d\u2019inhumanit\u00e9s presque au jour le jour et \u00e0 travers les yeux d\u2019un simple trouffion. Une reconstitution remarquable de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10686,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,16],"tags":[23,83],"class_list":["post-10685","post","type-post","status-publish","format-standard","has-post-thumbnail","category-histoire-active","category-publications","tag-14-18","tag-bande-dessinee","entry"],"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/11\/PdGcouv-755x1024.jpg?resize=600%2C400&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/11\/PdGcouv-755x1024.jpg?resize=600%2C600&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-2Ml","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":8157,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2014\/08\/16\/les-poilus-vraiment-en-couleurs\/","url_meta":{"origin":10685,"position":0},"title":"Les poilus (vraiment) en couleurs","author":"Lyonel Kaufmann","date":"16 ao\u00fbt 2014","format":false,"excerpt":"Les \u00e9ditions Taschen publient des autochromes en couleurs de la Premi\u00e8re Guerre mondiale. Contrairement au travail de faussaire r\u00e9alis\u00e9 pour Apocalypse, la 1\u00e8re Guerre mondiale, il ne s\u2019agit pas d\u2019images en noir\/blanc coloris\u00e9es apr\u00e8s coup, mais de photographies prises en couleurs au moment du conflit. Ces images rares permettent de\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":12084,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/10\/05\/un-nouvel-album-de-tardi-consacre-a-la-guerre-des-tranchees\/","url_meta":{"origin":10685,"position":1},"title":"Un nouvel album de Tardi consacr\u00e9 \u00e0 la guerre des tranch\u00e9es","author":"Lyonel Kaufmann","date":"5 octobre 2016","format":false,"excerpt":"Le dessinateur Jacques Tardi s\u2019est fait un nom dans le monde de la bande dessin\u00e9e mais bien au-del\u00e0 aussi en signant de nombreux albums portant sur la Premi\u00e8re Guerre mondiale. Le voil\u00e0 donc qui revient en cette rentr\u00e9e avec un nouveau titre consacr\u00e9 \u00e0 cette horreur. Intitul\u00e9\u00a0Le dernier assaut\u00a0(112 pages\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/10\/Le-dernier-assaut-1.jpg?fit=600%2C784&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/10\/Le-dernier-assaut-1.jpg?fit=600%2C784&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/10\/Le-dernier-assaut-1.jpg?fit=600%2C784&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":2900,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/06\/22\/problematiser-14-18-un-armistice-de-21-ans\/","url_meta":{"origin":10685,"position":2},"title":"Probl\u00e9matiser 14-18 : un armistice de 21 ans?","author":"Lyonel Kaufmann","date":"22 juin 2010","format":false,"excerpt":"Les pr\u00e9occupations des historiens peuvent aider les enseignants \u00e0 construire une probl\u00e9matique \u00e0 laquelle leurs \u00e9l\u00e8ves devront ensuite r\u00e9pondre. En voici un exemple \u00e0 l'aide d'un article de 2008 paru dans la Revue historique des arm\u00e9es. En 2008, Georges-Henri Soutou s'interroge : 1918 repr\u00e9sentait-elle la fin de la Premi\u00e8re Guerre\u2026","rel":"","context":"Dans &quot;Didactique&quot;","block_context":{"text":"Didactique","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":103,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2006\/07\/25\/les-suisses-et-la-guerre-despagne\/","url_meta":{"origin":10685,"position":3},"title":"Les Suisses et la Guerre d&#039;Espagne (1936-1939)","author":"Lyonel Kaufmann","date":"25 juillet 2006","format":false,"excerpt":"Le 18 juillet 1936 marque le d\u00e9but de la Guerre d'Espagne. Ce jour-l\u00e0, l'arm\u00e9e tente un coup d'Etat; ce dernier \u00e9choue, mais les g\u00e9n\u00e9raux rebelles, parmi lesquels figure le g\u00e9n\u00e9ral Franco, refusent la m\u00e9diation et poursuivent le combat. Pendant trois ans, cette guerre va d\u00e9chirer l'Espagne et co\u00fbter la vie\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8540,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2014\/11\/11\/14-18-revue-de-presse-du-11-novembre\/","url_meta":{"origin":10685,"position":4},"title":"14-18 : revue de presse du 11 novembre","author":"Lyonel Kaufmann","date":"11 novembre 2014","format":false,"excerpt":"Les comm\u00e9morations de 14-18 battent leur plein plus particuli\u00e8rement en ce 11 novembre. Revue de presse subjective d\u2019articles actuels ou de 2014 sur le conflit. Documentaire. En m\u00e9moire de ces \u00abPoilus d\u2019ailleurs\u00bb | Mediapart\u00a0 Ils venaient de tous les coins du monde, enr\u00f4l\u00e9s de gr\u00e9 ou de force pour se\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/1415738078_thumb.jpeg.jpg?fit=720%2C405&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/1415738078_thumb.jpeg.jpg?fit=720%2C405&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/1415738078_thumb.jpeg.jpg?fit=720%2C405&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/1415738078_thumb.jpeg.jpg?fit=720%2C405&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":7246,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2013\/08\/02\/3e-guerre-mondiale-la-reine-dangleterre-avait-prepare-son-discours-le-nouvel-observateur\/","url_meta":{"origin":10685,"position":5},"title":"3e guerre mondiale : la reine d&#039;Angleterre avait pr\u00e9par\u00e9 son discours &#124; Le Nouvel Observateur","author":"Lyonel Kaufmann","date":"2 ao\u00fbt 2013","format":false,"excerpt":"La reine d'Angleterre en 1984. (BOUCHON\/AFP) \"Aujourd\u2019hui, la folie de la guerre se r\u00e9pand une fois de plus sur le monde et notre courageux pays doit une fois encore se pr\u00e9parer \u00e0 survivre face \u00e0 l'adversit\u00e9.\" Ce sont les mots que la reine d\u2019Angleterre, Elisabeth II, aurait prononc\u00e9s, au d\u00e9but\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/6183981-3e-guerre-mondiale-elisabeth-ii-avait-prepare-son-discours.jpg?fit=833%2C413&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/6183981-3e-guerre-mondiale-elisabeth-ii-avait-prepare-son-discours.jpg?fit=833%2C413&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/6183981-3e-guerre-mondiale-elisabeth-ii-avait-prepare-son-discours.jpg?fit=833%2C413&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/6183981-3e-guerre-mondiale-elisabeth-ii-avait-prepare-son-discours.jpg?fit=833%2C413&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/11\/PdGcouv-755x1024.jpg?fit=755%2C1024&ssl=1","_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/10685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=10685"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/10685\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/10686"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=10685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=10685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=10685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}