{"id":10988,"date":"2016-02-03T00:40:57","date_gmt":"2016-02-02T23:40:57","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/?p=10988"},"modified":"2017-08-10T11:00:40","modified_gmt":"2017-08-10T10:00:40","slug":"1916-2016-la-terrible-beaute-de-linsurrection-de-paques-a-dublin-reste-vivante-aujourdhui","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/02\/03\/1916-2016-la-terrible-beaute-de-linsurrection-de-paques-a-dublin-reste-vivante-aujourdhui\/","title":{"rendered":"1916 &#8211; 2016 : La terrible beaut\u00e9 de l&rsquo;Insurrection de P\u00e2ques \u00e0 Dublin reste vivante aujourd&rsquo;hui"},"content":{"rendered":"<p><strong>Alors que 2016 marquera le centenaire de l&rsquo;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Insurrection_de_P\u00e2ques_1916\" target=\"_blank\" rel=\"noopener\">Insurrection de P\u00e2ques<\/a> \u00e0 Dublin (appel\u00e9e \u00e9galement les P\u00e2ques sanglantes), le journal anglais <em>The Guardian<\/em> publie un tr\u00e8s int\u00e9ressant\u00a0article sur la m\u00e9moire de cet \u00e9v\u00e9nement.\u00a0Indirectement \u00a0un tel article fait \u00e9cho \u00e0 la mani\u00e8re dont les soci\u00e9t\u00e9s actuelles sont confront\u00e9es au terrorisme.<\/strong><\/p>\n<figure id=\"attachment_13172\" aria-describedby=\"caption-attachment-13172\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/594B38F9-2F5C-476F-A6E6-A25F679E78CA.jpeg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"13172\" data-permalink=\"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/02\/03\/1916-2016-la-terrible-beaute-de-linsurrection-de-paques-a-dublin-reste-vivante-aujourdhui\/594b38f9-2f5c-476f-a6e6-a25f679e78ca\/\" data-orig-file=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/594B38F9-2F5C-476F-A6E6-A25F679E78CA.jpeg?fit=1920%2C1152&amp;ssl=1\" data-orig-size=\"1920,1152\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"594B38F9-2F5C-476F-A6E6-A25F679E78CA\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;La rue Sackville d\u00e9vast\u00e9s &amp;#8211; maintenant O&amp;rsquo;Connell Street &amp;#8211; apr\u00e8s l&amp;rsquo;Insurrection de P\u00e2ques de 1916. Photo: Bettmann \/ Corbis&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/594B38F9-2F5C-476F-A6E6-A25F679E78CA.jpeg?fit=700%2C420&amp;ssl=1\" class=\"size-large wp-image-13172\" src=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/594B38F9-2F5C-476F-A6E6-A25F679E78CA.jpeg?resize=700%2C420&#038;ssl=1\" alt=\"\" width=\"700\" height=\"420\" srcset=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/594B38F9-2F5C-476F-A6E6-A25F679E78CA.jpeg?resize=700%2C420&amp;ssl=1 700w, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/594B38F9-2F5C-476F-A6E6-A25F679E78CA.jpeg?resize=300%2C180&amp;ssl=1 300w, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/594B38F9-2F5C-476F-A6E6-A25F679E78CA.jpeg?resize=768%2C461&amp;ssl=1 768w, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/594B38F9-2F5C-476F-A6E6-A25F679E78CA.jpeg?resize=800%2C480&amp;ssl=1 800w, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/594B38F9-2F5C-476F-A6E6-A25F679E78CA.jpeg?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><figcaption id=\"caption-attachment-13172\" class=\"wp-caption-text\">La rue Sackville d\u00e9vast\u00e9s &#8211; maintenant O&rsquo;Connell Street &#8211; apr\u00e8s l&rsquo;Insurrection de P\u00e2ques de 1916. Photo: Bettmann \/ Corbis<\/figcaption><\/figure>\n<p><span style=\"-webkit-text-size-adjust: 100%;\">La\u00a0<\/span><a class=\" u-underline\" style=\"-webkit-text-size-adjust: 100%;\" href=\"http:\/\/www.theguardian.com\/artanddesign\/2016\/jan\/21\/contested-legacy-echoes-of-the-easter-rising-1916-centenary-ireland\" data-link-name=\"in body link\" data-component=\"in-body-link\">m\u00e9moire de l&rsquo;Insurrection de\u00a0<\/a><span style=\"-webkit-text-size-adjust: 100%;\">P\u00e2ques a longtemps \u00e9t\u00e9 hant\u00e9 par une angoissante question:\u00a0<\/span><a class=\" u-underline\" style=\"-webkit-text-size-adjust: 100%;\" href=\"http:\/\/www.theguardian.com\/world\/2016\/jan\/03\/easter-rising-1916-centernary-peace-process\" data-link-name=\"in body link\" data-component=\"in-body-link\">est-elle maintenant\u00a0<\/a><span style=\"-webkit-text-size-adjust: 100%;\">termin\u00e9e?\u00a0Le soul\u00e8vement peut \u00eatre consid\u00e9r\u00e9e comme un \u00e9v\u00e9nement fondateur pour trois entit\u00e9s politiques: la R\u00e9publique d&rsquo;Irlande, Irlande du Nord et (bien que cela est commod\u00e9ment ignor\u00e9) l&rsquo;actuel Royaume-Uni, qui a chang\u00e9 radicalement quand la plupart de l&rsquo;Irlande a gagn\u00e9 son ind\u00e9pendance.\u00a0Pourtant, la lutte a toujours \u00e9t\u00e9 de d\u00e9cider si elle est l&rsquo;histoire ou l&rsquo;actualit\u00e9, quelque chose qui est arriv\u00e9 ou un pr\u00e9sage de quelque chose devant encore se produire.<\/span><\/p>\n<p>L&rsquo;article met en \u00e9vidence le contraste entre l&rsquo;\u00e9chec programm\u00e9 de cette insurrection lamentable, limit\u00e9e \u00e0 Dublin o\u00f9 il n&rsquo;\u00e9tait question que de tenir un nombre limit\u00e9 de b\u00e2timents publics avant que les troupes britanniques n&rsquo;\u00e9crasent la r\u00e9bellion et sa puissance dans l&rsquo;imaginaire collectif irlandais.<\/p>\n<figure id=\"attachment_13173\" aria-describedby=\"caption-attachment-13173\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/36209215-BBCE-40F6-8CFF-3C4C9BE4C963.jpeg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"13173\" data-permalink=\"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/02\/03\/1916-2016-la-terrible-beaute-de-linsurrection-de-paques-a-dublin-reste-vivante-aujourdhui\/36209215-bbce-40f6-8cff-3c4c9be4c963\/\" data-orig-file=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/36209215-BBCE-40F6-8CFF-3C4C9BE4C963.jpeg?fit=1920%2C1152&amp;ssl=1\" data-orig-size=\"1920,1152\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"36209215-BBCE-40F6-8CFF-3C4C9BE4C963\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Les soldats britanniques inspectent la coque du General Post Office de Dublin apr\u00e8s les combats de 1916 Photo: Hulton Archive \/ Getty Images&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/36209215-BBCE-40F6-8CFF-3C4C9BE4C963.jpeg?fit=700%2C420&amp;ssl=1\" class=\"size-large wp-image-13173\" src=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/36209215-BBCE-40F6-8CFF-3C4C9BE4C963.jpeg?resize=700%2C420&#038;ssl=1\" alt=\"\" width=\"700\" height=\"420\" srcset=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/36209215-BBCE-40F6-8CFF-3C4C9BE4C963.jpeg?resize=700%2C420&amp;ssl=1 700w, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/36209215-BBCE-40F6-8CFF-3C4C9BE4C963.jpeg?resize=300%2C180&amp;ssl=1 300w, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/36209215-BBCE-40F6-8CFF-3C4C9BE4C963.jpeg?resize=768%2C461&amp;ssl=1 768w, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/36209215-BBCE-40F6-8CFF-3C4C9BE4C963.jpeg?resize=800%2C480&amp;ssl=1 800w, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/36209215-BBCE-40F6-8CFF-3C4C9BE4C963.jpeg?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><figcaption id=\"caption-attachment-13173\" class=\"wp-caption-text\">Les soldats britanniques inspectent la coque du General Post Office de Dublin apr\u00e8s les combats de 1916 Photo: Hulton Archive \/ Getty Images<\/figcaption><\/figure>\n<p>Bien \u00e9videmment la puissance \u00e9vocatrice\u00a0de cet \u00e9v\u00e9nement doit une partie de son succ\u00e8s au po\u00e8me <a href=\"http:\/\/www.easter1916.net\/peom.htm\" target=\"_blank\" rel=\"noopener\">Easter 1916<\/a> de WB Yeats (<em>All changed, changed utterly \/ A Terrible beauty is born)<\/em>, mais elle le doit beaucoup aux Britanniques qui par la suite ex\u00e9cut\u00e8rent en mai 15 chefs de la r\u00e9bellion. A partir de ce moment-l\u00e0,\u00a0l&rsquo;humeur du public a commenc\u00e9 \u00e0 changer et les rebelles, au lieu d&rsquo;\u00eatre des fous dangereux, sont devenus des martyrs ((A l&rsquo;image de James Connolly ex\u00e9cut\u00e9 par un peloton d&rsquo;ex\u00e9cution attach\u00e9 \u00e0 une chaise, car il \u00e9tait d\u00e9j\u00e0 bless\u00e9 et ne pouvait pas se tenir debout.)).\u00a0Plus pr\u00e9cis\u00e9ment, ils sont devenus des martyrs catholiques.\u00a0Comme le chef rebelle Patrick Pearse l&rsquo;avait clairement envisag\u00e9, le sacrifice \u00e0 P\u00e2ques a \u00e9t\u00e9 \u00e9lev\u00e9s au rang\u00a0du plus grand des sacrifices de sang : celui du Christ lui-m\u00eame.<\/p>\n<p>Comment pouvons-nous aujourd&rsquo;hui contenir cette puissance de l&rsquo;imaginaire g\u00e9n\u00e9r\u00e9 par cet \u00e9v\u00e9nement\u00a0? Pour <em>The Guardian<\/em>, il est imp\u00e9ratif que les comm\u00e9morations restituent des r\u00e9alit\u00e9s plus complexes, que les rebelles ne soient pas trait\u00e9s sous l&rsquo;angle soit de saints, soit de terroristes, mais en v\u00e9ritables acteurs politiques d&rsquo;un conflit europ\u00e9en plus large. Pour le journal, il est r\u00e9jouissant\u00a0que le plus grand succ\u00e8s des ventes de livre sur le centenaire n&rsquo;est pas une hagiographie, mais la r\u00e9cup\u00e9ration minutieuse par\u00a0\u00a0Joe Duffy des noms et des histoires des\u00a0<a class=\" u-underline\" href=\"http:\/\/www.irishtimess.xyz\/culture\/books\/children-of-the-rising-by-joe-duffy-the-forgotten-casualties-of-1916-1.2419717\" data-link-name=\"in body link\" data-component=\"in-body-link\">40 enfants qui ont \u00e9t\u00e9 tu\u00e9s par des rebelles ou des forces\u00a0<\/a>britanniques lors des affrontements.\u00a0Le contexte de la premi\u00e8re guerre mondiale, le r\u00f4le central des femmes et la pauvret\u00e9 \u00e9pouvantable de Dublin sont tous en cours d&rsquo;\u00e9criture dans l&rsquo;histoire de l&rsquo;Insurrection de P\u00e2ques 1916. Il faut \u00e9galement accept\u00e9 que tous ces travaux historiques n&#8217;emp\u00eacheront pas la force \u00e9vocatrice et\u00a0l&rsquo;imaginaire de l&rsquo;\u00e9v\u00e9nement. Il s&rsquo;agit aussi d&rsquo;accueillir\u00a0l&rsquo;id\u00e9e m\u00eame que les rebelles eux-m\u00eames avait appel\u00e9 de leurs voeux\u00a0: la cr\u00e9ation d&rsquo;une vraie r\u00e9publique de citoyens \u00e9gaux.<\/p>\n<p>Source\u00a0: <em><a href=\"http:\/\/www.theguardian.com\/commentisfree\/2016\/feb\/01\/easter-rising-century-ireland-1916\">The terrible beauty of\u00a0the Easter Rising remains alive today | Fintan O\u2019Toole<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors que 2016 marquera le centenaire de l&rsquo;Insurrection de P\u00e2ques \u00e0 Dublin (appel\u00e9e \u00e9galement les P\u00e2ques sanglantes), le journal anglais The Guardian publie un tr\u00e8s int\u00e9ressant\u00a0article sur la m\u00e9moire de cet \u00e9v\u00e9nement.\u00a0Indirectement \u00a0un tel article fait \u00e9cho \u00e0 la mani\u00e8re dont les soci\u00e9t\u00e9s actuelles sont confront\u00e9es au terrorisme. La\u00a0m\u00e9moire de l&rsquo;Insurrection de\u00a0P\u00e2ques a longtemps \u00e9t\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13172,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,11,13],"tags":[],"class_list":{"0":"post-10988","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-histoire-savante","8":"category-nouvelles-de-lhistoire","9":"category-opinionsreflexions","10":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/594B38F9-2F5C-476F-A6E6-A25F679E78CA.jpeg?resize=600%2C400&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/594B38F9-2F5C-476F-A6E6-A25F679E78CA.jpeg?resize=600%2C600&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/594B38F9-2F5C-476F-A6E6-A25F679E78CA.jpeg?fit=1920%2C1152&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-2Re","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":11221,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/03\/17\/linsurrection-de-paques-a-dublin-un-champ-de-bataille-de-la-premiere-guerre-mondiale\/","url_meta":{"origin":10988,"position":0},"title":"L&rsquo;Insurrection de P\u00e2ques \u00e0 Dublin : un champ de bataille de la Premi\u00e8re Guerre mondiale","author":"Lyonel Kaufmann","date":"17 mars 2016","format":false,"excerpt":"Du 25 mars (vendredi saint) au 2 avril 2016, l'Irlande c\u00e9l\u00e9brera le centenaire de l'Easter Rising (Insurrection de P\u00e2ques 1916), \u00e9l\u00e9ment fondateur de la R\u00e9publique. Comme le souligne l'historien nord-irlandais Keith Jeffery, la Premi\u00e8re Guerre mondiale a donn\u00e9 l'opportunit\u00e9 aux S\u00e9paratistes de frapper en plein coeur l'Empire britannique et de\u2026","rel":"","context":"Dans &quot;Opinions&amp;R\u00e9flexions&quot;","block_context":{"text":"Opinions&amp;R\u00e9flexions","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/opinionsreflexions\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/03\/1pOQ9OT.jpg?fit=719%2C404&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/03\/1pOQ9OT.jpg?fit=719%2C404&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/03\/1pOQ9OT.jpg?fit=719%2C404&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/03\/1pOQ9OT.jpg?fit=719%2C404&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":176,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2007\/03\/11\/links-for-2007-03-11\/","url_meta":{"origin":10988,"position":1},"title":"Liens (11.03.2007)","author":"Lyonel Kaufmann","date":"11 mars 2007","format":false,"excerpt":"The 1916 Rising : Personalities & Perspectives L\u2019insurrection de P\u00e2ques 1916 est un \u00e9v\u00e8nement important de l\u2019Histoire irlandaise, et fait partie de la m\u00e9moire collective des Irlandais. C\u2019est la r\u00e9bellion d\u2019un peuple contre l\u2019occupant britannique (National Library of Ireland). (tags: histoire histoire&m\u00e9moire Irelande P\u00e2quesSanglantes Lib\u00e9rationNationale Ind\u00e9pendance Nationalisme XXeSi\u00e8cle XXe XXe_si\u00e8cle)\u2026","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":12145,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/10\/17\/faire-le-point-sur-la-classe-inversee-en-histoire-comme-ailleurs\/","url_meta":{"origin":10988,"position":2},"title":"Faire le point sur la Classe invers\u00e9e en histoire\u2026 comme ailleurs","author":"Lyonel Kaufmann","date":"17 octobre 2016","format":false,"excerpt":"Dans cet article, je reviens, dans un premier temps, sur deux articles publi\u00e9s ici qui ont fait le buzz relativement \u00e0 la classe invers\u00e9e. Dans un deuxi\u00e8me temps, \u00e0 l'aide du mod\u00e8le SAMR,\u00a0\u00a0je m'int\u00e9resse aux conditions \u00e0 partir desquelles un dispositif p\u00e9dagogique, telle la classe invers\u00e9e, recourant \u00e0 des outils\u2026","rel":"","context":"Dans &quot;Didactique&quot;","block_context":{"text":"Didactique","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/10\/0.jpg?fit=480%2C360&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":18264,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2021\/03\/08\/wikipedia-les-150-ans-de-la-commune-mois-de-contributions\/","url_meta":{"origin":10988,"position":3},"title":"Wikipedia : \u00abLes 150 ans de la Commune\u00bb : mois de contributions","author":"Lyonel Kaufmann","date":"8 mars 2021","format":false,"excerpt":"\u00c0 l'occasion du anniversaire de la Commune de Paris est organis\u00e9 un edit-a-thon afin de cr\u00e9er et d'am\u00e9liorer les articles sur l'insurrection parisienne de 1871 et toutes celles en France en 1870 et 1871. Il se d\u00e9roule du mars au 31 mars 2021. 23 mars 1871, proclamation de la seconde\u2026","rel":"","context":"Dans &quot;Humanit\u00e9s Digitales&quot;","block_context":{"text":"Humanit\u00e9s Digitales","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/humanites-digitales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2021\/03\/Affiche_seconde_Commune_de_Lyon_Archives_municipales_de_Lyon_6fi_6832.TIF.bce736d784a042569720fd2eef4334d8.jpg?fit=864%2C1197&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2021\/03\/Affiche_seconde_Commune_de_Lyon_Archives_municipales_de_Lyon_6fi_6832.TIF.bce736d784a042569720fd2eef4334d8.jpg?fit=864%2C1197&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2021\/03\/Affiche_seconde_Commune_de_Lyon_Archives_municipales_de_Lyon_6fi_6832.TIF.bce736d784a042569720fd2eef4334d8.jpg?fit=864%2C1197&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2021\/03\/Affiche_seconde_Commune_de_Lyon_Archives_municipales_de_Lyon_6fi_6832.TIF.bce736d784a042569720fd2eef4334d8.jpg?fit=864%2C1197&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":12099,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/10\/08\/les-scientifiques-percent-le-secret-des-habits-dotzi-lhomme-de-glace\/","url_meta":{"origin":10988,"position":4},"title":"Les scientifiques percent le secret des habits d&rsquo;Otzi, l&rsquo;Homme de Glace","author":"Lyonel Kaufmann","date":"8 octobre 2016","format":false,"excerpt":"Digne d'un sc\u00e9nario de la s\u00e9rie les Experts ou de Bones, l'article du blog D\u00e9couvertes arch\u00e9ologiques nous entra\u00eene sur le travail et les analyses des chercheurs de l'University College de Dublin. Fascinant. Bonne lecture. Il y a environ 3500 ans, mourrait l'homme que l'on connait sous le nom d'\u00f6tzi. Personne\u2026","rel":"","context":"Dans &quot;BP13\/22SHS Enseigner les sciences humaines et sociales aux cycles 1 et 2&quot;","block_context":{"text":"BP13\/22SHS Enseigner les sciences humaines et sociales aux cycles 1 et 2","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/cours-et-seminaires\/bp13shn-enseigner-les-sciences-sociales-et-les-sciences-de-la-nature-aux-cycles-1-et-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/10\/Les-scientifiques-percent-le-secret-des-habits-dOtzi-lHomme-de-Glace.jpg?fit=520%2C390&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11325,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/04\/09\/612journal-de-la-grande-guerre-6-avril-1916-1914-1918-reims-dans-la-grande-guerre\/","url_meta":{"origin":10988,"position":5},"title":"612\/journal de la grande guerre: 6 avril\u00a01916 \u2014 1914-1918: Reims dans la Grande Guerre","author":"Lyonel Kaufmann","date":"9 avril 2016","format":false,"excerpt":"Je vous invite \u00e0 suivre cet int\u00e9ressant blog consacr\u00e9 \u00e0 Reims pendant la Premi\u00e8re Guerre mondiale. Vous aurez l'occasion de suivre le conflit au jour le jour au travers du Carnet d'un r\u00e9mois Paul Hess et des contre rendus du journal Le Miroir. Chaque jour \u00e9galement une photo tir\u00e9es des\u2026","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/04\/6-avril-1916-copie.jpg?fit=587%2C559&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/04\/6-avril-1916-copie.jpg?fit=587%2C559&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/04\/6-avril-1916-copie.jpg?fit=587%2C559&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/10988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=10988"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/10988\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/13172"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=10988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=10988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=10988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}