{"id":111,"date":"2006-08-31T02:20:27","date_gmt":"2006-08-31T01:20:27","guid":{"rendered":"http:\/\/histoire.lyonelkaufmann.ch\/?p=182"},"modified":"2006-08-31T02:20:27","modified_gmt":"2006-08-31T01:20:27","slug":"links-for-2006-08-31","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2006\/08\/31\/links-for-2006-08-31\/","title":{"rendered":"Liens (31.08.2006)"},"content":{"rendered":"<ul class=\"delicious\">\n<li>\n<div class=\"delicious-link\"><a href=\"http:\/\/www.inrp.fr\/she\/agregation_ses_2007.htm\">Agr\u00e9gation externe de SES (Sciences \u00e9conomiques et sociales) 2007<\/a><\/div>\n<div class=\"delicious-extended\">\u00ab\u00a0L&rsquo;enseignement (primaire, secondaire et sup\u00e9rieur) en Allemagne, en France et en Grande-Bretagne de 1815 \u00e0 1939.\u00a0\u00bb<br \/>\nBibliographie des ouvrages publi\u00e9s par le Service d&rsquo;histoire de l&rsquo;\u00e9ducation et ses chercheurs (INRP).<\/div>\n<\/li>\n<\/ul>\n<p><b>Mise \u00e0 jour (01.09.2006)<\/b><br \/>\nDaniel Letouzey, de ClioWeb, a regrouper sur son site tant la bibliographie officielle que les deux contre-bibliographies. Toutes trois sont regroup\u00e9es \u00e0 l&rsquo;adresse suivante : <a href=\"http:\/\/aphgcaen.free.fr\/concours\/agrses07.htm\">Agr\u00e9gation externe de SES (2007)<\/a> Qu&rsquo;il en soit sinc\u00e8rement remerci\u00e9.<\/p>\n<div class=\"delicious-tags\">(tags: <a href=\"http:\/\/del.icio.us\/histoirehep\/Histoire\">Histoire<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/HistoireEducation\">HistoireEducation<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/\u00e9ducation\">\u00e9ducation<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/enseignement\">enseignement<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/XIXe\">XIXe<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/XXe\">XXe<\/a>)<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Agr\u00e9gation externe de SES (Sciences \u00e9conomiques et sociales) 2007 \u00ab\u00a0L&rsquo;enseignement (primaire, secondaire et sup\u00e9rieur) en Allemagne, en France et en Grande-Bretagne de 1815 \u00e0 1939.\u00a0\u00bb Bibliographie des ouvrages publi\u00e9s par le Service d&rsquo;histoire de l&rsquo;\u00e9ducation et ses chercheurs (INRP). Mise \u00e0 jour (01.09.2006) Daniel Letouzey, de ClioWeb, a regrouper sur son site tant la bibliographie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[18],"tags":[],"class_list":{"0":"post-111","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-annuaire-de-sites","8":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?fit=658%2C184&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-1N","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":215,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2007\/07\/31\/links-for-2007-07-31\/","url_meta":{"origin":111,"position":0},"title":"Liens  (31.07.2007)","author":"Lyonel Kaufmann","date":"31 juillet 2007","format":false,"excerpt":"Cours d'Histoire \u00e9conomique (P.-C. Hatcoeur) Cours d'introduction \u00e0 l'histoire \u00e9conomique pour des \u00e9conomistes. Le cours s'appuie sur une liste de textes (certains sont mis en lien), sur des \u00e9l\u00e9ments de d\u00e9bats historiques et sur une bibliographie fort int\u00e9ressante en histoire \u00e9conomique. (tags: histoire histoireeconomique historiographie bibliographie)","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":17918,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2020\/12\/28\/humanites-numeriques-et-education-bibliographie\/","url_meta":{"origin":111,"position":1},"title":"Bibliographie : Humanit\u00e9s num\u00e9riques et \u00e9ducation :","author":"Lyonel Kaufmann","date":"28 d\u00e9cembre 2020","format":false,"excerpt":"R\u00e9sum\u00e9 Bibliographie sur le th\u00e8me \u00ab\u00a0humanit\u00e9s num\u00e9riques et \u00e9ducation\u00a0\u00bb produite dans le cadre de la\u00a0pr\u00e9paration et le lancement des groupes th\u00e9matiques num\u00e9riques\u00a0#GTnum 2020-2022\u00a0de la Direction du num\u00e9rique pour l\u2019\u00e9ducation. Photo by Ali Pazani on Pexels.com Pr\u00e9sentation g\u00e9n\u00e9rale Remarque pr\u00e9alable : fruit d\u2019un travail de veille et de documentation pour la\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"photo of woman wearing turtleneck top","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/pexels-photo-2777898-e1678963278806.jpeg?fit=576%2C720&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/pexels-photo-2777898-e1678963278806.jpeg?fit=576%2C720&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/pexels-photo-2777898-e1678963278806.jpeg?fit=576%2C720&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":17982,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2020\/12\/26\/bibliographie-education-numerique-et-recherche\/","url_meta":{"origin":111,"position":2},"title":"Bibliographie \u2013 \u00ab \u00c9cole, num\u00e9rique et confinement \u00bb","author":"Lyonel Kaufmann","date":"26 d\u00e9cembre 2020","format":false,"excerpt":"R\u00e9sum\u00e9 Recension bibliographique sur le th\u00e8me \u00ab \u00c9cole, num\u00e9rique et confinement\u00a0\u00bb : bilan des publications fran\u00e7aises et internationales sur la p\u00e9riode de mars 2020 au 23 d\u00e9cembre 2020. Pr\u00e9sentation g\u00e9n\u00e9rale Cette recension bibliographique et sitographique sur le th\u00e8me \u00ab\u00a0\u00c9cole, num\u00e9rique et confinement\u00a0\u00bb est le fruit d\u2019un travail de veille et\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/EGNe_note_Fr_couv.png?fit=669%2C950&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/EGNe_note_Fr_couv.png?fit=669%2C950&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/EGNe_note_Fr_couv.png?fit=669%2C950&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":190,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2007\/04\/18\/295\/","url_meta":{"origin":111,"position":3},"title":"Bloc-Notes : lu r\u00e9cemment sur la to\u00eele\u2026","author":"Lyonel Kaufmann","date":"18 avril 2007","format":false,"excerpt":"Histoire : Enseignement Histoire-g\u00e9o : Profs et \u00e9l\u00e8ves : un seul lit pour deux r\u00eaves (l'Expresso du 5 avril 2007) Profs et \u00e9l\u00e8ves vivent-ils la m\u00eame le\u00e7on en cours ? Nicole Braxmeyer et Jean-Claude Guillaume nous donnent une rare occasion de sonder les attentes, les intentions, les motivations des professeurs\u2026","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":18959,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2022\/06\/12\/zotero-6-0-un-lecteur-de-pdf-ameliore-et-un-nouvel-editeur-de-notes\/","url_meta":{"origin":111,"position":4},"title":"Zotero 6.0 : un lecteur de pdf am\u00e9lior\u00e9 et un nouvel \u00e9diteur de notes","author":"Lyonel Kaufmann","date":"12 juin 2022","format":false,"excerpt":"En mars 2022, la version 6 de Zotero a introduit une s\u00e9rie de nouvelles fonctionnalit\u00e9s, y compris une toute nouvelle fa\u00e7on de travailler avec les PDF et les notes, qui transformeront la fa\u00e7on dont vous menez votre recherche. C'est probablement la principale nouveaut\u00e9 de cette version. Ouvrir les PDF dans\u2026","rel":"","context":"Dans &quot;Humanit\u00e9s Digitales&quot;","block_context":{"text":"Humanit\u00e9s Digitales","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/humanites-digitales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/06\/pdf-reader-e1678961170517.jpg?fit=720%2C469&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/06\/pdf-reader-e1678961170517.jpg?fit=720%2C469&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/06\/pdf-reader-e1678961170517.jpg?fit=720%2C469&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/06\/pdf-reader-e1678961170517.jpg?fit=720%2C469&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":184,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2007\/04\/05\/m157-internet-et-histoire-19122006\/","url_meta":{"origin":111,"position":5},"title":"Liens (05.04.2007)","author":"Lyonel Kaufmann","date":"5 avril 2007","format":false,"excerpt":"Histoire : Enseignement Histoire-g\u00e9o : Profs et \u00e9l\u00e8ves : un seul lit pour deux r\u00eaves (l'Expresso du 5 avril 2007) Profs et \u00e9l\u00e8ves vivent-ils la m\u00eame le\u00e7on en cours ? Nicole Braxmeyer et Jean-Claude Guillaume nous donnent une rare occasion de sonder les attentes, les intentions, les motivations des professeurs\u2026","rel":"","context":"Dans &quot;Cours et s\u00e9minaires&quot;","block_context":{"text":"Cours et s\u00e9minaires","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/cours-et-seminaires\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=111"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/111\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/9896"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}