{"id":1206,"date":"2009-03-17T13:57:38","date_gmt":"2009-03-17T12:57:38","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/?p=1206"},"modified":"2009-03-17T13:57:38","modified_gmt":"2009-03-17T12:57:38","slug":"creer-cest-resister-resister-cest-creer","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2009\/03\/17\/creer-cest-resister-resister-cest-creer\/","title":{"rendered":"\u00ab Cr\u00e9er, c&#039;est r\u00e9sister. R\u00e9sister, c&#039;est cr\u00e9er. \u00bb"},"content":{"rendered":"<div><object width=\"480\" height=\"381\" data=\"http:\/\/www.dailymotion.com\/swf\/k6UwcIzBVDfX9i2Lc2&amp;related=1\" type=\"application\/x-shockwave-flash\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowScriptAccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.dailymotion.com\/swf\/k6UwcIzBVDfX9i2Lc2&amp;related=1\" \/><param name=\"allowfullscreen\" value=\"true\" \/><\/object><br \/>\n<strong><a href=\"http:\/\/www.dailymotion.com\/video\/xe3rq_programme-de-la-resistance\">Programme de la r\u00e9sistance<\/a><\/strong><br \/>\n<em>envoy\u00e9 par <a href=\"http:\/\/www.dailymotion.com\/marxattaque\">marxattaque<\/a><\/em><\/div>\n<div><\/div>\n<div><em><\/p>\n<div>\n<p><strong>\u00ab\u00a0Cr\u00e9er, c&rsquo;est r\u00e9sister. R\u00e9sister, c&rsquo;est cr\u00e9er.\u00a0\u00bb<\/strong><\/p>\n<p><em><strong>Le nouvel appel du Conseil National de la\u00a0R\u00e9sistance (8 mars 2004)<\/strong><\/em><\/p>\n<p><span style=\"font-style: normal;\">Les r\u00e9sistant ne se sont pas seulement battu contre Hitler et contre les nazis: Ils avaient un id\u00e9al&#8230; Ils l&rsquo;ont consign\u00e9 dans le programme du conseil national de la r\u00e9sistance et aimerai bien qu&rsquo;on oublie pas compl\u00e8tement leur h\u00e9ritage, ce pourquoi ils se sont battus.<\/span><\/p>\n<p><a href=\"http:\/\/www.dailymotion.com\/video\/k5BQS0nwg6nwbh2Lc2\"><span style=\"font-style: normal;\">Dailymotion &#8211; Programme de la r\u00e9sistance, a video from marxattaque. programme, r\u00e9sistance, s\u00e9curit\u00e9, social, sociale<\/span><\/a><\/p>\n<p><span style=\"font-style: normal;\">Texte int\u00e9gral: <\/span><a href=\"http:\/\/www.reopen911.info\/11-septembre\/appel-du-conseil-national-de-la-resistance\/\" target=\"_blank\"><span style=\"font-style: normal;\">Appel du Conseil National de la R\u00e9sistance<\/span><\/a><\/p>\n<p><span style=\"font-style: normal;\">Compl\u00e9ment: <\/span><a href=\"http:\/\/fr.wikisource.org\/wiki\/Programme_du_Conseil_national_de_la_R\u00e9sistance\" target=\"_blank\"><span style=\"font-style: normal;\">Le Programme du Conseil national de la R\u00e9sistance du\u00a015 mars 1944<\/span><\/a><\/div>\n<p><\/em><\/div>\n<p><a href=\"http:\/\/histoire.tumblr.com\/rss\">Aller \u00e0 la source<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Programme de la r\u00e9sistance envoy\u00e9 par marxattaque \u00ab\u00a0Cr\u00e9er, c&rsquo;est r\u00e9sister. R\u00e9sister, c&rsquo;est cr\u00e9er.\u00a0\u00bb Le nouvel appel du Conseil National de la\u00a0R\u00e9sistance (8 mars 2004) Les r\u00e9sistant ne se sont pas seulement battu contre Hitler et contre les nazis: Ils avaient un id\u00e9al&#8230; Ils l&rsquo;ont consign\u00e9 dans le programme du conseil national de la r\u00e9sistance et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10311,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11],"tags":[61,169,273],"class_list":["post-1206","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nouvelles-de-lhistoire","tag-appel","tag-conseil-national-de-la-resistance","tag-france","entry"],"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/JcF2.jpg?resize=320%2C240&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/JcF2.jpg?resize=320%2C240&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-js","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":4653,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2009\/03\/17\/creer-cest-resister-resister-cest-creer-2\/","url_meta":{"origin":1206,"position":0},"title":"http:\/\/www.dailymotion.com\/swf\/k6UwcIzBVDfX9i2Lc2&amp;related=1 \u00ab&#160;Cr\u00e9er, c&#8217;est r\u00e9sister. R\u00e9si","author":"Lyonel Kaufmann","date":"17 mars 2009","format":"video","excerpt":"http:\/\/www.dailymotion.com\/swf\/k6UwcIzBVDfX9i2Lc2&related=1 \u00ab\u00a0Cr\u00e9er, c\u2019est r\u00e9sister. R\u00e9sister, c\u2019est cr\u00e9er.\u00a0\u00bb Le nouvel appel du Conseil National de la\u00a0R\u00e9sistance (8 mars 2004) Les r\u00e9sistant ne se sont pas seulement battu contre Hitler et contre les nazis: Ils avaient un id\u00e9al\u2026 Ils l\u2019ont consign\u00e9 dans le programme du conseil national de la r\u00e9sistance et aimerai\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"http:\/\/www.dailymotion.com\/swf\/k6UwcIzBVDfX9i2Lc2&amp;related=1","width":350,"height":200},"classes":[]},{"id":16429,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2019\/09\/28\/reseaux-le-jeu-educatif-sur-la-resistance\/","url_meta":{"origin":1206,"position":1},"title":"R\u00e9seaux, le jeu \u00e9ducatif sur la R\u00e9sistance","author":"Lyonel Kaufmann","date":"28 septembre 2019","format":false,"excerpt":"R\u00e9seaux est un jeu de plateau \u00e9ducatif cr\u00e9\u00e9 par les Archives d\u00e9partementales des Yvelines. Inspir\u00e9 de documents d'archives, R\u00e9seaux est un outil p\u00e9dagogique pour d\u00e9couvrir comment fonctionnaient les r\u00e9seaux clandestins, prendre conscience des risques encourus par les r\u00e9sistants et de leurs actes h\u00e9ro\u00efques. https:\/\/vimeo.com\/352428135 Dans R\u00e9seaux, vous incarnez les chefs\u2026","rel":"","context":"Dans &quot;Histoire active&quot;","block_context":{"text":"Histoire active","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-active\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8026,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2014\/06\/03\/revue-de-presse-tf1-depolitise-la-resistance-et-reecrit-lhistoire-de-mon-pere-rue89\/","url_meta":{"origin":1206,"position":2},"title":"Revue de presse : TF1\u00a0d\u00e9politise la r\u00e9sistance et r\u00e9\u00e9crit l\u2019histoire de mon p\u00e8re &#124; Rue89","author":"Lyonel Kaufmann","date":"3 juin 2014","format":false,"excerpt":"R\u00e9action \u00e0 la diffusion par TF1 de la s\u00e9rie R\u00e9sistance : \u00abPourquoi jouer ainsi avec la r\u00e9alit\u00e9 historique\u00a0? Pourquoi rendre Fran\u00e7ais des r\u00e9sistants \u00e9trangers\u00a0? Et quand le \u00ab\u00a0proc\u00e8s\u00a0\u00bb des militants de l\u2019OS (proc\u00e8s dit \u00ab\u00a0de La Maison de la Chimie\u00a0\u00bb en avril 1942) est port\u00e9 \u00e0 l\u2019\u00e9cran, quel dommage de\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3730,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/05\/04\/va-pensiero-de-verdi-en-2011-un-symbole-de-resistance-comme-en-1842\/","url_meta":{"origin":1206,"position":3},"title":"\u00abVa Pensiero\u00bb de Verdi en 2011 : un symbole de r\u00e9sistance patriotique comme en 1842","author":"Lyonel Kaufmann","date":"4 mai 2011","format":false,"excerpt":"Le 12 mars dernier, l\u2019Italie f\u00eatait le 150\u00e8me anniversaire de sa cr\u00e9ation et \u00e0 cette occasion fut donn\u00e9e, \u00e0 l\u2019op\u00e9ra de Rome, une repr\u00e9sentation de l\u2019op\u00e9ra le plus symbolique de cette unification: Nabucco de Verdi.\u00a0Nabucco de Verdi est une \u0153uvre autant musicale que politique\u00a0: elle \u00e9voque l\u2019\u00e9pisode de l\u2019esclavage des\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/028.jpg?fit=480%2C360&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":17283,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2020\/04\/05\/jeux-devasion-escape-games-en-histoire\/","url_meta":{"origin":1206,"position":4},"title":"Jeux d&rsquo;\u00e9vasion (escape games) en histoire","author":"Lyonel Kaufmann","date":"5 avril 2020","format":false,"excerpt":"Cr\u00e9er un enjeu de classe stimulant tout en permettant d'approfondir connaissances et comp\u00e9tences : c'est ce que propose le jeu d'\u00e9vasion (de l'anglais escape game). En voici une s\u00e9lection par l'Acad\u00e9mie de Lile. La \"malle retrouv\u00e9e\" Un adolescent d\u00e9couvre dans une vieille malle des objets appartenant \u00e0 un soldat de\u2026","rel":"","context":"Dans &quot;Histoire active&quot;","block_context":{"text":"Histoire active","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-active\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/04\/joshua-coleman-uB16HY_ah4o-unsplash.jpg?fit=640%2C480&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/04\/joshua-coleman-uB16HY_ah4o-unsplash.jpg?fit=640%2C480&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/04\/joshua-coleman-uB16HY_ah4o-unsplash.jpg?fit=640%2C480&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":11177,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/03\/10\/des-femmes-resistantes-au-memorial-de-la-shoah\/","url_meta":{"origin":1206,"position":5},"title":"Des femmes r\u00e9sistantes au M\u00e9morial de la Shoah","author":"Lyonel Kaufmann","date":"10 mars 2016","format":false,"excerpt":"A l\u2019occasion de la journ\u00e9e internationale des femmes, le M\u00e9morial de la Shoah a inaugur\u00e9 sa nouvelle exposition consacr\u00e9e\u00a0 \u00e0 la place des femmes dans l\u2019ensemble des mouvements de la R\u00e9sistance. Compos\u00e9e de nombreux documents d\u2019archives originaux,\u00a0 de photographies et d\u2019une soixantaine d\u2019objets, cette exposition dresse le portrait de ces\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"0803168","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/03\/0803168.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/JcF2.jpg?fit=320%2C240&ssl=1","_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/1206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=1206"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/1206\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/10311"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=1206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=1206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=1206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}