{"id":15124,"date":"2018-11-04T16:13:39","date_gmt":"2018-11-04T15:13:39","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/?p=15124"},"modified":"2018-11-04T16:14:29","modified_gmt":"2018-11-04T15:14:29","slug":"frere-dame-rencontre-avec-la-grande-revelation-de-la-rentree-litteraire-david-diop","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2018\/11\/04\/frere-dame-rencontre-avec-la-grande-revelation-de-la-rentree-litteraire-david-diop\/","title":{"rendered":"Fr\u00e8re d&rsquo;\u00e2me : Rencontre avec la grande r\u00e9v\u00e9lation de la rentr\u00e9e litt\u00e9raire, David Diop"},"content":{"rendered":"<p><strong>A\u00a0travers l\u2019exp\u00e9rience d\u2019un jeune Africain envoy\u00e9 \u00e0 la boucherie, David Diop adopte un point de vue in\u00e9dit sur la guerre de 14-18 et explore la douleur de l\u2019exil. Son roman,<em>\u00a0Fr\u00e8re d\u2019\u00e2me<\/em> (Seuil, 176 pages), figure parmi les attendus des prix litt\u00e9raires 2018.\u00a0<\/strong><\/p>\n<blockquote><p><em>\u00ab Tout a commenc\u00e9 pour David Diop \u00e0 la lecture de lettres de poilus, \u201ccharg\u00e9es d\u2019une grande \u00e9motion, car ce sont des lettres qui ont \u00e9t\u00e9 \u00e9crites par des jeunes gens qui allaient mourir. J\u2019ai voulu chercher des lettres \u00e9quivalentes de tirailleurs s\u00e9n\u00e9galais, mais je n\u2019en ai pas trouv\u00e9es. Il y a un lieu au\u00a0Mali o\u00f9 certains effets de ces soldats auraient \u00e9t\u00e9 conserv\u00e9s, dont des lettres. Mais un\u00a0historien m\u2019a confirm\u00e9 que souvent celles-ci n\u2019\u00e9taient pas intimes mais administratives. Je me suis dit que je\u00a0pouvais, moi, imaginer une\u00a0intimit\u00e9 d\u2019un tirailleur s\u00e9n\u00e9galais pendant la\u00a0guerre.\u201d<\/em><\/p>\n<p><em>Ce sera celle d\u2019Alfa Ndiaye, l\u2019un des narrateurs les\u00a0plus bouleversants qu\u2019on ait pu inventer ces derni\u00e8res ann\u00e9es. Engag\u00e9 volontaire, dans ce qui allait \u00eatre une boucherie, pour suivre\u00a0 son ami, son plus que fr\u00e8re, bref son \u201cfr\u00e8re d\u2019\u00e2me\u201d Mademba Diop, il va vivre dans sa chair la violence et l\u2019injustice de la\u00a0guerre.<\/em><\/p>\n<p><em>Si tous les jeunes gens enr\u00f4l\u00e9s en auront souffert, les soldats s\u00e9n\u00e9galais \u00e9taient ceux qu\u2019on envoyaitau front en\u00a0premi\u00e8re ligne, c\u2019est-\u00e0-dire ceux qui se faisaient tirer par les\u00a0Allemands comme des lapins, ceux aussi \u00e0 qui l\u2019on ne donnait pas de manteau, puisqu\u2019ils allaient mourir de toute fa\u00e7on. \u201cCertains \u00e9taient envoy\u00e9s pour couper les barbel\u00e9s entre les\u00a0deux lignes et l\u00e0, c\u2019\u00e9tait du tir au pigeon. Mais tout le monde a souffert de cette abomination.\u201d<\/em><\/p>\n<p><em>Dans Fr\u00e8re d\u2019\u00e2me, ce sont en effet eux que le\u00a0capitaine Armand sacrifie d\u2019abord \u2013\u00a0les autres jeunes y passeront ensuite, de toute fa\u00e7on. D\u00e8s le d\u00e9but, Alfa assiste \u00e0 la mort lente et atrocement douloureuse de son ami, \u00e9ventr\u00e9 par l\u2019ennemi \u201caux yeux bleus\u201d. \u201cAlfa Ndiaye refuse trois fois de l\u2019achever. C\u2019est ce moment-l\u00e0 qui est fatal pour lui. Alfa tombe dans une esp\u00e8ce de folie meurtri\u00e8re, car il a perdu sa raison de faire la guerre et son meilleur ami\u201d, raconte David Diop.\u00bb\u00a0<\/em><\/p><\/blockquote>\n<p>Source : <a href=\"https:\/\/abonnes.lesinrocks.com\/2018\/10\/30\/livres\/frere-dame-de-david-diop-un-tirailleur-senegalais-pris-dans-le-feu-de-la-grande-guerre-111138912\/\">LesInrocks &#8211; Rencontre avec la grande r\u00e9v\u00e9lation de la rentr\u00e9e litt\u00e9raire, David Diop<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A\u00a0travers l\u2019exp\u00e9rience d\u2019un jeune Africain envoy\u00e9 \u00e0 la boucherie, David Diop adopte un point de vue in\u00e9dit sur la guerre de 14-18 et explore la douleur de l\u2019exil. Son roman,\u00a0Fr\u00e8re d\u2019\u00e2me (Seuil, 176 pages), figure parmi les attendus des prix litt\u00e9raires 2018.\u00a0 \u00ab Tout a commenc\u00e9 pour David Diop \u00e0 la lecture de lettres de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11,16],"tags":[23,436,580],"class_list":["post-15124","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nouvelles-de-lhistoire","category-publications","tag-14-18","tag-litterature","tag-premiere-guerre-mondiale","entry"],"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/11\/ouv_david-diop-c-hermance-triay_editions-seuil.jpg?resize=600%2C400&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/11\/ouv_david-diop-c-hermance-triay_editions-seuil.jpg?resize=600%2C600&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-3VW","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":15588,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2018\/12\/31\/david-diop-la-france-a-construit-limage-dun-tirailleur-courageux-obeissant-et-parfois-sanguinaire\/","url_meta":{"origin":15124,"position":0},"title":"David Diop : \u00ab La France a construit l\u2019image d\u2019un tirailleur courageux, ob\u00e9issant et parfois sanguinaire \u00bb","author":"Lyonel Kaufmann","date":"31 d\u00e9cembre 2018","format":false,"excerpt":"Auteur du roman \u00ab Fr\u00e8re d\u2019\u00e2me \u00bb, le laur\u00e9at du Goncourt des lyc\u00e9ens d\u00e9crypte les repr\u00e9sentations li\u00e9es aux combattants africains pendant la premi\u00e8re guerre mondiale. Propos recueillis par Gladys Marivat pour le journal Le Monde. Extrait. Comment, \u00e0 l\u2019\u00e9poque, \u00e9taient repr\u00e9sent\u00e9s les tirailleurs s\u00e9n\u00e9galais\u00a0? En\u00a01910, le g\u00e9n\u00e9ral Charles Mangin \u00e9crit\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/12\/BFAFD7A8-E472-46A5-B0FC-6F31C7EEC01E.df31949b547b4c5b986c1c2fd91ebc5b.jpeg?fit=688%2C459&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/12\/BFAFD7A8-E472-46A5-B0FC-6F31C7EEC01E.df31949b547b4c5b986c1c2fd91ebc5b.jpeg?fit=688%2C459&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/12\/BFAFD7A8-E472-46A5-B0FC-6F31C7EEC01E.df31949b547b4c5b986c1c2fd91ebc5b.jpeg?fit=688%2C459&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":7840,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2014\/02\/04\/la-grande-guerre-a-nourri-la-litterature-durant-un-siecle\/","url_meta":{"origin":15124,"position":1},"title":"\u00ab\u00a0La Grande Guerre a nourri la litt\u00e9rature durant un si\u00e8cle\u00a0\u00bb","author":"Lyonel Kaufmann","date":"4 f\u00e9vrier 2014","format":false,"excerpt":"Pour Laurence Campa, ma\u00eetresse de conf\u00e9rences en lettres modernes \u00e0 l'universit\u00e9 Paris-XII Val-de-Marne, la Premi\u00e8re Guerre mondiale continue d'inspirer les \u00e9crivains parce qu'elle est plus qu'un cadre historique. Auteure de la \u00ab Petite biblioth\u00e8que du centenaire\u00a0\u00bb, s\u00e9lection comment\u00e9e d'\u0153uvres litt\u00e9raires sur la Grande Guerre de 1914 \u00e0 aujourd'hui, elle est\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":10679,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2015\/11\/26\/plateforme-1418\/","url_meta":{"origin":15124,"position":2},"title":"Plateforme 14\/18 est en ligne !","author":"Lyonel Kaufmann","date":"26 novembre 2015","format":false,"excerpt":"Plateforme 14\/18 s\u2019adresse notamment aux enseignants du secondaire \u00e0 leurs \u00e9l\u00e8ves et aux \u00e9tudiants. Elle a re\u00e7u pour objectif de favoriser la compr\u00e9hension des enjeux historiques de la Grande Guerre \u00e0 travers le portrait des huit membres d\u2019une famille, les R\u00e9sal et de deux autres correspondants proches de la famille,\u2026","rel":"","context":"Dans &quot;Histoire active&quot;","block_context":{"text":"Histoire active","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-active\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/11\/1448492633_thumb.jpeg?fit=765%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/11\/1448492633_thumb.jpeg?fit=765%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/11\/1448492633_thumb.jpeg?fit=765%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/11\/1448492633_thumb.jpeg?fit=765%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":18289,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2021\/04\/04\/aux-etats-unis-un-musee-en-ligne-consacre-aux-lettres-de-guerre\/","url_meta":{"origin":15124,"position":3},"title":"Aux \u00c9tats-Unis, un mus\u00e9e en ligne consacr\u00e9 aux lettres de guerre du Vietnam","author":"Lyonel Kaufmann","date":"4 avril 2021","format":false,"excerpt":"Dans un projet accessible enti\u00e8rement en ligne, l\u2019historien Andrew Carroll\u00a0pr\u00e9sente, en la contextualisant, la correspondance de soldats am\u00e9ricains lors de la guerre du Vietnam. Ces documents, pour certains in\u00e9dits, \u00e9clairent le quotidien du\u00a0conflit. \u201cIls m\u2019appellent, prends soin de toi, je vais bien\u201d,\u00a0conclut un certain Arthur Bustamante dans une lettre \u00e0\u2026","rel":"","context":"Dans &quot;Histoire active&quot;","block_context":{"text":"Histoire active","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-active\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2021\/04\/img_1011.jpg?fit=512%2C342&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10414,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2015\/08\/11\/%e2%96%b6-la-peur-bande-annonce-2015\/","url_meta":{"origin":15124,"position":4},"title":"\u25b6 LA PEUR Bande Annonce (2015)","author":"Lyonel Kaufmann","date":"11 ao\u00fbt 2015","format":false,"excerpt":"\u00ab Tu crois pas qu'on nous a bourr\u00e9 le cr\u00e2ne avec la \"haine des races\" ? \u00bb\u00a0 Sortie le 12 ao\u00fbt du film La Peur, bas\u00e9 sur le livre de Gabriel Chevalier. Sa bande-annonce : \u00ab La terre molle, gorg\u00e9e d'hommes, vivants ou morts, semblait maudite. Les jeunes gens, ceux\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/08\/0.jpg?fit=480%2C360&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":20466,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2025\/11\/09\/six-jeux-video-recents-inspires-par-la-premiere-guerre-mondiale\/","url_meta":{"origin":15124,"position":5},"title":"Six jeux vid\u00e9o r\u00e9cents inspir\u00e9s par la Premi\u00e8re Guerre mondiale","author":"Lyonel Kaufmann","date":"9 novembre 2025","format":false,"excerpt":"Strat\u00e9gie, tir, histoires bouleversantes ou horreur pure\u2026 La Grande Guerre continue d\u2019alimenter la cr\u00e9ativit\u00e9 des concepteurs de jeux vid\u00e9o. \u00ab Le Monde \u00bb en a s\u00e9lectionn\u00e9 six. \u00ab Soldats inconnus. Fr\u00e8res d\u2019armes \u00bb est sorti en 2024. UBISOFT Plus rares que ceux consacr\u00e9s \u00e0 la seconde guerre mondiale, les jeux\u2026","rel":"","context":"Dans &quot;EdNum&quot;","block_context":{"text":"EdNum","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/humanites-digitales\/ednum\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2025\/11\/OIP-2927118599.jpg?fit=474%2C474&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/11\/ouv_david-diop-c-hermance-triay_editions-seuil.jpg?fit=1400%2C700&ssl=1","_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/15124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=15124"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/15124\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/15123"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=15124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=15124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=15124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}