{"id":152,"date":"2006-12-10T02:18:37","date_gmt":"2006-12-10T01:18:37","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/?p=248"},"modified":"2006-12-10T02:18:37","modified_gmt":"2006-12-10T01:18:37","slug":"links-for-2006-12-10","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2006\/12\/10\/links-for-2006-12-10\/","title":{"rendered":"Liens (10.12.2006)"},"content":{"rendered":"<ul class=\"delicious\">\n<li>\n<div class=\"delicious-link\"><a href=\"http:\/\/expositions.bnf.fr\/homere\/\">BnF &#8211; Hom\u00e8re, Iliade, Odyss\u00e9e, Ulysse, Troie<\/a><\/div>\n<div class=\"delicious-extended\">Conception \u00ab\u00a0online\u00a0\u00bb de l&rsquo;exposition de la BNF consacr\u00e9e \u00e0 Hom\u00e8re. L&rsquo;expo permet notamment de donner les cl\u00e9s de compr\u00e9hension de l&rsquo;oeuvre ou de distinguer entre mythe et histoire. Un must.<\/div>\n<div class=\"delicious-tags\">(tags: <a href=\"http:\/\/del.icio.us\/histoirehep\/histoire\">histoire<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/antiquit\u00e9\">antiquit\u00e9<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/Gr\u00e8ce\">Gr\u00e8ce<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/Hom\u00e8re\">Hom\u00e8re<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/Ulysse\">Ulysse<\/a>)<\/div>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>BnF &#8211; Hom\u00e8re, Iliade, Odyss\u00e9e, Ulysse, Troie Conception \u00ab\u00a0online\u00a0\u00bb de l&rsquo;exposition de la BNF consacr\u00e9e \u00e0 Hom\u00e8re. L&rsquo;expo permet notamment de donner les cl\u00e9s de compr\u00e9hension de l&rsquo;oeuvre ou de distinguer entre mythe et histoire. Un must. (tags: histoire antiquit\u00e9 Gr\u00e8ce Hom\u00e8re Ulysse)<\/p>\n","protected":false},"author":1,"featured_media":9896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[18],"tags":[],"class_list":{"0":"post-152","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-annuaire-de-sites","8":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?fit=658%2C184&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-2s","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":220,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2007\/08\/18\/links-for-2007-08-18\/","url_meta":{"origin":152,"position":0},"title":"Liens (18.08.2007)","author":"Lyonel Kaufmann","date":"18 ao\u00fbt 2007","format":false,"excerpt":"Le Monde.fr : La guerre de Troie, un conflit entre Grecs et Hittites ? Lira-t-on, un jour, une version hittite du r\u00e9cit de la guerre de Troie? Pour cet article du journal Le Monde, il n'est pas absurde de le croire. (tags: Histoire Antiquit\u00e9 Gr\u00e8ce GuerreTroie Troie Hom\u00e8re)","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":18999,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2022\/06\/21\/ulysses-passe-a-aux-tables\/","url_meta":{"origin":152,"position":1},"title":"Ulysses passe \u00e0 table","author":"Lyonel Kaufmann","date":"21 juin 2022","format":false,"excerpt":"La fonction la plus demand\u00e9e par les utilisateurs d\u2019Ulysses ? La prise en charge compl\u00e8te des tableaux1. L\u2019\u00e9diteur de texte comprenait la syntaxe MultiMarkdown permettant de cr\u00e9er des s\u00e9ries, mais n\u2019offrait d\u2019aucune aide. Ulysses comble cette lacune, aussi bien sur iOS que macOS, et permet maintenant de cr\u00e9er des tableaux\u2026","rel":"","context":"Dans &quot;Humanit\u00e9s Digitales&quot;","block_context":{"text":"Humanit\u00e9s Digitales","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/humanites-digitales\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":11125,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/02\/21\/jean-pierre-vernant-une-histoire-dulysse-pour-les-enfants\/","url_meta":{"origin":152,"position":2},"title":"Jean-Pierre Vernant : Une histoire d&rsquo;Ulysse pour les enfants","author":"Lyonel Kaufmann","date":"21 f\u00e9vrier 2016","format":false,"excerpt":"Dans le nouveau th\u00e9\u00e2tre de Montreuil, en 2001, Jean-Pierre Vernant racontait l\u2019histoire d'Ulysse \u00e0 un public d'enfants. Dans l'\u00e9mission \"Histoire d'\u00e9coutes\", Jean-Pierre Vernant racontait l\u2019histoire d'Ulysse \u00e0 des enfants, un enregistrement de 2001. Une perle. L'\u00e9mission :\u00a0http:\/\/ift.tt\/1SKR9zv","rel":"","context":"Dans &quot;Opinions&amp;R\u00e9flexions&quot;","block_context":{"text":"Opinions&amp;R\u00e9flexions","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/opinionsreflexions\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/02\/1VxuiW3.jpg?fit=510%2C504&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":487,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2008\/11\/05\/links-for-2008-11-05\/","url_meta":{"origin":152,"position":3},"title":"La BNF, son blog et ses futurs blogs","author":"Lyonel Kaufmann","date":"5 novembre 2008","format":false,"excerpt":"Buzzeum \u00bb La BNF, son blog et ses futurs blogs Buzzeum nous apprend que la BNF se met \u00e0 l'internet social et participatif. D'abord en ouvrant une plate-forme de blog dont le premier est consacr\u00e9 aux expositions de l'institution. Ensuite, elle ouvre \u00e9galement sa page Facebook. (tags: Histoire M\u00e9diaTIC Mus\u00e9es\u2026","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":17205,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2020\/03\/23\/gastronomie-medievale-enseigner-avec-le-numerique\/","url_meta":{"origin":152,"position":4},"title":"Gastronomie m\u00e9di\u00e9vale \u2014 Enseigner avec le num\u00e9rique","author":"Lyonel Kaufmann","date":"23 mars 2020","format":false,"excerpt":"Une exposition en ligne de la Biblioth\u00e8que nationale de France. L'exposition est structur\u00e9e en 3 parties, en images, arr\u00eat sur et gros plan. La premi\u00e8re section s'int\u00e9resse \u00e0 l'alimentation, la cuisine et les repas. On apprend entre autres que les\u00a0c\u00e9r\u00e9ales\u00a0sont la base de l'alimentation, pr\u00e9par\u00e9es le plus souvent sous forme\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/03\/img_8647-1.png?fit=768%2C746&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/03\/img_8647-1.png?fit=768%2C746&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/03\/img_8647-1.png?fit=768%2C746&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/03\/img_8647-1.png?fit=768%2C746&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":13549,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2017\/11\/05\/antiquite-et-cinema-1-egypte-2-rome\/","url_meta":{"origin":152,"position":5},"title":"Antiquit\u00e9 et cin\u00e9ma : 1. Egypte 2. Rome","author":"Lyonel Kaufmann","date":"5 novembre 2017","format":false,"excerpt":"Le blog \u00ab\u00a0L\u2019Antiquit\u00e9 au cin\u00e9ma\u00a0\u00bb nous promet trois billets sur cette th\u00e9matique. Les deux premiers sont d\u00e9j\u00e0 publi\u00e9s et m\u00e9ritent le d\u00e9tour. Le premier est consacr\u00e9 \u00e0 l\u2019Egypte antique et le deuxi\u00e8me \u00e0 Rome. A consommer sans mod\u00e9ration. Le cin\u00e9ma s\u2019est tr\u00e8s vite empar\u00e9 de sujets historiques, et pourtant faire\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/11\/Image-05.11.17-22-56.79ce8d2bb89b427fb6b5692ef1b7d196.jpeg?fit=768%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/11\/Image-05.11.17-22-56.79ce8d2bb89b427fb6b5692ef1b7d196.jpeg?fit=768%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/11\/Image-05.11.17-22-56.79ce8d2bb89b427fb6b5692ef1b7d196.jpeg?fit=768%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/11\/Image-05.11.17-22-56.79ce8d2bb89b427fb6b5692ef1b7d196.jpeg?fit=768%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=152"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/152\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/9896"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}