{"id":17959,"date":"2020-12-23T20:58:25","date_gmt":"2020-12-23T19:58:25","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/?p=17959"},"modified":"2020-12-23T21:02:51","modified_gmt":"2020-12-23T20:02:51","slug":"markdown-rediger-dans-votre-navigateur-avec-stackedit-io","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2020\/12\/23\/markdown-rediger-dans-votre-navigateur-avec-stackedit-io\/","title":{"rendered":"Markdown : r\u00e9diger dans votre navigateur avec Stackedit.io"},"content":{"rendered":"\n<p><strong>Dans le cadre d\u2019une s\u00e9rie d\u2019articles consacr\u00e9s au format <em>markdown<\/em> et \u00e0 la question de la ma\u00eetrise de nos donn\u00e9es, je vous pr\u00e9sente aujourd\u2019hui <a href=\"https:\/\/stackedit.io\/\" target=\"_blank\" rel=\"noreferrer noopener\">Stackedit.io<\/a>. en prolongement de <a href=\"https:\/\/lyonelkaufmann.ch\/histoire\/2020\/12\/13\/markdown-the-programming-historian\/\" target=\"_blank\" rel=\"noreferrer noopener\">mon article consacr\u00e9 \u00e0 The Programming Historian<\/a><\/strong>.<\/p>\n\n\n\n<p><a href=\"https:\/\/programminghistorian.org\/fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">The Programming Historian<\/a> propose aux personnes de se familiariser avec la r\u00e9daction en utilisant la syntaxe markdown avec <a href=\"https:\/\/stackedit.io\/\">Stackedit.io<\/a>.<\/p>\n\n\n\n<p><a href=\"https:\/\/stackedit.io\/\" target=\"_blank\" rel=\"noreferrer noopener\">Stackedit.io<\/a> vous offre la possibilit\u00e9 de r\u00e9diger des documents en utilisant le Markdown \u00e0 l\u2019aide de votre navigateur que vous soyez connect\u00e9 ou non (les fichiers sont sauvegard\u00e9s sur votre ordinateur). C\u2019est plut\u00f4t malin.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/ecran-stackedit.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"383\" data-attachment-id=\"17963\" data-permalink=\"https:\/\/lyonelkaufmann.ch\/histoire\/2020\/12\/23\/markdown-rediger-dans-votre-navigateur-avec-stackedit-io\/ecran-stackedit\/\" data-orig-file=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/ecran-stackedit.png?fit=2814%2C1540&amp;ssl=1\" data-orig-size=\"2814,1540\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ecran-stackedit\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/ecran-stackedit.png?fit=700%2C383&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/ecran-stackedit.png?resize=700%2C383&#038;ssl=1\" alt=\"\" class=\"wp-image-17963\" srcset=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/ecran-stackedit.png?resize=700%2C383&amp;ssl=1 700w, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/ecran-stackedit.png?resize=300%2C164&amp;ssl=1 300w, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/ecran-stackedit.png?resize=768%2C420&amp;ssl=1 768w, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/ecran-stackedit.png?resize=1536%2C841&amp;ssl=1 1536w, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/ecran-stackedit.png?resize=2048%2C1121&amp;ssl=1 2048w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><\/div>\n\n\n\n<p>Votre fen\u00eatre de travail est scind\u00e9e en deux. A gauche, vous r\u00e9digez votre texte et le mettez en forme au format markdown avec la barre de mise en forme (comme dans votre traitement de texte). A droite, vous visualisez le texte mis en forme. Vous pouvez \u00e9galement passer d&rsquo;un mode \u00e0 l&rsquo;autre.<\/p>\n\n\n\n<p>Les jetons d\u2019acc\u00e8s \u00e9mis par Google, Dropbox, GitHub\u2026 sont stock\u00e9s dans votre navigateur et ne sont pas envoy\u00e9s \u00e0 un quelconque backend ou \u00e0 une tierce partie, de sorte que personne n\u2019a acc\u00e8s \u00e0 vos donn\u00e9es.<\/p>\n\n\n\n<p>SackEdit vous permet aussi d\u2019organiser vos fichiers au sein de dossiers. Il devient ainsi l\u2019\u00e9quivalent d\u2019un bloc-notes personnalis\u00e9.<\/p>\n\n\n\n<p>Vous pouvez g\u00e9rer plusieurs espaces de travail et les synchoniser. Par exemple, l\u2019un pourra \u00eatre sur Google Drive et l\u2019autre sur Github. En utilisant Github, vous pouvez ainsi synchroniser vos fichiers entre diff\u00e9rents ordinateurs et vous disposez \u00e9galement d\u2019une sauvegarde.<\/p>\n\n\n\n<p>Mais le partage d&rsquo;espace, gr\u00e2ce au m\u00e9canisme de synchronisation, permet un travail collaboratif. Si deux collaborateurs travaillent en m\u00eame temps sur le m\u00eame fichier, StackEdit se charge de fusionner les modifications. En plus, vous pouvez publier\/sauvegarder vos fichiers sur Github, Google Drive ou Dropbox notamment.<\/p>\n\n\n\n<p>En plus, il est \u00e9glement possible de lier Stackedit.io avec votre compte WordPress ou Blogger et de r\u00e9diger vos billets de blogs en mardown avant de les publier sur votre blog.<\/p>\n\n\n\n<p>Enfin, en mode sponsor (en clair un abonnement \u00e0 <em>StackEdit.io<\/em> \u00e0 dur\u00e9e variable), vous pouvez exporter votre travail au format .pdf ou .docx gr\u00e2ce \u00e0 un moteur Pandoc.<\/p>\n\n\n\n<p>Autrement, on retrouve les fonctionnalit\u00e9s de base de tout \u00e9diteur Markdown. <em>StackEdit.io<\/em> est une bonne entr\u00e9e en mati\u00e8re pour se familiariser avec la r\u00e9daction de textes ou documents en utilisant la syntaxe Markdown.<\/p>\n\n\n\n<p>Lien : <strong><a href=\"https:\/\/stackedit.io\/\" target=\"_blank\" rel=\"noreferrer noopener\">Stackedit.io<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre d\u2019une s\u00e9rie d\u2019articles consacr\u00e9s au format markdown et \u00e0 la question de la ma\u00eetrise de nos donn\u00e9es, je vous pr\u00e9sente aujourd\u2019hui Stackedit.io. en prolongement de mon article consacr\u00e9 \u00e0 The Programming Historian. The Programming Historian propose aux personnes de se familiariser avec la r\u00e9daction en utilisant la syntaxe markdown avec Stackedit.io. Stackedit.io [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17952,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[802],"tags":[],"class_list":{"0":"post-17959","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-humanites-digitales","8":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/pexels-photo-5966170.jpeg?resize=600%2C400&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/pexels-photo-5966170.jpeg?resize=600%2C600&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/pexels-photo-5966170.jpeg?fit=867%2C1300&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-4FF","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":17900,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2020\/12\/13\/markdown-the-programming-historian\/","url_meta":{"origin":17959,"position":0},"title":"Markdown : The Programming Historian","author":"Lyonel Kaufmann","date":"13 d\u00e9cembre 2020","format":false,"excerpt":"Le format markdown pr\u00e9sente l\u2019avantage d\u2019\u00eatre un langage \u00e0 la syntaxe relativement simple et l\u00e9ger. Il permet aussi de s\u2019affranchir, au moment de la r\u00e9daction, de la question du format de fichier. En effet, au moment de la publication vous pourrez enregistrer le texte et les images dans un certain\u2026","rel":"","context":"Dans &quot;Humanit\u00e9s Digitales&quot;","block_context":{"text":"Humanit\u00e9s Digitales","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/humanites-digitales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/about.png?fit=621%2C479&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/about.png?fit=621%2C479&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/about.png?fit=621%2C479&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":18951,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2022\/06\/11\/markdown-simplenote-lecriture-collaborative-facile\/","url_meta":{"origin":17959,"position":1},"title":"Markdown : SimpleNote, l&rsquo;\u00e9criture collaborative facile","author":"Lyonel Kaufmann","date":"11 juin 2022","format":false,"excerpt":"Le format markdown pr\u00e9sente l\u2019avantage d\u2019\u00eatre un langage \u00e0 la syntaxe relativement simple et l\u00e9ger. Il permet aussi de s\u2019affranchir, au moment de la r\u00e9daction, de la question du format de fichier. En effet, au moment de la publication vous pourrez enregistrer le texte et les images dans un certain\u2026","rel":"","context":"Dans &quot;Humanit\u00e9s Digitales&quot;","block_context":{"text":"Humanit\u00e9s Digitales","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/humanites-digitales\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":18959,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2022\/06\/12\/zotero-6-0-un-lecteur-de-pdf-ameliore-et-un-nouvel-editeur-de-notes\/","url_meta":{"origin":17959,"position":2},"title":"Zotero 6.0 : un lecteur de pdf am\u00e9lior\u00e9 et un nouvel \u00e9diteur de notes","author":"Lyonel Kaufmann","date":"12 juin 2022","format":false,"excerpt":"En mars 2022, la version 6 de Zotero a introduit une s\u00e9rie de nouvelles fonctionnalit\u00e9s, y compris une toute nouvelle fa\u00e7on de travailler avec les PDF et les notes, qui transformeront la fa\u00e7on dont vous menez votre recherche. C'est probablement la principale nouveaut\u00e9 de cette version. Ouvrir les PDF dans\u2026","rel":"","context":"Dans &quot;Humanit\u00e9s Digitales&quot;","block_context":{"text":"Humanit\u00e9s Digitales","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/humanites-digitales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/06\/pdf-reader-e1678961170517.jpg?fit=720%2C469&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/06\/pdf-reader-e1678961170517.jpg?fit=720%2C469&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/06\/pdf-reader-e1678961170517.jpg?fit=720%2C469&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/06\/pdf-reader-e1678961170517.jpg?fit=720%2C469&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":18999,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2022\/06\/21\/ulysses-passe-a-aux-tables\/","url_meta":{"origin":17959,"position":3},"title":"Ulysses passe \u00e0 table","author":"Lyonel Kaufmann","date":"21 juin 2022","format":false,"excerpt":"La fonction la plus demand\u00e9e par les utilisateurs d\u2019Ulysses ? La prise en charge compl\u00e8te des tableaux1. L\u2019\u00e9diteur de texte comprenait la syntaxe MultiMarkdown permettant de cr\u00e9er des s\u00e9ries, mais n\u2019offrait d\u2019aucune aide. Ulysses comble cette lacune, aussi bien sur iOS que macOS, et permet maintenant de cr\u00e9er des tableaux\u2026","rel":"","context":"Dans &quot;Humanit\u00e9s Digitales&quot;","block_context":{"text":"Humanit\u00e9s Digitales","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/humanites-digitales\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2597,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/02\/25\/links-for-2010-02-24\/","url_meta":{"origin":17959,"position":4},"title":"Essays on History and New Media &#124; Center for History and New Media","author":"Lyonel Kaufmann","date":"25 f\u00e9vrier 2010","format":false,"excerpt":"Essays on History and New Media |\u00a0Center for History and New Media Cette page du \u00abCenter for History and New Media\u00bb regroupe une s\u00e9rie d'articles consacr\u00e9s aux aspects th\u00e9oriques et pratiques de l'histoire \u00e0 l'\u00e8re digitale. Les articles ont \u00e9t\u00e9 publi\u00e9s de 1995 \u00e0 2009. Le premier article recens\u00e9 de\u2026","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6219,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2012\/10\/01\/eric-hobsbawm-fin-de-parcours\/","url_meta":{"origin":17959,"position":5},"title":"Eric Hobsbawm : fin de parcours","author":"Lyonel Kaufmann","date":"1 octobre 2012","format":false,"excerpt":"N\u00e9 \u00e0 Alexandrie de parents juifs en 1917, l\u2019historien britannique Eric Hobsbawn s\u2019est \u00e9teint le 1er octobre 2012 au Free Hospital de Londres, \u00e0 l\u2019\u00e2ge de 95 ans. Membre du Parti communiste de Grande-Bretagne depuis 1936, il collabora jusqu\u2019en 1991 \u00e0 la revue Marxism Today. En 2009, Mediapart nous proposait\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/eric-hobsbawm-0021.jpg?fit=460%2C276&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/17959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=17959"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/17959\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/17952"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=17959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=17959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=17959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}