{"id":18478,"date":"2021-10-06T12:43:53","date_gmt":"2021-10-06T11:43:53","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/?p=18478"},"modified":"2021-10-06T12:49:43","modified_gmt":"2021-10-06T11:49:43","slug":"la-carte-du-vinland-pretendument-datee-du-xve-siecle-est-un-faux","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2021\/10\/06\/la-carte-du-vinland-pretendument-datee-du-xve-siecle-est-un-faux\/","title":{"rendered":"La carte du Vinland, pre\u0301tendument date\u0301e du XVe sie\u0300cle est un faux"},"content":{"rendered":"<p>Source : <a href=\"https:\/\/www.sciencesetavenir.fr\/archeo-paleo\/archeologie\/censee-refleter-des-voyages-vikings-en-amerique-la-celebre-carte-du-vinland-est-definitivement-un-faux_158073\" title=\"La c\u00e9l\u00e8bre carte du Vinland est un faux!\">www.sciencesetavenir.fr<\/a><\/p>\n<h1>La c\u00e9l\u00e8bre carte du Vinland est un faux!<\/h1>\n<figure><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2021\/10\/Ca.jpeg?ssl=1\" alt=\"\"><br \/>\n<\/figure>\n<p>CR\u00c9DITS: UNIVERSIT\u00c9 DE YALE \/DOMAINE PUBLIC<\/p>\n<p>Fausse carte et vrais d\u00e9bats. Pendant pr\u00e8s d&rsquo;un demi-si\u00e8cle, des sp\u00e9cialistes se sont oppos\u00e9s sur la question de l&rsquo;authenticit\u00e9 d&rsquo;une carte m\u00e9di\u00e9vale \u2013 dite carte du Vinland &#8211; cens\u00e9e refl\u00e9ter des voyages Vikings en Am\u00e9rique, bien avant ceux initi\u00e9s par Christophe Colomb, en 1492. Soi-disant dat\u00e9 de 1440, ce parchemin acquis en 1965 par la c\u00e9l\u00e8bre Universit\u00e9 de Yale, dans le Connecticut (Etats-Unis), pr\u00e9tendait pr\u00e9senter une partie du littoral nord-am\u00e9ricain sous le nom de \u00ab\u00a0<em>Vinlanda Insula\u00a0\u00bb<\/em> et donc une possible premi\u00e8re repr\u00e9sentation du Nouveau-Monde. Or un article du <em>New York Times<\/em> du 30 septembre 2021 est revenu sur un communiqu\u00e9 de l&rsquo;Universit\u00e9 de Yale o\u00f9 Raymond Clemens, conservateur des livres anciens de la Beinecke Rare Book &amp; Manuscript Library, reconna\u00eet que <em>\u00ab\u00a0la carte du Vinland est un faux\u00a0\u00bb<\/em>, mettant ainsi fin \u00e0 ces sp\u00e9culations.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Source : www.sciencesetavenir.fr La c\u00e9l\u00e8bre carte du Vinland est un faux! CR\u00c9DITS: UNIVERSIT\u00c9 DE YALE \/DOMAINE PUBLIC Fausse carte et vrais d\u00e9bats. Pendant pr\u00e8s d&rsquo;un demi-si\u00e8cle, des sp\u00e9cialistes se sont oppos\u00e9s sur la question de l&rsquo;authenticit\u00e9 d&rsquo;une carte m\u00e9di\u00e9vale \u2013 dite carte du Vinland &#8211; cens\u00e9e refl\u00e9ter des voyages Vikings en Am\u00e9rique, bien avant ceux [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18477,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11],"tags":[],"class_list":{"0":"post-18478","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nouvelles-de-lhistoire","8":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2021\/10\/Ca-e1678962398748.jpeg?resize=600%2C400&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2021\/10\/Ca-e1678962398748.jpeg?resize=600%2C540&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2021\/10\/Ca-e1678962398748.jpeg?fit=720%2C540&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-4O2","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":15021,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2018\/10\/07\/assassins-creed-odyssey-une-carte-postale-de-la-grece-pas-un-cours-dhistoire\/","url_meta":{"origin":18478,"position":0},"title":"\u00ab\u00a0Assassin\u2019s Creed Odyssey\u00a0\u00bb\u00a0: une carte postale de la Gr\u00e8ce, pas un cours d\u2019histoire","author":"Lyonel Kaufmann","date":"7 octobre 2018","format":false,"excerpt":"Pour Laury-Nuria Andr\u00e9, docteure en histoire de l\u2019art et auteure de Game of Rome\u00a0: ou L\u2019Antiquit\u00e9 vid\u00e9oludique, le dernier volet d\u2019Assassin\u2019s Creed ne peut pas pr\u00e9tendre au statut de support \u00e9ducatif\u00a0: \u00ab\u00a0L\u2019Antiquit\u00e9 est un mythe. Comme pour L\u2019Odyss\u00e9e, il n\u2019y a pas de version officielle. Assassin\u2019s Creed Odyssey nous montre\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/10\/9d8074b_m1Ldg_jiwO-KZCd4wflizpd3.jpg?fit=1068%2C601&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/10\/9d8074b_m1Ldg_jiwO-KZCd4wflizpd3.jpg?fit=1068%2C601&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/10\/9d8074b_m1Ldg_jiwO-KZCd4wflizpd3.jpg?fit=1068%2C601&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/10\/9d8074b_m1Ldg_jiwO-KZCd4wflizpd3.jpg?fit=1068%2C601&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/10\/9d8074b_m1Ldg_jiwO-KZCd4wflizpd3.jpg?fit=1068%2C601&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":12786,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2017\/02\/12\/des-incroyables-cartes-et-infographies-du-xixe-siecle\/","url_meta":{"origin":18478,"position":1},"title":"Des incroyables cartes et infographies du XIXe si\u00e8cle","author":"Lyonel Kaufmann","date":"12 f\u00e9vrier 2017","format":false,"excerpt":"Entre 1849 et 1851, l\u2019illustrateur topographique et graveur Emslie et l\u2019\u00e9diteur Reynolds con\u00e7urent des diagrammes scientifiques repr\u00e9sentant dans un grand livre de douze pages intitul\u00e9 Geological Diagrams. A l\u2019\u00e9poque, les illustrateurs et cartographes contribuaient beaucoup au d\u00e9veloppement de l\u2019accessibilit\u00e9 et de la visibilit\u00e9 de la recherche scientifique en cr\u00e9ant des\u2026","rel":"","context":"Dans &quot;Publications&quot;","block_context":{"text":"Publications","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/publications\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/02\/Image-12.02.17-20-42.82c82788fde043b7a3d2809a64fe2aa0.jpeg?fit=1090%2C898&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/02\/Image-12.02.17-20-42.82c82788fde043b7a3d2809a64fe2aa0.jpeg?fit=1090%2C898&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/02\/Image-12.02.17-20-42.82c82788fde043b7a3d2809a64fe2aa0.jpeg?fit=1090%2C898&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/02\/Image-12.02.17-20-42.82c82788fde043b7a3d2809a64fe2aa0.jpeg?fit=1090%2C898&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/02\/Image-12.02.17-20-42.82c82788fde043b7a3d2809a64fe2aa0.jpeg?fit=1090%2C898&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":323,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2008\/05\/10\/links-for-2008-05-10\/","url_meta":{"origin":18478,"position":2},"title":"Programme d&#039;Etude sur le G\u00e9nocide &#124; Yale University","author":"Lyonel Kaufmann","date":"10 mai 2008","format":false,"excerpt":"Programme d'Etude sur le G\u00e9nocide | Yale University Ce Programme de l'Universit\u00e9 de Yale conduit des recherches, s\u00e9minaires et conf\u00e9rences sur les questions comparatives, interdisciplinaires et politiques qui se rapportent au ph\u00e9nom\u00e8ne des g\u00e9nocides pass\u00e9s ou pr\u00e9sents. Site en fran\u00e7ais. (tags: 39-45 XXeSi\u00e8cle G\u00e9nocide Interdisciplinarit\u00e9)","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":11390,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/04\/24\/une-exposition-sur-la-cartographie-ou-le-miroir-du-monde-eduscol-hg\/","url_meta":{"origin":18478,"position":3},"title":"Une exposition sur la cartographie ou le miroir du monde\u00a0&#8211; \u00c9duscol HG","author":"Lyonel Kaufmann","date":"24 avril 2016","format":false,"excerpt":"G\u00e9rard Mercator et Abraham Ortelius sont consid\u00e9r\u00e9s comme les fondateurs de la g\u00e9ographie moderne. Tous deux originaires de Flandre, ils se rencontrent en 1554 et bien vite une amiti\u00e9 voit le jour. Leur travail va r\u00e9volutionner la cartographie. \u00c0 Mercator, on doit en 1569 la c\u00e9l\u00e8bre carte du monde :\u2026","rel":"","context":"Dans &quot;Opinions&amp;R\u00e9flexions&quot;","block_context":{"text":"Opinions&amp;R\u00e9flexions","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/opinionsreflexions\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/04\/eda27319-a4c4-484b-8c92-66f3befe075d.jpg?fit=600%2C519&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/04\/eda27319-a4c4-484b-8c92-66f3befe075d.jpg?fit=600%2C519&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/04\/eda27319-a4c4-484b-8c92-66f3befe075d.jpg?fit=600%2C519&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":18791,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2022\/03\/08\/la-propagande-nazie-et-la-guerre-des-cartes-visionscarto\/","url_meta":{"origin":18478,"position":4},"title":"La propagande nazie et la \u00ab guerre des cartes \u00bb | visionscarto","author":"Lyonel Kaufmann","date":"8 mars 2022","format":false,"excerpt":"La cartographie a \u00e9t\u00e9 un instrument important de la propagande nazie. Bien que principalement destin\u00e9e \u00e0 la population allemande, elle a aussi \u00e9t\u00e9 massivement diffus\u00e9e \u00e0 l\u2019\u00e9tranger. Visionscarto propose d\u2019explorer ici un atlas de guerre allemand publi\u00e9 en 1941 aux \u00c9tats-Unis, dans lequel sont expos\u00e9s et justifi\u00e9s les points de\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/03\/palsky-coverb121-d06cb.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":15943,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2019\/04\/14\/cartographie-numerique-les-nouvelles-facons-de-faire-mentir-les-cartes-a-lere-numerique\/","url_meta":{"origin":18478,"position":5},"title":"Cartographie num\u00e9rique: Les nouvelles fa\u00e7ons de \u00ab\u00a0faire mentir les cartes\u00a0\u00bb \u00e0 l&rsquo;\u00e8re num\u00e9rique","author":"Lyonel Kaufmann","date":"14 avril 2019","format":false,"excerpt":"La r\u00e9\u00e9dition de l'ouvrage de Mark Monmonier est l'occasion pour le blog Cartographie(s) num\u00e9rique(s) de s'interroger sur les fa\u00e7ons, anciennes ou nouvelles, de \"faire mentir les cartes\" comme nous invite \u00e0 le faire le titre de son c\u00e9l\u00e8bre ouvrage. L\u2019article est compl\u00e9t\u00e9 par une tr\u00e8s pr\u00e9cieuse bibliographie. Extrait. \u00ab\u00a0L'apport principal\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/04\/B95BF3CB-7941-4113-A398-FE94817728DE.11098bb0601143d2b2fb8e6cff61d7a2.jpeg?fit=328%2C456&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/18478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=18478"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/18478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/18477"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=18478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=18478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=18478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}