{"id":18646,"date":"2021-12-22T17:57:18","date_gmt":"2021-12-22T16:57:18","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/?p=18646"},"modified":"2021-12-22T17:57:21","modified_gmt":"2021-12-22T16:57:21","slug":"repenser-les-futurs-de-leducation-lespace-physique-et-social-de-lecole-demeure-crucial-unesco","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2021\/12\/22\/repenser-les-futurs-de-leducation-lespace-physique-et-social-de-lecole-demeure-crucial-unesco\/","title":{"rendered":"Repenser les Futurs de l\u2019\u00e9ducation : l\u2019espace physique et social de l\u2019\u00e9cole demeure crucial (UNESCO)"},"content":{"rendered":"\n<p>Face aux transformations de nos soci\u00e9t\u00e9s que provoquent la mondialisation, le d\u00e9fi climatique, la r\u00e9volution num\u00e9rique, ou encore la pandemie de la Covid, l\u2019\u00e9ducation se trouvent \u00e0 un moment charni\u00e8re, avec \u00ab un pied dans le pass\u00e9 et un pied dans le futur \u00bb.<\/p>\n\n\n\n<p>L\u2019UNESCO a publi\u00e9 cette ann\u00e9e un rapport invitant \u00e0 \u00ab Repenser les Futurs de l\u2019\u00e9ducation \u00bb, notamment en r\u00e9examinant les rapports de humain \u00e0 humain, de l\u2019humain \u00e0 son environnement, et de l\u2019humain \u00e0 la technologie.<\/p>\n\n\n\n<p>Et si beaucoup de choses sont \u00e0 revoir, l\u2019espace physique et social de l\u2019\u00e9cole demeure crucial, comme l\u2019explique Sobhil Tawil, Directeur, Futurs de l\u2019\u00e9ducation et innovation \u00e0 l\u2019UNESCO.<\/p>\n\n\n\n<p>Extrait sonore : <a href=\"https:\/\/news.un.org\/fr\/audio\/2021\/12\/1111152?jwsource=em\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/news.un.org\/fr\/audio\/2021\/12\/1111152?jwsource=em<\/a><\/p>\n\n\n\n<p>T\u00e9l\u00e9charger : <a href=\"https:\/\/news.un.org\/feed\/download\/1111152\/fr\/sites\/news.un.org.fr\/files\/audio\/2021\/12\/2021-12-retro-cut_nws_escpace_scolaire_techno_unesco_100_0.mp3\">\u00a0T\u00e9l\u00e9charger<\/a><\/p>\n\n\n\n<p>(Extrait sonore : Tawil, Directeur, Futurs de l\u2019\u00e9ducation et innovation \u00e0 l\u2019UNESCO; propos recueillis par Cristina Silveiro)<\/p>\n\n\n\n<p>Source : <a href=\"https:\/\/news.un.org\/fr\/audio\/2021\/12\/1111152\">news.un.org<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Face aux transformations de nos soci\u00e9t\u00e9s que provoquent la mondialisation, le d\u00e9fi climatique, la r\u00e9volution num\u00e9rique, ou encore la pandemie de la Covid, l\u2019\u00e9ducation se trouvent \u00e0 un moment charni\u00e8re, avec \u00ab un pied dans le pass\u00e9 et un pied dans le futur \u00bb. L\u2019UNESCO a publi\u00e9 cette ann\u00e9e un rapport invitant \u00e0 \u00ab Repenser [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18647,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[13],"tags":[],"class_list":{"0":"post-18646","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-opinionsreflexions","8":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2021\/12\/pexels-photo-3856027-e1678962325166.jpeg?resize=600%2C400&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2021\/12\/pexels-photo-3856027-e1678962325166.jpeg?resize=600%2C480&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2021\/12\/pexels-photo-3856027-e1678962325166.jpeg?fit=720%2C480&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-4QK","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":6815,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2014\/09\/09\/quelle-place-pour-le-mobile-de-nos-eleves-en-classe\/","url_meta":{"origin":18646,"position":0},"title":"Quelle place pour le mobile de nos \u00e9l\u00e8ves en classe ?","author":"Lyonel Kaufmann","date":"9 septembre 2014","format":false,"excerpt":"Du 18 au 22 f\u00e9vrier, l'Unesco organise la semaine du mobile de l'UNESCO (18 - 22 f\u00e9vrier prochain) et s'interroge sur la place du t\u00e9l\u00e9phone dans l'enseignement. Comme le note Bruno Devauchelle, Paradoxe que celui d'une semaine qui est consacr\u00e9e \u00e0 l'apprendre \u00e0 l'aide des mobiles alors que dans le\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/04.jpg?fit=480%2C360&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5402,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2012\/05\/19\/etre-enseignant-a-lere-du-numerique-defis-et-opportunites\/","url_meta":{"origin":18646,"position":1},"title":"\u00catre enseignant \u00e0 l\u2019\u00e8re du num\u00e9rique, d\u00e9fis et opportunit\u00e9s","author":"Lyonel Kaufmann","date":"19 mai 2012","format":false,"excerpt":"G\u00e9n\u00e9ralement, je d\u00e9croche tr\u00e8s rapidement lorsque je visionne une conf\u00e9rence mise en ligne. Tel n'est pas le cas avec cette intervention d'Eric Sanchez sur l'enseignant et l'enseignement \u00e0 l'\u00e8re du num\u00e9rique. S'il part de son exp\u00e9rience dans l'enseignement sup\u00e9rieur, sa conf\u00e9rence interpelle tout enseignant et futur enseignant sur l'\u00e9volution de\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/fO_jFnvraaywHxA4FwhgNjl72eJkfbmt4t8yenImKBXEejxNn4ZJNZ2ss5Ku7Cxt.jpg?fit=500%2C275&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4042,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/09\/03\/sir-ken-robinson-revolutionnez-leducation\/","url_meta":{"origin":18646,"position":2},"title":"Sir Ken Robinson: R\u00e9volutionnez l&#039;\u00e9ducation!","author":"Lyonel Kaufmann","date":"3 septembre 2011","format":false,"excerpt":"\u00abLes dogmes du pass\u00e9 serein sont inad\u00e9quats pour le pr\u00e9sent temp\u00e9tueux.\u00bb Abraham Lincoln au Congr\u00e8s (1862) D\u00e9sormais les jeux sont faits concernant les deux projets d'\u00e9cole soumis aux citoyen-ne-s vaudois-e-s. Quelque soit le r\u00e9sultat, ces deux projets sont ancr\u00e9s dans le paradigme d'un syst\u00e8me scolaire issu de l'industrialisation du 19e\u2026","rel":"","context":"Dans &quot;Opinions&amp;R\u00e9flexions&quot;","block_context":{"text":"Opinions&amp;R\u00e9flexions","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/opinionsreflexions\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/027.jpg?fit=480%2C360&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":16422,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2019\/09\/24\/le-futur-de-leducation-numerique-mondes-sociaux\/","url_meta":{"origin":18646,"position":3},"title":"Le futur de l\u2019\u00e9ducation num\u00e9rique | Mondes sociaux","author":"Lyonel Kaufmann","date":"24 septembre 2019","format":false,"excerpt":"\u00a0\u00bbHacker c'est donc se rebeller, d\u00e9tourner les codes, \u00eatre \u00e0 la limite de la l\u00e9galit\u00e9\u2026 pour faire avancer la soci\u00e9t\u00e9 (..) Parce qu'une action vaut mieux qu'une critique, j'ai cr\u00e9\u00e9 HackEdu, avec une conviction : l'\u00e9ducation ne peut-\u00eatre disrupt\u00e9e que par ceux qui la font\". (St\u00e9phanie Pfeiffer, cr\u00e9atrice de HackEdu)\u2026","rel":"","context":"Dans &quot;Humanit\u00e9s Digitales&quot;","block_context":{"text":"Humanit\u00e9s Digitales","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/humanites-digitales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/09\/DraggedImage.b6d6bf2ec6c646dcaff2b4e6287c9e94.png?fit=960%2C602&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/09\/DraggedImage.b6d6bf2ec6c646dcaff2b4e6287c9e94.png?fit=960%2C602&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/09\/DraggedImage.b6d6bf2ec6c646dcaff2b4e6287c9e94.png?fit=960%2C602&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/09\/DraggedImage.b6d6bf2ec6c646dcaff2b4e6287c9e94.png?fit=960%2C602&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":20593,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2026\/03\/16\/ludoviach-ch-21-22-04-2026-deux-jours-pour-repenser-lapprentissage-a-lere-de-lia-et-de-linnovation\/","url_meta":{"origin":18646,"position":4},"title":"Ludovia#CH (21-22-04.2026) : deux jours pour repenser l\u2019apprentissage \u00e0 l\u2019\u00e8re de l\u2019IA et de l\u2019innovation","author":"Lyonel Kaufmann","date":"16 mars 2026","format":false,"excerpt":"Les 21et 22 avril 2026, la sixi\u00e8me \u00e9dition de LUDOVIA#CH revient \u00e0 Yverdon-les-Bains. Organis\u00e9 conjointement par la\u00a0Haute \u00e9cole p\u00e9dagogique du canton de Vaud\u00a0et de la\u00a0Haute \u00e9cole d\u2019ing\u00e9nierie et de gestion du canton de Vaud et le soutien du D\u00e9partement de l\u2019enseignement et de la formation professionnelle, l\u2019\u00e9v\u00e9nement proposera conf\u00e9rences, ateliers,\u2026","rel":"","context":"Dans &quot;EdNum&quot;","block_context":{"text":"EdNum","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/humanites-digitales\/ednum\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2026\/03\/HEP_Vaud_Affiches_A1_Ludovia_2026_06.03.2026_web.jpg?fit=847%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2026\/03\/HEP_Vaud_Affiches_A1_Ludovia_2026_06.03.2026_web.jpg?fit=847%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2026\/03\/HEP_Vaud_Affiches_A1_Ludovia_2026_06.03.2026_web.jpg?fit=847%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2026\/03\/HEP_Vaud_Affiches_A1_Ludovia_2026_06.03.2026_web.jpg?fit=847%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":20092,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2024\/11\/20\/cfp-recto-verso-futurs\/","url_meta":{"origin":18646,"position":5},"title":"CfP- RECTO VERSO &#8211; \u201eFuturs\u201c","author":"Lyonel Kaufmann","date":"20 novembre 2024","format":false,"excerpt":"\u00a0 RECTO VERSO est une s\u00e9rie de manifestations coordonn\u00e9es par l\u2019Acad\u00e9mie suisse des sciences humaines et sociales (ASSH) et organis\u00e9es par ses institutions membres. Chaque ann\u00e9e, les diff\u00e9rents \u00e9v\u00e9nements mettent en lumi\u00e8re, dans une perspective scientifique, un th\u00e8me actuel et pertinent pour la soci\u00e9t\u00e9. Le prochain cycle de manifestations (juillet\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2024\/11\/IMG_7531.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/18646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=18646"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/18646\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/18647"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=18646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=18646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=18646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}