{"id":19951,"date":"2024-04-12T07:57:06","date_gmt":"2024-04-12T06:57:06","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/2024\/04\/12\/decouverte-a-pompei-de-fresques-inspirees-de-la-guerre-de-troie-le-monde\/"},"modified":"2024-04-12T07:57:06","modified_gmt":"2024-04-12T06:57:06","slug":"decouverte-a-pompei-de-fresques-inspirees-de-la-guerre-de-troie-le-monde","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2024\/04\/12\/decouverte-a-pompei-de-fresques-inspirees-de-la-guerre-de-troie-le-monde\/","title":{"rendered":"D\u00e9couverte \u00e0 Pomp\u00e9i de fresques inspir\u00e9es de la guerre de Troie | Le Monde"},"content":{"rendered":"\n<p>De splendides fresques inspir\u00e9es de la guerre de Troie ornant une salle de banquet ont \u00e9t\u00e9 d\u00e9couvertes \u00e0 Pomp\u00e9i, a annonc\u00e9, jeudi 11&nbsp;avril, la direction du c\u00e9l\u00e8bre site arch\u00e9ologique situ\u00e9 pr\u00e8s de Naples, dans le sud de l\u2019Italie.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"525\" data-attachment-id=\"19950\" data-permalink=\"https:\/\/lyonelkaufmann.ch\/histoire\/2024\/04\/12\/decouverte-a-pompei-de-fresques-inspirees-de-la-guerre-de-troie-le-monde\/italy-archaeology-pompeii\/\" data-orig-file=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2024\/04\/img_6849-1.jpg?fit=800%2C600&amp;ssl=1\" data-orig-size=\"800,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;AFP&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;This handout picture released by the archaelogical park of Pompeii on April 11, 2024 shows frescoes depicting mythological characters Helen and Paris according to a Greek inscription placed between the two figures in a banqueting room with black walls part of the ongoing excavations in the block 10 of Regio IX, in Pompeii, near Naples.  RESTRICTED TO EDITORIAL USE - MANDATORY CREDIT \\&quot;AFP PHOTO \/ Parco Archeologico di Pompei press office \\&quot; - NO MARKETING NO ADVERTISING CAMPAIGNS - DISTRIBUTED AS A SERVICE TO CLIENTS\\n (Photo by Handout \/ PARCO ARCHEOLOGICO DI POMPEI PRESS OFFICE \/ AFP) \/ RESTRICTED TO EDITORIAL USE - MANDATORY CREDIT \\&quot;AFP PHOTO \/ Parco Archeologico di Pompei press office \\&quot; - NO MARKETING NO ADVERTISING CAMPAIGNS - DISTRIBUTED AS A SERVICE TO CLIENTS&quot;,&quot;created_timestamp&quot;:&quot;1712827474&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;ITALY-ARCHAEOLOGY-POMPEII&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"ITALY-ARCHAEOLOGY-POMPEII\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;This handout picture released by the archaelogical park of Pompeii on April 11, 2024 shows frescoes depicting mythological characters Helen and Paris according to a Greek inscription placed between the two figures in a banqueting room with black walls part of the ongoing excavations in the block 10 of Regio IX, in Pompeii, near Naples.  RESTRICTED TO EDITORIAL USE &amp;#8211; MANDATORY CREDIT \u00ab\u00a0AFP PHOTO \/ Parco Archeologico di Pompei press office \u00a0\u00bb &amp;#8211; NO MARKETING NO ADVERTISING CAMPAIGNS &amp;#8211; DISTRIBUTED AS A SERVICE TO CLIENTS&lt;br \/&gt;\n (Photo by Handout \/ PARCO ARCHEOLOGICO DI POMPEI PRESS OFFICE \/ AFP) \/ RESTRICTED TO EDITORIAL USE &amp;#8211; MANDATORY CREDIT \u00ab\u00a0AFP PHOTO \/ Parco Archeologico di Pompei press office \u00a0\u00bb &amp;#8211; NO MARKETING NO ADVERTISING CAMPAIGNS &amp;#8211; DISTRIBUTED AS A SERVICE TO CLIENTS&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2024\/04\/img_6849-1.jpg?fit=700%2C525&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2024\/04\/img_6849-1.jpg?resize=700%2C525&#038;ssl=1\" class=\"wp-image-19950\" srcset=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2024\/04\/img_6849-1.jpg?resize=700%2C525&amp;ssl=1 700w, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2024\/04\/img_6849-1.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2024\/04\/img_6849-1.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2024\/04\/img_6849-1.jpg?resize=702%2C526&amp;ssl=1 702w, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2024\/04\/img_6849-1.jpg?w=800&amp;ssl=1 800w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption class=\"wp-element-caption\">Une fresque d\u00e9couverte \u00e0 Pomp\u00e9i repr\u00e9sentant H\u00e9l\u00e8ne, femme de M\u00e9n\u00e9las, le roi de Sparte, et P\u00e2ris, le prince troyen qui enleva cette derni\u00e8re.&nbsp;&nbsp;HANDOUT \/ AFP<\/figcaption><\/figure>\n\n\n\n<p>Cette pi\u00e8ce aux dimensions imposantes \u2013 15&nbsp;m\u00e8tres sur 6 \u2013 pr\u00e9sente des d\u00e9corations raffin\u00e9es de sujets mythologiques ressortant sur des murs au fond noir ainsi que des mosa\u00efques. Autant d\u2019\u00e9l\u00e9ments qui t\u00e9moignent du mode de vie luxueux r\u00e9gnant dans la cit\u00e9 antique d\u00e9truite et ensevelie sous les cendres en l\u2019an&nbsp;79 lors d\u2019une \u00e9ruption du V\u00e9suve.<\/p>\n\n\n\n<p>Lire la suite de l\u2019article : <a href=\"https:\/\/www.lemonde.fr\/sciences\/article\/2024\/04\/11\/decouverte-a-pompei-de-fresques-inspirees-de-la-guerre-de-troie_6227252_1650684.html\">https:\/\/www.lemonde.fr\/sciences\/article\/2024\/04\/11\/decouverte-a-pompei-de-fresques-inspirees-de-la-guerre-de-troie_6227252_1650684.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De splendides fresques inspir\u00e9es de la guerre de Troie ornant une salle de banquet ont \u00e9t\u00e9 d\u00e9couvertes \u00e0 Pomp\u00e9i, a annonc\u00e9, jeudi 11&nbsp;avril, la direction du c\u00e9l\u00e8bre site arch\u00e9ologique situ\u00e9 pr\u00e8s de Naples, dans le sud de l\u2019Italie. Cette pi\u00e8ce aux dimensions imposantes \u2013 15&nbsp;m\u00e8tres sur 6 \u2013 pr\u00e9sente des d\u00e9corations raffin\u00e9es de sujets mythologiques [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11,17],"tags":[],"class_list":{"0":"post-19951","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nouvelles-de-lhistoire","8":"category-sur-le-web","9":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2024\/04\/img_6849-1.jpg?resize=600%2C400&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2024\/04\/img_6849-1.jpg?resize=600%2C600&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2024\/04\/img_6849-1.jpg?fit=800%2C600&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-5bN","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":18033,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2020\/12\/26\/un-fast-food-antique-decouvert-intact-dans-les-ruines-de-pompei\/","url_meta":{"origin":19951,"position":0},"title":"Un \u00ab\u00a0fast-food\u00a0\u00bb antique d\u00e9couvert intact dans les ruines de Pompei","author":"Lyonel Kaufmann","date":"26 d\u00e9cembre 2020","format":false,"excerpt":"Voici une nouvelle qui int\u00e9ressera celles et ceux qui travaillent en 6e Harmos le th\u00e8me 8 Dans l'Antiquit\u00e9 \u2013 vie quotidienne dans le monde romain et plus particuli\u00e8rement le sujet de la nourriture\/alimentation. Un thermopolium a \u00e9t\u00e9 mis au jour \u00e0 Pomp\u00e9i, ont annonc\u00e9 samedi les responsables du site arch\u00e9ologique\u2026","rel":"","context":"Dans &quot;BP13\/22SHS Enseigner les sciences humaines et sociales aux cycles 1 et 2&quot;","block_context":{"text":"BP13\/22SHS Enseigner les sciences humaines et sociales aux cycles 1 et 2","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/cours-et-seminaires\/bp13shn-enseigner-les-sciences-sociales-et-les-sciences-de-la-nature-aux-cycles-1-et-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/11853000.image_.jpeg?fit=640%2C480&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/11853000.image_.jpeg?fit=640%2C480&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/12\/11853000.image_.jpeg?fit=640%2C480&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":18241,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2021\/02\/28\/decouverte-dun-char-de-lepoque-romaine-pres-de-pompei\/","url_meta":{"origin":19951,"position":1},"title":"D\u00e9couverte d&rsquo;un char de l&rsquo;\u00e9poque romaine pr\u00e8s de Pomp\u00e9i","author":"Lyonel Kaufmann","date":"28 f\u00e9vrier 2021","format":false,"excerpt":"Un d\u00e9tail du char de c\u00e9r\u00e9monie romain exhum\u00e9 de Pomp\u00e9i, samedi 27 f\u00e9vrier 2021. \u2014 \u00a9 AFP Le parc arch\u00e9ologique de Pomp\u00e9i a annonc\u00e9 samedi la d\u00e9couverte d'un grand char de c\u00e9r\u00e9monie. Il a \u00e9t\u00e9 retrouv\u00e9 dans un excellent \u00e9tat, \u00e0 quelques centaines de m\u00e8tres seulement au nord du c\u00e9l\u00e8bre\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2021\/02\/file7ep0wxn69gy1ggaos40u-e1678962835311.jpg?fit=720%2C392&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2021\/02\/file7ep0wxn69gy1ggaos40u-e1678962835311.jpg?fit=720%2C392&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2021\/02\/file7ep0wxn69gy1ggaos40u-e1678962835311.jpg?fit=720%2C392&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2021\/02\/file7ep0wxn69gy1ggaos40u-e1678962835311.jpg?fit=720%2C392&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":17531,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2020\/07\/04\/au-grand-palais-une-balade-immersive-dans-les-rues-de-pompei\/","url_meta":{"origin":19951,"position":2},"title":"Au Grand Palais, une balade immersive dans les rues de Pomp\u00e9i","author":"Lyonel Kaufmann","date":"4 juillet 2020","format":false,"excerpt":"Reconstitution en 3D du V\u00e9suve dans le cadre de l'exposition \u00ab Pomp\u00e9i \u00bb, au Grand Palais, \u00e0 Paris, le 26 juin. DIDIER PLOWY Pomp\u00e9i en a vu d'autres. La ville romaine a \u00e9t\u00e9 d\u00e9truite par l'\u00e9ruption du V\u00e9suve en l'an 79 ; ses habitants ont succomb\u00e9 \u00e0 d'horribles nu\u00e9es ardentes\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/07\/e061fad_612104220-vue-d-expo-3-c-Rmn-Grand-Palais-Photo-Didier-Plowy.jpg?fit=688%2C459&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/07\/e061fad_612104220-vue-d-expo-3-c-Rmn-Grand-Palais-Photo-Didier-Plowy.jpg?fit=688%2C459&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/07\/e061fad_612104220-vue-d-expo-3-c-Rmn-Grand-Palais-Photo-Didier-Plowy.jpg?fit=688%2C459&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":5501,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2012\/06\/01\/visites-virtuelles-de-sites-historiques-par-google\/","url_meta":{"origin":19951,"position":3},"title":"Visites virtuelles de sites historiques par Google","author":"Lyonel Kaufmann","date":"1 juin 2012","format":false,"excerpt":"Google World Wonders est le nouveau projet de Google dans le domaine du patrimoine. Il s'agit d'une plateforme de ressources p\u00e9dagogiques destin\u00e9e aux \u00e9tudiants et enseignants, qui propose une d\u00e9couverte virtuelle de quelques-uns des sites les plus c\u00e9l\u00e8bres au monde.\u00a0 Avec la technologie Street View, les internautes peuvent visiter Pomp\u00e9i,\u2026","rel":"","context":"Dans &quot;Histoire active&quot;","block_context":{"text":"Histoire active","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-active\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/022.jpg?fit=480%2C360&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8093,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2014\/07\/06\/joe-sacco-et-la-premiere-guerre-mondiale-comment-il-en-est-venu-a-realiser-une-exceptionnelle-tapisserie-sur-la-bataille-de-la-somme-slate-fr\/","url_meta":{"origin":19951,"position":4},"title":"Joe Sacco et la Premi\u00e8re Guerre mondiale: comment il en est venu \u00e0 r\u00e9aliser une exceptionnelle tapisserie sur la Bataille de la Somme &#124; Slate.fr","author":"Lyonel Kaufmann","date":"6 juillet 2014","format":false,"excerpt":"Le 1er juillet 1916, commence la bataille de la Somme, la plus meurtri\u00e8re que l'arm\u00e9e britannique ait jamais connue. Rencontre de Slate.fr avec l\u2019auteur de la longue fresque qui est expos\u00e9e tout cet \u00e9t\u00e9 \u00e0 la station Montparnasse \u00e0 Paris. D\u00e9tail de la tapisserie r\u00e9alis\u00e9e par Joe Sacco. Se jouant\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"wpid-tapisserie-sacco-2014-07-6-16-07.jpg","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2014\/07\/wpid-tapisserie-sacco-2014-07-6-16-07.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2014\/07\/wpid-tapisserie-sacco-2014-07-6-16-07.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2014\/07\/wpid-tapisserie-sacco-2014-07-6-16-07.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2014\/07\/wpid-tapisserie-sacco-2014-07-6-16-07.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2014\/07\/wpid-tapisserie-sacco-2014-07-6-16-07.jpg?resize=1050%2C600 3x"},"classes":[]},{"id":220,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2007\/08\/18\/links-for-2007-08-18\/","url_meta":{"origin":19951,"position":5},"title":"Liens (18.08.2007)","author":"Lyonel Kaufmann","date":"18 ao\u00fbt 2007","format":false,"excerpt":"Le Monde.fr : La guerre de Troie, un conflit entre Grecs et Hittites ? Lira-t-on, un jour, une version hittite du r\u00e9cit de la guerre de Troie? Pour cet article du journal Le Monde, il n'est pas absurde de le croire. (tags: Histoire Antiquit\u00e9 Gr\u00e8ce GuerreTroie Troie Hom\u00e8re)","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/19951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=19951"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/19951\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/19950"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=19951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=19951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=19951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}