{"id":205,"date":"2007-06-09T02:17:54","date_gmt":"2007-06-09T01:17:54","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/2007\/06\/09\/links-for-2007-06-09\/"},"modified":"2007-06-09T02:17:54","modified_gmt":"2007-06-09T01:17:54","slug":"links-for-2007-06-09","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2007\/06\/09\/links-for-2007-06-09\/","title":{"rendered":"Liens (09.06.2007)"},"content":{"rendered":"<ul class=\"delicious\">\n<li>\n<div class=\"delicious-link\"><a href=\"http:\/\/ww3.ac-creteil.fr\/hgc\/spip\/article.php3?id_article=828\">HistG\u00e9o Cr\u00e9teil &#8211; \u00ab\u00a0Le Sacre de Napol\u00e9on\u00a0\u00bb<\/a><\/div>\n<p>\t\tS\u00e9quence d&rsquo;enseignement relative au tableau de David sur le sacre de Napol\u00e9on. Elle recourt largement \u00e0 l&rsquo;utilisation (int\u00e9ressante) des M\u00e9dias et Technologies. Notamment d&rsquo;un logiciel de pr\u00e9sentation (PowerPoint).<\/p>\n<div class=\"delicious-tags\">(tags: <a href=\"http:\/\/del.icio.us\/histoirehep\/Histoire\">Histoire<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/R\u00e9volutions\">R\u00e9volutions<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/France\">France<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/Education&#038;M\u00e9dias\">Education&#038;M\u00e9dias<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/XIXe\">XIXe<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/HistoireArt\">HistoireArt<\/a>)<\/div>\n<\/li>\n<li>\n<div class=\"delicious-link\"><a href=\"http:\/\/www.timesonline.co.uk\/tol\/news\/uk\/education\/article1600686.ece\">Schools drop Holocaust lessons to avoid offence-News-UK-Education-TimesOnline<\/a><\/div>\n<p>\t\tUne enqu\u00eate de l&rsquo;Historical Association aupr\u00e8s des enseignants britanniques met en \u00e9vidence le fait que les enseignants  ont tendance \u00e0 \u00e9vacuer des sujets controvers\u00e9s tels que l&rsquo;Holocauste ou les Croisades pouvant choquer ou offenser leurs \u00e9l\u00e8ves.<br \/>\n\t\tL&rsquo;info remonte en fait au 2 avril 2007. Elle s&rsquo;appuye sur le rapport <a href=\"http:\/\/www.dfes.gov.uk\/research\/data\/uploadfiles\/RW100.pdf\"><i>Teaching Emotive and Controversial History 3-19 <\/i><\/a> (.pdf) publi\u00e9 par The Historical Association. Les auteurs \u00e9voquent comme principales difficult\u00e9s rencontr\u00e9es par les enseignant-e-s : la nature du sujet, son approche scientifique, la formation des profs, le temps disponible; les connaissances et les repr\u00e9sentations des \u00e9l\u00e8ves qui semblent oubli\u00e9es. Outre la question de l&rsquo;Holocauste, le apport propose 3 \u00e9tudes de cas : Britain and the Slave Trade (p 37), The Russian Civil War and the NEP (p 38), Muslim History (p 40). Or les journaux n&rsquo;ont titr\u00e9s que sur l&rsquo;Holocauste et les Croisades. Pourquoi?<br \/>\n\t\tMes remerciements \u00e0 <a href=\"http:\/\/clioweb.free.fr\/\">Daniel Letouzey (clioweb)<\/a> pour ses informations compl\u00e9mentaires.<\/p>\n<div class=\"delicious-tags\">(tags: <a href=\"http:\/\/del.icio.us\/histoirehep\/Histoire\">Histoire<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/Histoire&#038;M\u00e9moire\">Histoire&#038;M\u00e9moire<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/Holocauste\">Holocauste<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/Shoah\">Shoah<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/SujetsSensibles\">SujetsSensibles<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/39-45\">39-45<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/Croisades\">Croisades<\/a>)<\/div>\n<\/li>\n<li>\n<div class=\"delicious-link\"><a href=\"http:\/\/www.monde-diplomatique.fr\/2007\/04\/DUPONT\/14645\">\u00ab Rome \u00bb, ton univers impitoyable&#8230;, par Florence Dupont (Le Monde diplomatique)<\/a><\/div>\n<p>\t\tImmense succ\u00e8s, la s\u00e9rie \u00ab\u00a0Rome\u00a0\u00bb a \u00e9t\u00e9 diffus\u00e9e partout \u00e0 travers le monde et salu\u00e9e par la critique. Mais, sous une apparence objective, elle d\u00e9forme les faits et invente une ville qui n\u2019a jamais exist\u00e9.  Vision occidentale et machiste?<\/p>\n<div class=\"delicious-tags\">(tags: <a href=\"http:\/\/del.icio.us\/histoirehep\/Histoire\">Histoire<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/antiquit%C3%A9\">Antiquit\u00e9<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/Rome\">Rome<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/Education&#038;M\u00e9dias\">Education&#038;M\u00e9dias<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/Genre\">Genre<\/a>)<\/div>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>HistG\u00e9o Cr\u00e9teil &#8211; \u00ab\u00a0Le Sacre de Napol\u00e9on\u00a0\u00bb S\u00e9quence d&rsquo;enseignement relative au tableau de David sur le sacre de Napol\u00e9on. Elle recourt largement \u00e0 l&rsquo;utilisation (int\u00e9ressante) des M\u00e9dias et Technologies. Notamment d&rsquo;un logiciel de pr\u00e9sentation (PowerPoint). (tags: Histoire R\u00e9volutions France Education&#038;M\u00e9dias XIXe HistoireArt) Schools drop Holocaust lessons to avoid offence-News-UK-Education-TimesOnline Une enqu\u00eate de l&rsquo;Historical Association aupr\u00e8s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[18],"tags":[],"class_list":{"0":"post-205","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-annuaire-de-sites","8":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?fit=658%2C184&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-3j","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":15062,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2018\/10\/21\/percer-le-secret-de-napoleon-ier-grace-a-assassins-creed\/","url_meta":{"origin":205,"position":0},"title":"Percer le secret de Napol\u00e9on Ier gr\u00e2ce \u00e0 Assassin\u2019s Creed ?","author":"Lyonel Kaufmann","date":"21 octobre 2018","format":false,"excerpt":"Du 19 octobre au 4 novembre 2018, le Mus\u00e9e de l\u2019Arm\u00e9e (Paris) accueille un jeu immersif in\u00e9dit, d\u00e9velopp\u00e9 en partenariat avec l\u2019agence Cultival et Ubisoft. Le public est invit\u00e9 \u00e0 percer le secret de Napol\u00e9on Ier tout en d\u00e9couvrant l\u2019H\u00f4tel national des Invalides \u00ab\u00a0comme il ne l\u2019a jamais vu\u00a0\u00bb !\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/10\/img_6833.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/10\/img_6833.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/10\/img_6833.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/10\/img_6833.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/10\/img_6833.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":7500,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2013\/09\/15\/revue-de-presse-napoleon-1-caricatures-biblioweb\/","url_meta":{"origin":205,"position":1},"title":"Revue de presse : Napol\u00e9on (1) Caricatures &#124; Biblioweb","author":"Lyonel Kaufmann","date":"15 septembre 2013","format":false,"excerpt":"Sitographie et bibliographie sur la caricature anti-napol\u00e9onnienne. Napol\u00e9on (1) Caricatures | Biblioweb","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/talmanapo.gif?fit=537%2C720&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/talmanapo.gif?fit=537%2C720&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/talmanapo.gif?fit=537%2C720&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":3827,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/06\/09\/limage-en-cours-dhistoire-crdp-de-lacademie-de-lyon\/","url_meta":{"origin":205,"position":2},"title":"L&#039;IMAGE EN COURS D&#039;HISTOIRE &#8211; CRDP de l\u2019acad\u00e9mie de LYON","author":"Lyonel Kaufmann","date":"9 juin 2011","format":false,"excerpt":"L\u2019id\u00e9e que les images sont plus simples \u00e0 lire, \u00e0 comprendre et \u00e0 analyser doit \u00eatre nuanc\u00e9e. Evoquer la culture des \u00e9l\u00e8ves principalement bas\u00e9e sur les images n\u2019est pas suffisant. Certes ils ont des r\u00e9f\u00e9rences culturelles li\u00e9es \u00e0 la t\u00e9l\u00e9vision ou au cin\u00e9ma mais ils conservent une grande part de\u2026","rel":"","context":"Dans &quot;Didactique&quot;","block_context":{"text":"Didactique","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":14081,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2018\/04\/25\/tablettes-au-college-a-rixheim-le-numerique-revolutionnait-lenseignement-de-lhistoire\/","url_meta":{"origin":205,"position":3},"title":"Tablettes au coll\u00e8ge : \u00e0 Rixheim, le num\u00e9rique r\u00e9volutionnerait \u00a0l&rsquo;enseignement de l&rsquo;histoire","author":"Lyonel Kaufmann","date":"25 avril 2018","format":false,"excerpt":"Depuis d\u00e9cembre 2017, tous les \u00e9l\u00e8ves du coll\u00e8ge Dreyfus de Rixheim ont une tablette dans leur sac. L'article de France 3 Grand Est rend compte de cette exp\u00e9rience et oscille entre la pens\u00e9e magique (\"Fini, donc, le cours magistral, \u00e9crit au tableau\" ou \"Les tablettes sont donc en train de\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/04\/mobile-phone-1875813_960_720.jpg?fit=960%2C640&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/04\/mobile-phone-1875813_960_720.jpg?fit=960%2C640&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/04\/mobile-phone-1875813_960_720.jpg?fit=960%2C640&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/04\/mobile-phone-1875813_960_720.jpg?fit=960%2C640&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2948,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/07\/09\/napoleon-1-caricatures-biblioweb\/","url_meta":{"origin":205,"position":4},"title":"Napol\u00e9on 1 Caricatures &#124; Biblioweb","author":"Lyonel Kaufmann","date":"9 juillet 2010","format":false,"excerpt":"Biblioweb nous propose un tr\u00e8s int\u00e9ressant inventaire des ressources relatives \u00e0 la caricature napol\u00e9onienne. Les ressources pr\u00e9sent\u00e9es sont essentiellement issues du r\u00e9sultat de ses recherches et l'inventaire se conclut sur une s\u00e9lection d'ouvrages. L'article: Napol\u00e9on 1 Caricatures | Biblioweb.","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/talmanapo1.gif?fit=537%2C720&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/talmanapo1.gif?fit=537%2C720&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/talmanapo1.gif?fit=537%2C720&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":1145,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2009\/03\/02\/microhistoire-de-la-semaine-twitter-3\/","url_meta":{"origin":205,"position":5},"title":"MicroHistoire de la Semaine (Twitter)","author":"Lyonel Kaufmann","date":"2 mars 2009","format":false,"excerpt":"Safari en version 4 b\u00eata vaut vraiment le d\u00e9tour notamment parce qu'il plus v\u00e9loce. :D http:\/\/ow.ly\/sH9 # Traduit en anglais, le roman \u00abLes Bienveillantes\u00bb de Jonathan Littell est \u00e9charp\u00e9 par le \u00abNew York Times\u00bb http:\/\/ow.ly\/tbj # RT @clionautes: Histoire du Moyen Orient en 90 secondes flash: http:\/\/tinyurl.com\/yej2qa # Une approche\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=205"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/205\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/9896"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}