{"id":211,"date":"2007-07-26T02:19:24","date_gmt":"2007-07-26T01:19:24","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/2007\/07\/26\/links-for-2007-07-26\/"},"modified":"2007-07-26T02:19:24","modified_gmt":"2007-07-26T01:19:24","slug":"links-for-2007-07-26","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2007\/07\/26\/links-for-2007-07-26\/","title":{"rendered":"Liens (26.07.2007)"},"content":{"rendered":"<ul class=\"delicious\">\n<li> <a href=\"http:\/\/www.citationspolitiques.com\/index.php3\">Dictionnaire des citations politiques &#8211; (c) Damien B\u00e9goc<\/a><br \/>\nDictionnaire des citations politiques de Damien B\u00e9goc (version en ligne): 1275 citations de toutes tendances, 400 auteurs fran\u00e7ais ou \u00e9trangers, contemporains ou classiques, index de 720 mots-cl\u00e9s et 4600 entr\u00e9es.<\/p>\n<p class=\"delicious-tags\">(tags: <a href=\"http:\/\/del.icio.us\/histoirehep\/Histoire\">Histoire<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/Politique\">Politique<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/Citation\">Citation<\/a>)<\/p>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Dictionnaire des citations politiques &#8211; (c) Damien B\u00e9goc Dictionnaire des citations politiques de Damien B\u00e9goc (version en ligne): 1275 citations de toutes tendances, 400 auteurs fran\u00e7ais ou \u00e9trangers, contemporains ou classiques, index de 720 mots-cl\u00e9s et 4600 entr\u00e9es. (tags: Histoire Politique Citation)<\/p>\n","protected":false},"author":1,"featured_media":9896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[18],"tags":[],"class_list":{"0":"post-211","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-annuaire-de-sites","8":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?fit=658%2C184&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-3p","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":4576,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2009\/10\/21\/les-colonies-netaient-pas-la-france-nous\/","url_meta":{"origin":211,"position":0},"title":"Africultures &#8211; Article &#8211; Enjeux politiques de l&#8217;histoire coloniale","author":"Lyonel Kaufmann","date":"21 octobre 2009","format":"quote","excerpt":"Les colonies n\u2019\u00e9taient pas la France, nous rebat-on les oreilles, mais l\u2019expansion du g\u00e9nie fran\u00e7ais. Mais ne sont-ce pas les m\u00eames qui nous assurent que Vichy n\u2019\u00e9tait pas la France, mais la \u201cn\u00e9gation de la R\u00e9publique\u201d\u00a0?","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4421,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/09\/01\/les-ecoles-sont-dabord-des-lieux-dapprentissage\/","url_meta":{"origin":211,"position":1},"title":"Ludovia 2011\u00a0: les politiques et la mobilit\u00e9\u00a0&#124;&#124;\u00a0Relief","author":"Lyonel Kaufmann","date":"1 septembre 2011","format":"quote","excerpt":"Les \u00e9coles sont d\u2019abord des lieux d\u2019apprentissage, et non de gestion du mat\u00e9riel informatique. Il faut lib\u00e9rer les \u00e9coles de la gestion des appareils. D\u00e8s lors que le num\u00e9rique devient une extension de l\u2019homme, il faut apprendre \u00e0 les consommer.","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4412,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/11\/25\/les-resultats-quantitatifs-de-letude-menee-par\/","url_meta":{"origin":211,"position":2},"title":"Place des femmes&#160;: peut mieux faire g\u00e9n\u00e9ral sur les manuels scolaires &#124; Mediapart","author":"Lyonel Kaufmann","date":"25 novembre 2011","format":"quote","excerpt":"Les r\u00e9sultats quantitatifs de l\u2019\u00e9tude men\u00e9e par Amandine Berton Schmitt sont en effet assez effrayants. Dans les onze manuels \u00e9tudi\u00e9s, sur les 339 biographies propos\u00e9es, seulement onze d\u2019entre elles sont consacr\u00e9es \u00e0 des femmes, soit seulement 3,2%. \u00ab\u00a0Parmi les auteur-e-s de documents propos\u00e9s, 4\u00a0% sont des femmes. 3,5% des documents\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4628,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2009\/04\/20\/18-juin-1940-le-general-de-gaulle-envoit-un\/","url_meta":{"origin":211,"position":3},"title":"Quand Internet croit faire de la politique &#8211; Framablog","author":"Lyonel Kaufmann","date":"20 avril 2009","format":"quote","excerpt":"18 juin 1940 - le g\u00e9n\u00e9ral de Gaulle envoit un message sur Twitter et cr\u00e9e une cause sur Facebook. 19 juin 1940 - d\u00e9j\u00e0 plus de 30 millions d\u2019internautes ont rejoint les rangs des \u201cFran\u00e7ais Libres\u201d sur les r\u00e9seaux sociaux. Les SMS et mails de soutien affluent. Des milliers de\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":7621,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2013\/10\/21\/damien-carron-la-suisse-et-la-guerre-dindependance-algerienne-1954-1962-lausanne-2013-h-soz-u-kult-rezensionen-bucher\/","url_meta":{"origin":211,"position":4},"title":"Damien Carron: La Suisse et la guerre d\u2019ind\u00e9pendance alg\u00e9rienne (1954\u20131962). Lausanne 2013. &#8211; H-Soz-u-Kult \/ Rezensionen \/ B\u00fccher","author":"Lyonel Kaufmann","date":"21 octobre 2013","format":false,"excerpt":"\u201eLa Suisse et la guerre d\u2019ind\u00e9pendance alg\u00e9rienne (1954\u20131962)\u201c est la publication de la th\u00e8se de doctorat de Damien Caron, soutenue \u00e0 l\u2019universit\u00e9 de Fribourg en avril 2010. L\u2019ouvrage se base sur des sources alg\u00e9riennes, fran\u00e7aises et suisses, conserv\u00e9es dans leurs archives nationales respectives ainsi que sur des sources orales et\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4533,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/05\/05\/les-tic-sont-interessantes-et-plus-generalement\/","url_meta":{"origin":211,"position":5},"title":"http:\/\/www.brunodevauchelle.com\/blog\/?p=654","author":"Lyonel Kaufmann","date":"5 mai 2010","format":"quote","excerpt":"Les TIC sont int\u00e9ressantes et plus g\u00e9n\u00e9ralement les technologies \u00e9ducatives, car elles sont, depuis les ann\u00e9es 50\u00a0en France, positionn\u00e9es \u00e0 priori comme \u00ab\u00a0un corps \u00e9tranger\u00a0\u00bb \u00e0 introduire, voire \u00e0 int\u00e9grer dans le corps m\u00eame de l\u2019enseignement (scolaire et universitaire). Corps \u00e9tranger, certes mais pas compl\u00e8tement. En effet si d\u2019une part\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=211"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/211\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/9896"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}