{"id":253,"date":"2007-11-19T23:51:42","date_gmt":"2007-11-19T22:51:42","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/2007\/11\/19\/mshis31-lenseignant-dhistoire-et-linternet-27112007\/"},"modified":"2007-11-19T23:51:42","modified_gmt":"2007-11-19T22:51:42","slug":"mshis31-lenseignant-dhistoire-et-linternet-27112007","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2007\/11\/19\/mshis31-lenseignant-dhistoire-et-linternet-27112007\/","title":{"rendered":"MSHIS31 &#8211; L&#039;enseignant d&#039;histoire et l&#039;internet (20.11.2007)"},"content":{"rendered":"<div align=\"justify\">La conf&eacute;rence de Philippe Rygiel est centr&eacute;e sur l&rsquo;usage de l&rsquo;internet par l&rsquo;historien universitaire Dans son introduction &agrave; <i>Les historiens, leurs revues et Internet (France, Espagne, Italie)<\/i> [Paris, Publibook, 2005, 193&#160;pages], Philippe Rygiel concluait de la mani&egrave;re suivante<\/p>\n<blockquote><p><i>&laquo;Nous esp&eacute;rons, sans pr&eacute;sumer d&rsquo;un accord sur les fins, que les &eacute;l&eacute;ments de r&eacute;flexion ainsi propos&eacute;s, convaincront les lecteurs de la n&eacute;cessit&eacute; d&rsquo;un d&eacute;bat, auquel ne prendraient pas part les seuls sp&eacute;cialistes de la question, sur ce qu&rsquo;utiliser un ordinateur et se connecter au r&eacute;seau veut dire pour l&rsquo;historien.&raquo;<\/i><\/p><\/blockquote>\n<p>Pr&eacute;alablement, il pr&eacute;sentait la structure de l&rsquo;ouvrage collectif de la mani&egrave;re suivante :<\/p>\n<blockquote><p><i>&laquo;L&rsquo;organisation de l&rsquo;ouvrage prend sens &agrave; partir de ces positions. Nous avons tent&eacute; de r&eacute;fl&eacute;chir, en historiens, ce que sont la plupart des auteurs r&eacute;unis ici, &agrave; partir de r&eacute;cits de pratiques, ou de l&rsquo;observation des ressources offertes aux historiens par le r&eacute;seau, aux pratiques professionnelles induites ou permises par la participation au r&eacute;seau. Il s&rsquo;agissait en somme d&rsquo;examiner les possibles transformations d&rsquo;une activit&eacute; con&ccedil;ue comme un m&eacute;tier, d&eacute;fini par ses pratiques, les relations sociales qu&rsquo;il implique et ses lieux d&rsquo;exercices. Et la structure de l&rsquo;ouvrage refl&egrave;te cette conception, qui distingue les temps de la lecture, de l&rsquo;&eacute;criture, de la publication et de l&rsquo;enseignement [&#8230;].&raquo;<\/i><\/p><\/blockquote>\n<p>Cet atelier maintenant &agrave; pour objectif de s&rsquo;interroger sur la traduction de ces usages relativement &agrave; l&rsquo;enseignant-e d&rsquo;histoire en reprenant le questionnement de Philippe Rygiel.<b> Trois questions pour lancer la discussion :<\/b><\/p>\n<blockquote><p><b>&#8211; qu&rsquo;est-ce qu&rsquo;utiliser un ordinateur et se connecter au r&eacute;seau pour l&rsquo;enseignant-e d&rsquo;histoire?<br \/>\n&#8211; quelles sont les possibles transformations de l&rsquo;activiti&eacute; professionnelle de l&rsquo;enseigant-e- d&rsquo;histoire?<br \/>\n&#8211; quelles sont les opportunit&eacute;s offertes par les outils num&eacute;riques actuels dans ma pratique professionnelle?<\/b><\/p><\/blockquote>\n<p>Pour vous aider dans votre travail, voici en premier lieu une liste de ressources en ligne &agrave; consulter &agrave; deux.<\/p>\n<p><b><i>Du c&ocirc;t&eacute; de l&rsquo;histoire savante :<\/i><\/b><br \/>\n&#149; <a href=\"http:\/\/www.revues.org\/\">http:\/\/www.revues.org\/<\/a><br \/>\n&#149; <a href=\"http:\/\/barthes.ens.fr\/clio\/outils\/biblios\/histhist.html\">http:\/\/barthes.ens.fr\/clio\/outils\/biblios\/histhist.html<\/a><br \/>\n&#149; <a href=\"http:\/\/www.parutions.com\/index.php?pid=1&#038;rid=4\">http:\/\/www.parutions.com\/index.php?pid=1&#038;rid=4<\/a><\/p>\n<p>&#149; <a href=\"http:\/\/www.histoire.presse.fr\/\">http:\/\/www.histoire.presse.fr\/<\/a><br \/>\n&#149; <a href=\"http:\/\/histoire.typepad.fr\/le_blog_de_lhistoire\/\">http:\/\/histoire.typepad.fr\/le_blog_de_lhistoire\/<\/a><br \/>\n&#149; <a href=\"http:\/\/www.historia.presse.fr\/\">http:\/\/www.historia.presse.fr\/<\/a><\/p>\n<p>&#149; <a href=\"http:\/\/www.lethiboniste.blogspot.com\/\">http:\/\/www.lethiboniste.blogspot.com\/<\/a><\/p>\n<p>&#149; <a href=\"http:\/\/www.digitalhistory.uh.edu\/history_portal.cfm\">http:\/\/www.digitalhistory.uh.edu\/history_portal.cfm<\/a><\/p>\n<p>&#149; <a href=\"http:\/\/www.hls-dhs-dss.ch\/index.php?lg=f\">http:\/\/www.hls-dhs.ch<\/a><\/p>\n<p><b><i>Du c&ocirc;t&eacute; de l&rsquo;enseignement et de la didactique:<\/i><\/b><br \/>\n&#149; <a href=\"http:\/\/www.didactique-histoire.net\">http:\/\/www.didactique-histoire.net<\/a><br \/>\n&#149; <a href=\"http:\/\/www.tacite.ch\">http:\/\/www.tacite.ch<\/a><br \/>\n&#149; <a href=\"https:\/\/lyonelkaufmann.ch\/histoire\">https:\/\/lyonelkaufmann.ch\/histoire<\/a><br \/>\n&#149; <a href=\"http:\/\/www.aphg.asso.fr\/\">http:\/\/www.aphg.asso.fr\/<\/a><br \/>\n&#149; <a href=\"http:\/\/www.fritic.org\/dyn\/9.asp?url=39025%2Easp\">http:\/\/www.fritic.org\/dyn\/9.asp?url=39025%2Easp<\/a><br \/>\n&#149; <a href=\"http:\/\/www.hist.net\/\">http:\/\/www.hist.net\/<\/a><br \/>\n&#149; <a href=\"http:\/\/campus.ph.fhnw.ch\/Geschichte\/GeschichteLernenMitWikisUndWikipedia\">http:\/\/campus.ph.fhnw.ch\/Geschichte\/GeschichteLernenMitWikisUndWikipedia<\/a><\/p>\n<p><b><i>Du c&ocirc;t&eacute; institutionnel et des usages politiques et m&eacute;moriels de l&rsquo;histoire:<\/i><\/b><br \/>\n&#149; <a href=\"http:\/\/www.edu-vd.ch\/liens\/accueilMP.html\">http:\/\/www.edu-vd.ch\/liens\/accueilMP.html<\/a><br \/>\n&#149; <a href=\"http:\/\/www.educa.ch\/dyn\/12.asp\">http:\/\/www.educa.ch\/dyn\/12.asp<\/a><br \/>\n&#149; <a href=\"http:\/\/jahia.rpn.ch\/\">http:\/\/jahia.rpn.ch\/<\/a><br \/>\n&#149; <a href=\"http:\/\/www2.educnet.education.fr\/histgeo\/\">http:\/\/www2.educnet.education.fr\/histgeo\/<\/a><br \/>\n&#149; <a href=\"http:\/\/www.cndp.fr\/spinoo\/\">http:\/\/www.cndp.fr\/spinoo\/<\/a><br \/>\n&#149; <a href=\"http:\/\/eduscol.education.fr\/\">http:\/\/eduscol.education.fr\/<\/a><br \/>\n&#149; <a href=\"http:\/\/www.ac-orleans-tours.fr\/hist-geo\/officiels\/Education-Nationale.htm\">http:\/\/www.ac-orleans-tours.fr\/hist-geo\/officiels\/Education-Nationale.htm<\/a><\/p>\n<p>&#149; <a href=\"http:\/\/ecehg.inrp.fr\/ECEHG\">http:\/\/ecehg.inrp.fr\/ECEHG<\/a><\/p>\n<p><b><i>Du c&ocirc;t&eacute; de l&rsquo;&eacute;change professionnel et de la mutualisation des ressources:<\/i><\/b><br \/>\n&#149; <a href=\"http:\/\/www.h-net.org\/%7Efrancais\/\">http:\/\/www.h-net.org\/%7Efrancais\/ <\/a><br \/>\n&#149; <a href=\"http:\/\/www.schoolhistory.co.uk\/forum\/index.php?\">http:\/\/www.schoolhistory.co.uk\/forum\/index.php<\/a><br \/>\n&#149; <a href=\"http:\/\/www.clionautes.org\/\">http:\/\/www.clionautes.org\/<\/a><br \/>\n&#149; <a href=\"http:\/\/soshg.free.fr\/\">http:\/\/soshg.free.fr\/<\/a><br \/>\n&#149; <a href=\"http:\/\/hypo.ge-dip.etat-ge.ch\/www\/cliotexte\/\">http:\/\/hypo.ge-dip.etat-ge.ch\/www\/cliotexte\/<\/a><br \/>\n&#149; <a href=\"http:\/\/clioweb.free.fr\/\">http:\/\/clioweb.free.fr\/<\/a> dont <a href=\"http:\/\/clioweb.free.fr\/102.htm\">http:\/\/clioweb.free.fr\/102.htm<\/a><\/p>\n<p><b><i>Du c&ocirc;t&eacute; de l&rsquo;enseignant et de ses &eacute;l&egrave;ves :<\/i><\/b><br \/>\n&#149; Le web p&eacute;dagogique : <a href=\"http:\/\/lewebpedagogique.com\">http:\/\/lewebpedagogique.com<\/a><br \/>\n\tdont  &#149; <a href=\"http:\/\/lewebpedagogique.com\/histoire\/\">http:\/\/lewebpedagogique.com\/histoire\/<\/a><br \/>\n\t\t&#149; <a href=\"http:\/\/lewebpedagogique.com\/termvictorlouis\">http:\/\/lewebpedagogique.com\/termvictorlouis<\/a><br \/>\n\t\t&#149; <a href=\"http:\/\/lewebpedagogique.com\/reussirenhg\">http:\/\/lewebpedagogique.com\/reussirenhg<\/a><br \/>\n\t\t&#149; <a href=\"http:\/\/lewebpedagogique.com\/bsentier\">http:\/\/lewebpedagogique.com\/bsentier<\/a><br \/>\n\t\t&#149; <a href=\"http:\/\/lewebpedagogique.com\/mariedesmares\">http:\/\/lewebpedagogique.com\/mariedesmares<\/a><\/p>\n<p>&#149; <a href=\"http:\/\/hgeo-college.blogspot.com\/\">http:\/\/hgeo-college.blogspot.com\/<\/a><br \/>\n&#149; <a href=\"http:\/\/s185254037.onlinehome.fr\/\">http:\/\/s185254037.onlinehome.fr\/<\/a><br \/>\n&#149; <a href=\"http:\/\/www.julien-eggenberger.ch\/index.php?option=com_docman&#038;Itemid=43\">http:\/\/www.julien-eggenberger.ch\/index.php?option=com_docman&#038;Itemid=43<\/a><br \/>\n&#149; <a href=\"http:\/\/www.gymnase-morges.ch\/docs\/Lienshist.html\">http:\/\/www.gymnase-morges.ch\/docs\/Lienshist.html<\/a><\/p>\n<p>&#149; <a href=\"http:\/\/kenny.over-blog.net\/article-1245614.html\">http:\/\/kenny.over-blog.net\/article-1245614.html<\/a><br \/>\n&#149; <a href=\"http:\/\/www.nack.ch\/wiki\/index.php\/Accueil\">http:\/\/www.nack.ch\/wiki\/index.php\/Accueil<\/a> puis <a href=\"http:\/\/www.nack.ch\/wiki\/index.php\/Histoire\">http:\/\/www.nack.ch\/wiki\/index.php\/Histoire<\/a><br \/>\n&#149; <a href=\"http:\/\/memoires-france-allemagne.blogspot.com\/\">http:\/\/memoires-france-allemagne.blogspot.com\/<\/a><br \/>\n&#149; <a href=\"http:\/\/histoirehep.blogspot.com\/\">http:\/\/histoirehep.blogspot.com\/<\/a><\/p>\n<p>&#149; e-learning : des cours en ligne existent comme ici avec Moodle (<a href=\"http:\/\/www.ecddfr.ch\/moodle\/course\/index.php\">http:\/\/www.ecddfr.ch\/moodle\/course\/index.php<\/a> ou <a href=\"http:\/\/www.cscfr.ch\/moodle\/\">http:\/\/www.cscfr.ch\/moodle\/<\/a>). Cependant, l&rsquo;acc&egrave;s est r&eacute;serv&eacute; aux gens inscrits. Ils sont donc mentionn&eacute;s sans qu&rsquo;ils vous soient possibles de les parcourir r&eacute;ellement. Par ailleurs,<a href=\"http:\/\/www.fristoria.ch\/\"> http:\/\/Fristoria.ch<\/a> est &eacute;galement r&eacute;alis&eacute; sur la base d&rsquo;une plate-forme de e-learning sans &ecirc;tre exactement une plate-forme (interactive) de cours en lignes; ici Moodle est utilis&eacute; comme une banque de documents et de s&eacute;quences d&rsquo;enseignement r&eacute;alis&eacute;s par des enseignant-e-s et disponibles en ligne.<\/p>\n<p>Mais s&ucirc;rement en connaissez-vous d&rsquo;autres? Pas de probl&egrave;me, ajoutez-les &agrave; votre r&eacute;flexion&#8230;<\/p>\n<blockquote><p><b>Au terme de ce parcours, quels sont les &eacute;l&eacute;ments significatifs que vous retenez relativement aux trois questions initiales. Et pour quelles raisons? Chaque duo r&eacute;dige &agrave; cet effet un commentaire &agrave; la suite de ce billet.<\/b><\/p><\/blockquote>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La conf&eacute;rence de Philippe Rygiel est centr&eacute;e sur l&rsquo;usage de l&rsquo;internet par l&rsquo;historien universitaire Dans son introduction &agrave; Les historiens, leurs revues et Internet (France, Espagne, Italie) [Paris, Publibook, 2005, 193&#160;pages], Philippe Rygiel concluait de la mani&egrave;re suivante &laquo;Nous esp&eacute;rons, sans pr&eacute;sumer d&rsquo;un accord sur les fins, que les &eacute;l&eacute;ments de r&eacute;flexion ainsi propos&eacute;s, convaincront [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11],"tags":[],"class_list":{"0":"post-253","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nouvelles-de-lhistoire","8":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?fit=658%2C184&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-45","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":178,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2007\/03\/19\/bp110-complements-a-la-deuxieme-seance\/","url_meta":{"origin":253,"position":0},"title":"BP110 &#8211; Compl\u00e9ments \u00e0 la deuxi\u00e8me s\u00e9ance (19.03.2007)","author":"Lyonel Kaufmann","date":"19 mars 2007","format":false,"excerpt":"Les extraits utilis\u00e9s lors de notre s\u00e9ance du lundi 19 mars 2007 figurent tous dans l'ouvrage suivant :\u00a0 Delacroix Ch.\u00a0 (2003). Histoire et historiens en France depuis 1945. Paris: Association pour la diffusion de la pens\u00e9e fran\u00e7aise, 319 p. Le texte de Fernand Braudel [extrait de La M\u00e9diterran\u00e9e et le\u2026","rel":"","context":"Dans &quot;BP110 - Faire de l'histoire aujourd'hui&quot;","block_context":{"text":"BP110 - Faire de l'histoire aujourd'hui","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/cours-et-seminaires\/bp110-faire-de-lhistoire-aujourdhui\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":310,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2008\/04\/02\/une-encyclopedie-des-violences-de-masse-sur-internet\/","url_meta":{"origin":253,"position":1},"title":"Une encyclop\u00e9die des violences de masse sur Internet","author":"Lyonel Kaufmann","date":"2 avril 2008","format":false,"excerpt":"Le XXe si\u00e8cle poss\u00e8de le triste privil\u00e8ge d'\u00eatre celui des massacres, des g\u00e9nocides ou de l'\u00e9puration ethnique. Et d'autres exactions vari\u00e9es pour lesquelles il a fallu inventer de nouveaux termes : d\u00e9mocides, f\u00e9micides, urbicides, etc. Environ 210 millions d'individusauraient ainsi p\u00e9ri, dont les trois quarts des civils : Tutsis, Juifs,\u2026","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/AKdq4.jpg?fit=320%2C240&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7062,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2013\/05\/15\/philippe-delisle-bande-dessinee-franco-belge-et-imaginaire-colonial-emulations-revue-des-jeunes-chercheurs-en-sciences-sociales\/","url_meta":{"origin":253,"position":2},"title":"Philippe Delisle &#8211; Bande dessin\u00e9e franco-belge et imaginaire colonial &#124; \u00c9mulations &#8211; Revue des jeunes chercheurs en sciences sociales","author":"Lyonel Kaufmann","date":"15 mai 2013","format":false,"excerpt":"Benoit Lucien Vaillot, de\u00a0Sciences Po Lyon - Universit\u00e9 Lumi\u00e8re Lyon 2, nous offre un compte-rendu de l'ouvrage de\u00a0Philippe Delisle\u00a0Bande dessin\u00e9e franco-belge et imaginaire colonial. Des ann\u00e9es 1930 aux ann\u00e9es 1980. Depuis une quinzaine d\u2019ann\u00e9es, des historiens : Nicolas Bancel, Pascal Blanchard ou encore Sandrine Lemaire en t\u00eate, d\u00e9veloppent le concept\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5593,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2012\/07\/04\/histoire-serieuse-et-histoire-grand-public-la-concurrence-des-histoires-chronique-no-134\/","url_meta":{"origin":253,"position":3},"title":"Histoire \u00abs\u00e9rieuse\u00bb et histoire grand public : la concurrence des histoires ? &#124;\u00a0Chronique no 134","author":"Lyonel Kaufmann","date":"4 juillet 2012","format":false,"excerpt":"A intervalle r\u00e9gulier, l\u2019histoire universitaire renvoie aupr\u00e8s du grand public une image peu flatteuse d\u2019elle-m\u00eame. Dans son num\u00e9ro de mars 2012 et sur son site internet, l\u2019American Historical Association (AHA) d\u00e9battait du \u00abProfessionnal Boredom\u00bb\u00a0in History (L\u2019ennui professionnel en histoire) et son pr\u00e9sident William Cronon plaidait pour une \u00e9criture de l\u2019histoire\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4640,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2009\/04\/01\/cette-introduction-a-lhistoriographie-propose-aux\/","url_meta":{"origin":253,"position":4},"title":"Cette introduction \u00e0 l\u2019historiographie propose aux \u00e9tudiants de licence, de master et de concours l\u2019","author":"Lyonel Kaufmann","date":"1 avril 2009","format":"image","excerpt":"Cette introduction \u00e0 l\u2019historiographie propose aux \u00e9tudiants de licence, de master et de concours l\u2019essentiel de ce qu\u2019ils doivent savoir sur la discipline historique. L\u2019historiographie est con\u00e7ue comme l\u2019histoire de l\u2019histoire, et participe \u00e0 ce titre \u00e0 l\u2019histoire des sciences sociales.L\u2019ouvrage adopte une d\u00e9marche chronologique et th\u00e9matique. Il souligne les\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":15429,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2018\/12\/01\/unige-10-ans-apres-la-saveur-des-savoirs-de-jean-pierre-astolfi\/","url_meta":{"origin":253,"position":5},"title":"UNIGE : 10 ans apr\u00e8s \u00abLa saveur des savoirs\u00bb de Jean-Pierre Astolfi","author":"Lyonel Kaufmann","date":"1 d\u00e9cembre 2018","format":false,"excerpt":"Le 27 novembre 2018 dernier, \u00e0 l\u2019Universit\u00e9 de Gen\u00e8ve, l\u2019\u00c9quipe de didactique de l\u2019histoire et de la citoyennet\u00e9 consacrait sa journ\u00e9e d\u2019\u00e9tudes \u00e0 un bilan critique, 10 ans apr\u00e8s sa publication, de l\u2019ouvrage de Jean-Pierre Astolfi \u00abLa Saveur des savoirs\u00bb. Il s\u2019agissait, sous la forme d\u2019un bilan critique, d\u2019en d\u00e9gager\u2026","rel":"","context":"Dans &quot;Didactique&quot;","block_context":{"text":"Didactique","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/11\/lXVa4vZRYaUeRryH55X7g_thumb_430b.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/11\/lXVa4vZRYaUeRryH55X7g_thumb_430b.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/11\/lXVa4vZRYaUeRryH55X7g_thumb_430b.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/11\/lXVa4vZRYaUeRryH55X7g_thumb_430b.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/11\/lXVa4vZRYaUeRryH55X7g_thumb_430b.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=253"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/253\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/9896"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}