{"id":283,"date":"2008-02-08T02:17:29","date_gmt":"2008-02-08T01:17:29","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/2008\/02\/08\/links-for-2008-02-08\/"},"modified":"2008-02-08T02:17:29","modified_gmt":"2008-02-08T01:17:29","slug":"links-for-2008-02-08","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2008\/02\/08\/links-for-2008-02-08\/","title":{"rendered":"Sur le chemin de  l&#039;\u00e9cole 2.0 (liens)"},"content":{"rendered":"<ul class=\"delicious\">\n<li>\n<div class=\"delicious-link\"><a href=\"http:\/\/www.school2-0.org\/index.htm\">School 2.0 &#8211; Join the Conversation<\/a><\/div>\n<p>\t\tIl y avait le Web 2.0. Il y a maintenant aussi l&rsquo;Ecole 2.0. Site gouvernemental US.<\/p>\n<div class=\"delicious-tags\">(tags: <a href=\"http:\/\/del.icio.us\/histoirehep\/Histoire\">Histoire<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/P\u00e9dagogie\">P\u00e9dagogie<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/Ecole2.0\">Ecole2.0<\/a>)<\/div>\n<\/li>\n<li>\n<div class=\"delicious-link\"><a href=\"http:\/\/www.internetactu.net\/2008\/01\/29\/sur-le-chemin-de-lecole-20\/\">InternetActu.net \u00bb Sur le chemin de l\u2019\u00e9cole 2.0<\/a><\/div>\n<p>\t\tArticle de synth\u00e8se sur l&rsquo;\u00e9cole 2.0 en \u00e9cho au web 2.0. A replacer dans le d\u00e9bat sur la place des technologies \u00e0 l&rsquo;\u00e9cole.<\/p>\n<div class=\"delicious-tags\">(tags: <a href=\"http:\/\/del.icio.us\/histoirehep\/Histoire\">Histoire<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/P\u00e9dagogie\">P\u00e9dagogie<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/Ecole2.0\">Ecole2.0<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/School2.0\">School2.0<\/a>)<\/div>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>School 2.0 &#8211; Join the Conversation Il y avait le Web 2.0. Il y a maintenant aussi l&rsquo;Ecole 2.0. Site gouvernemental US. (tags: Histoire P\u00e9dagogie Ecole2.0) InternetActu.net \u00bb Sur le chemin de l\u2019\u00e9cole 2.0 Article de synth\u00e8se sur l&rsquo;\u00e9cole 2.0 en \u00e9cho au web 2.0. A replacer dans le d\u00e9bat sur la place des technologies [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[18],"tags":[],"class_list":{"0":"post-283","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-annuaire-de-sites","8":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?fit=658%2C184&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-4z","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":434,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2008\/10\/13\/links-for-2008-10-13\/","url_meta":{"origin":283,"position":0},"title":"Th\u00e9ories \u00e9conomiques, Kondratieff et le Web 2.0","author":"Lyonel Kaufmann","date":"13 octobre 2008","format":false,"excerpt":"probl\u00e8mes \u00e9conomiques : th\u00e9ories \u00e9conomiques : macro\u00e9conomie - La Documentation fran\u00e7aise Tour d'horizon des diff\u00e9rentes th\u00e9ories macro\u00e9conomiques dont notamment les diff\u00e9rentes th\u00e9ories sur les crises \u00e9conomiques (cycles, Keynes, Marx, n\u00e9o-classique, Ecole de la r\u00e9gulation). (tags: Histoire CriseEconomique Th\u00e9oriesEconomiques Macro\u00e9conomie) Les cycles Kondratieff\u00a0: une philosophie critique Comme \u00e0 chaque crise les\u2026","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1731,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2009\/12\/27\/histoire-2-0-weekly-7\/","url_meta":{"origin":283,"position":1},"title":"Histoire 2.0 (weekly)","author":"Lyonel Kaufmann","date":"27 d\u00e9cembre 2009","format":false,"excerpt":"Le Web plus efficace que la classe?En cette fin d'ann\u00e9e, toute une s\u00e9rie d'informations r\u00e9colt\u00e9es et publi\u00e9es sur la to\u00eele met en perspective les utilisations des technologies dans l'enseignement et invite \u00e0 la r\u00e9flexion relativement \u00e0 leur utilisation dans l'enseignement de l'histoire. Petit tour d'horizon en quatre tableaux.Tags: histoire, web,\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1425,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2009\/07\/19\/histoire-2-0-weekly-3\/","url_meta":{"origin":283,"position":2},"title":"Histoire 2.0 (weekly)","author":"Lyonel Kaufmann","date":"19 juillet 2009","format":false,"excerpt":"Page d'accueil de la Biblioth\u00e8que num\u00e9rique mondialeTags: biblioth\u00e8que, Unesco, culture, livre, histoire, web 2.0., ressource, site, internetPosted from Diigo. The rest of Histoire 2.0 group favorite links are here.","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3139,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/08\/26\/en-ludovia-pascal-et-virginie-portrait-minute\/","url_meta":{"origin":283,"position":3},"title":"En Ludovia : Pascal et Virginie (portrait minute)","author":"Lyonel Kaufmann","date":"26 ao\u00fbt 2010","format":false,"excerpt":"Ludovia est aussi le lieu des rencontres et \u00e9changes informels et l'occasion pour moi de r\u00e9aliser un portrait minute de Pascal et Virginie. Pascal et Virginie sont des formateurs tice. Ils interviennent \u00e0 l'\u00e9cole primaire dans le cadre du projet num\u00e9rique destin\u00e9 aux \u00e9coles rurales. Ils y accompagnent les enseignants\u2026","rel":"","context":"Dans &quot;Ludovia&quot;","block_context":{"text":"Ludovia","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/ludovia-2010\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2893,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/06\/20\/revue-de-presse-histoire-2-0-06202010\/","url_meta":{"origin":283,"position":4},"title":"Revue de presse &#8211; Histoire 2.0 06\/20\/2010","author":"Lyonel Kaufmann","date":"20 juin 2010","format":false,"excerpt":"Charles de Gaulle - Paroles publiques Le site des archives audiovisuelles des discours de Charles de Gaulle. Une production de l'INA et de la fondation Charles de Gaulle. On repassera donc pour un regard distanc\u00e9 relativement au g\u00e9n\u00e9ral de Gaulle\u2026 Reste les documents Tags: RevuePresse, liens, histoire, 39-45, France, CharlesDeGaulle,\u2026","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1696,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2009\/12\/16\/les-clionautes-victimes-colaterales-de-la-reforme-des-lycees\/","url_meta":{"origin":283,"position":5},"title":"Les Clionautes victimes collat\u00e9rales de la r\u00e9forme des lyc\u00e9es?","author":"Lyonel Kaufmann","date":"16 d\u00e9cembre 2009","format":false,"excerpt":"Le d\u00e9bat pour savoir quelle position l'association devait prendre sur la r\u00e9forme du lyc\u00e9e de Luc Chatel a fait exploser l'association des Clionautes regroupant des professeurs d'histoire-g\u00e9o. Las des conflits de personne et d\u00e9\u00e7us par le conservatisme p\u00e9dagogique de certains membres, la pr\u00e9sidente, Caroline Jouneau-Sion, et une partie du bureau\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=283"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/283\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/9896"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}