{"id":2990,"date":"2010-07-24T06:47:49","date_gmt":"2010-07-24T05:47:49","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/07\/24\/revue-de-presse-du-july-24th\/"},"modified":"2010-07-24T06:47:49","modified_gmt":"2010-07-24T05:47:49","slug":"revue-de-presse-du-july-24th","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/07\/24\/revue-de-presse-du-july-24th\/","title":{"rendered":"Revue de presse du July 24th"},"content":{"rendered":"<table class=\"lifestream\">\n<tbody>\n<tr class=\"lifestream_feedid_2 lifestream_feed_delicious\">\n<td class=\"lifestream_icon\"><a href=\"http:\/\/www.rue89.com\/2010\/07\/19\/peut-on-danser-devant-auschwitz-une-video-fait-polemique-159174\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/plugins\/lifestream\/extensions\/delicious\/icon.png\" alt=\"delicious (feed #2)\" \/><\/a><\/td>\n<td class=\"lifestream_text\">\n<div class=\"lifestream_label\">A partag\u00e9 <a href=\"http:\/\/www.rue89.com\/2010\/07\/19\/peut-on-danser-devant-auschwitz-une-video-fait-polemique-159174\">Peut-on danser \u00e0 Auschwitz ? Une vid\u00e9o fait pol\u00e9mique | Rue89<\/a>.<\/div>\n<blockquote class=\"lifestream_blogpost\"><p>L&rsquo;artiste australienne Jane Korman a visit\u00e9 les camps de la mort en compagnie de son p\u00e8re de 89 ans, Adolek Kohn, survivant&#8230;<\/p><\/blockquote>\n<\/td>\n<\/tr>\n<tr class=\"lifestream_feedid_2 lifestream_feed_delicious\">\n<td class=\"lifestream_icon\"><a href=\"http:\/\/europe14-18.eu\/preview_site\/fr\/pages\/projet.htm\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/plugins\/lifestream\/extensions\/delicious\/icon.png\" alt=\"delicious (feed #2)\" \/><\/a><\/td>\n<td class=\"lifestream_text\">\n<div class=\"lifestream_label\">A partag\u00e9 <a href=\"http:\/\/europe14-18.eu\/preview_site\/fr\/pages\/projet.htm\">[from grandeguerre] Europe 14-18. Regards crois\u00e9s sur la Premi\u00e8re Guerre mondiale<\/a>.<\/div>\n<blockquote class=\"lifestream_blogpost\"><p>Pourquoi et comment aborder la question de la 1\u00e8re guerre mondiale dans l\u2019enseignement secondaire des pays europ\u00e9ens ? Se&#8230;<\/p><\/blockquote>\n<\/td>\n<\/tr>\n<tr class=\"lifestream_feedid_2 lifestream_feed_delicious\">\n<td class=\"lifestream_icon\"><a href=\"http:\/\/culturevisuelle.org\/icones\/968\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/plugins\/lifestream\/extensions\/delicious\/icon.png\" alt=\"delicious (feed #2)\" \/><\/a><\/td>\n<td class=\"lifestream_text\">\n<div class=\"lifestream_label\">A partag\u00e9 <a href=\"http:\/\/culturevisuelle.org\/icones\/968\">Cinehistory par Vanessa Schwartz | R\u00e9my Besson<\/a>.<\/div>\n<blockquote class=\"lifestream_blogpost\"><p>Dans cet article qui porte sur les rapport entre Cin\u00e9ma et Histoire, Vanessa R. Schwartz, pose la question de l\u2019influence &#8230;<\/p><\/blockquote>\n<\/td>\n<\/tr>\n<tr class=\"lifestream_feedid_2 lifestream_feed_delicious\">\n<td class=\"lifestream_icon\"><a href=\"http:\/\/culturevisuelle.org\/cinemadoc\/2010\/07\/22\/cinehistory-schwartz\/\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/plugins\/lifestream\/extensions\/delicious\/icon.png\" alt=\"delicious (feed #2)\" \/><\/a><\/td>\n<td class=\"lifestream_text\">\n<div class=\"lifestream_label\">A partag\u00e9 <a href=\"http:\/\/culturevisuelle.org\/cinemadoc\/2010\/07\/22\/cinehistory-schwartz\/\">Cinehistory \u2013 Schwartz | Cin\u00e9madoc<\/a>.<\/div>\n<blockquote class=\"lifestream_blogpost\"><p>Dans cet article qui porte sur les rapport entre Cin\u00e9ma et Histoire, Vanessa R. Schwartz, pose la question de l\u2019influence &#8230;<\/p><\/blockquote>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>A partag\u00e9 Peut-on danser \u00e0 Auschwitz ? Une vid\u00e9o fait pol\u00e9mique | Rue89. L&rsquo;artiste australienne Jane Korman a visit\u00e9 les camps de la mort en compagnie de son p\u00e8re de 89 ans, Adolek Kohn, survivant&#8230; A partag\u00e9 [from grandeguerre] Europe 14-18. Regards crois\u00e9s sur la Premi\u00e8re Guerre mondiale. Pourquoi et comment aborder la question de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8365,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11],"tags":[],"class_list":{"0":"post-2990","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nouvelles-de-lhistoire","8":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2014\/09\/icon111.png?resize=600%2C400&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2014\/09\/icon111.png?resize=600%2C600&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2014\/09\/icon111.png?fit=%2C&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-Me","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":6714,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2013\/01\/20\/le-travail-a-la-chaine-a-cent-ans-lusine-nouvelle\/","url_meta":{"origin":2990,"position":0},"title":"Le travail \u00e0 la cha\u00eene a cent ans &#124;\u00a0L&#039;usine nouvelle","author":"Lyonel Kaufmann","date":"20 janvier 2013","format":false,"excerpt":"Il y a cent ans tout juste, une nouvelle m\u00e9thode de production faisait son apparition dans l'usine de Ford de Highland Park, \u00e0 Detroit. Ce syst\u00e8me est d\u00e9riv\u00e9 du d\u00e9pe\u00e7age des animaux dans les abattoirs de Chicago. Henry Ford a fait appel \u00e0 l'ing\u00e9nieur Frederic Taylor, l'inventeur de l'organisation scientifique\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":17241,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2020\/03\/30\/histoirecafe-episode-2-mes-quatre-defis-dun-enseignement-a-distance\/","url_meta":{"origin":2990,"position":1},"title":"HistoireCaf\u00e9 : Mes quatre d\u00e9fis d\u2019un enseignement \u00e0 distance","author":"Lyonel Kaufmann","date":"30 mars 2020","format":false,"excerpt":"HistoireCaf\u00e9 est un podcast destin\u00e9 \u00e0 l'enseignement de l'histoire \u00e0 l'\u00e8re num\u00e9rique. \u00a0Pourquoi caf\u00e9 ? Parce que j'aime le caf\u00e9.\u00a0Ce deuxi\u00e8me \u00e9pisode est consacr\u00e9 \u00e0 quatre d\u00e9fis que j'ai relev\u00e9s pour passer \u00e0 un enseignement enti\u00e8rement \u00e0 distance.\u00a0 Apr\u00e8s deux semaines du basculement de nos enseignements enti\u00e8rement \u00e0 distance, un\u2026","rel":"","context":"Dans &quot;Enseignement \u00e0 distance&quot;","block_context":{"text":"Enseignement \u00e0 distance","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/enseignement-a-distance\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/03\/israel-palacio-Y20JJ_ddy9M-unsplash-2-e1678963780934.jpg?fit=720%2C480&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/03\/israel-palacio-Y20JJ_ddy9M-unsplash-2-e1678963780934.jpg?fit=720%2C480&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/03\/israel-palacio-Y20JJ_ddy9M-unsplash-2-e1678963780934.jpg?fit=720%2C480&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/03\/israel-palacio-Y20JJ_ddy9M-unsplash-2-e1678963780934.jpg?fit=720%2C480&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":10569,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2015\/10\/24\/quand-le-byod-et-la-classe-inversee-renforcent-les-inegalites-scolaires\/","url_meta":{"origin":2990,"position":2},"title":"Quand le BYOD et la classe invers\u00e9e renforcent les in\u00e9galit\u00e9s scolaires","author":"Lyonel Kaufmann","date":"24 octobre 2015","format":false,"excerpt":"Dans un article intitul\u00e9\u00a0Homework is a Social Justice Issue - Hybrid Pedagogy, Kris Shaffer revient sur la question des devoirs \u00e0 domicile \u00e0 l\u2019\u00e8re du BYOD (Bring Your Own Device) et de la classe invers\u00e9e et sur la question de l\u2019\u00e9galit\u00e9 des chances (justice sociale) \u00e0 l\u2019\u00e9cole. Il en arrive\u2026","rel":"","context":"Dans &quot;Didactique&quot;","block_context":{"text":"Didactique","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/10\/homework.jpg?fit=598%2C398&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/10\/homework.jpg?fit=598%2C398&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/10\/homework.jpg?fit=598%2C398&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":12329,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/11\/16\/dhitler-a-trump-larrivee-et-la-gestion-du-pouvoir\/","url_meta":{"origin":2990,"position":3},"title":"D&rsquo;Hitler \u00e0 Trump : l&rsquo;arriv\u00e9e et la gestion du pouvoir","author":"Lyonel Kaufmann","date":"16 novembre 2016","format":false,"excerpt":"Dans son \u00e9dition du 15 novembre 2016, le journal qu\u00e9b\u00e9cois La Presse se faisait l'\u00e9cho de la confusion qui semblait r\u00e9gner dans l'\u00e9quipe de transition de Donald Trump (Confusion dans l'\u00e9quipe de transition de Donald Trump | Catherine TRIOMPHE, Ivan COURONNE | \u00c9tats-Unis)\u00a0: Donald Trump luttait mercredi pour dissiper l'impression\u2026","rel":"","context":"Dans &quot;Opinions&amp;R\u00e9flexions&quot;","block_context":{"text":"Opinions&amp;R\u00e9flexions","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/opinionsreflexions\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/11\/trump-hitler.jpg?fit=880%2C580&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/11\/trump-hitler.jpg?fit=880%2C580&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/11\/trump-hitler.jpg?fit=880%2C580&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/11\/trump-hitler.jpg?fit=880%2C580&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":12724,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2017\/01\/25\/cours-a-distance-inspires-des-jeux-video-le-devoir\/","url_meta":{"origin":2990,"position":4},"title":"Cours \u00e0 distance inspir\u00e9s des jeux vid\u00e9o | Le Devoir","author":"Lyonel Kaufmann","date":"25 janvier 2017","format":false,"excerpt":"Le journal Le Devoir pr\u00e9sente les d\u00e9marches suivies par l'Universit\u00e9 de Laval dans le domaine des cours \u00e0 distance et plus particuli\u00e8rement leur \u00e9volution vers un univers s'inspirant des jeux vid\u00e9os. L'Universit\u00e9 de Laval a d\u00e9but\u00e9 par des cours \u00e0 distance via la poste. Elle a donc une longue pratique\u2026","rel":"","context":"Dans &quot;Humanit\u00e9s Digitales&quot;","block_context":{"text":"Humanit\u00e9s Digitales","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/humanites-digitales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/01\/Image-25.01.17-13-24.jpeg?fit=1200%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/01\/Image-25.01.17-13-24.jpeg?fit=1200%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/01\/Image-25.01.17-13-24.jpeg?fit=1200%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/01\/Image-25.01.17-13-24.jpeg?fit=1200%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/01\/Image-25.01.17-13-24.jpeg?fit=1200%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":923,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2009\/02\/06\/le-fantome-darthur-bloch-na-pas-fini-de-hanter-les-payernois\/","url_meta":{"origin":2990,"position":5},"title":"Le fant\u00f4me d\u2019Arthur Bloch n\u2019a pas fini de hanter les Payernois","author":"Lyonel Kaufmann","date":"6 f\u00e9vrier 2009","format":false,"excerpt":"\u200bAujourd\u2019hui, la Rue-\u00e0-Thomas a effac\u00e9 toute trace de sa sordide histoire. En 1942, \u00e0 la place du...","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/2990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=2990"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/2990\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/8365"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=2990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=2990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=2990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}