{"id":317,"date":"2008-04-15T02:30:29","date_gmt":"2008-04-15T01:30:29","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/2008\/04\/15\/links-for-2008-04-15\/"},"modified":"2008-04-15T02:30:29","modified_gmt":"2008-04-15T01:30:29","slug":"links-for-2008-04-15","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2008\/04\/15\/links-for-2008-04-15\/","title":{"rendered":"R\u00e8glement pour les fileuses log\u00e9es (Document)"},"content":{"rendered":"<ul class=\"delicious\">\n<li>\n<div class=\"delicious-link\"><a href=\"http:\/\/alainhubler.wordpress.com\/2008\/04\/14\/reglement-pour-les-fileuses-logees\/\">R\u00e8glement pour les fileuses log\u00e9es<\/a><\/div>\n<p>Le r\u00e8glement reproduit par Alain Hubler est celui des filatures H. Bertrand de Saint-Jean-du-Gard dans le Gard en France. Il a \u00e9t\u00e9 en vigueur entre 1918 et 1921.<\/p>\n<div class=\"delicious-tags\">(tags: <a href=\"http:\/\/del.icio.us\/histoirehep\/Histoire\">Histoire<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/R\u00e9volutionIndustrielle\">R\u00e9volutionIndustrielle<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/ConditionsTravail\">ConditionsTravail<\/a> <a href=\"http:\/\/del.icio.us\/histoirehep\/Sources&amp;Documents\">Sources&amp;Documents<\/a>)<\/div>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e8glement pour les fileuses log\u00e9es Le r\u00e8glement reproduit par Alain Hubler est celui des filatures H. Bertrand de Saint-Jean-du-Gard dans le Gard en France. Il a \u00e9t\u00e9 en vigueur entre 1918 et 1921. (tags: Histoire R\u00e9volutionIndustrielle ConditionsTravail Sources&amp;Documents)<\/p>\n","protected":false},"author":1,"featured_media":9896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[18],"tags":[],"class_list":{"0":"post-317","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-annuaire-de-sites","8":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?fit=658%2C184&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-57","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":6788,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2013\/02\/10\/le-traite-de-paris-de-1763-est-le-document-le-plus-important-de-notre-histoire-le-devoir\/","url_meta":{"origin":317,"position":0},"title":"Le trait\u00e9 de Paris de 1763 est le document le plus important de notre histoire &#124; Le Devoir","author":"Lyonel Kaufmann","date":"10 f\u00e9vrier 2013","format":false,"excerpt":"Apr\u00e8s les comm\u00e9morations canadiennes du 200e anniversaire de la Guerre de 1812, c'est au tour du trait\u00e9 de Paris de 1763 d'entrer dans la danse. La bataille des plaines d\u2019Abraham de 1759.\u00a0Photo : Approvisionnements et Services Canada. La bataille des plaines d\u2019Abraham du 13 septembre 1759 est devenue un des\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/image.jpg?fit=915%2C590&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/image.jpg?fit=915%2C590&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/image.jpg?fit=915%2C590&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/image.jpg?fit=915%2C590&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":81,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2006\/05\/02\/m078-planification-annuelle-2-mai-2006\/","url_meta":{"origin":317,"position":1},"title":"M078 &#8211; Planification annuelle (2 mai 2006)","author":"Lyonel Kaufmann","date":"2 mai 2006","format":false,"excerpt":"\u2605.\u00a0\u00a0\u00a0 Planification annuelle de 5e \u00e0 9e ann\u00e9e Objectifs : \u27a2\u00a0\u00a0\u00a0 identifier les sujets possibles \/ incontournables d'un degr\u00e9 ou d'un cycle \u27a2\u00a0\u00a0\u00a0 combien de temps consacrer aux diff\u00e9rents th\u00e8mes sujets \u27a2\u00a0\u00a0\u00a0 comment les articuler avec les plans d'\u00e9tudes et les comp\u00e9tences \u00e0 d\u00e9velopper c\/o les \u00e9l\u00e8ves \u27a2\u00a0\u00a0\u00a0 comment les\u2026","rel":"","context":"Dans &quot;Cours et s\u00e9minaires&quot;","block_context":{"text":"Cours et s\u00e9minaires","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/cours-et-seminaires\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":7085,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2013\/05\/23\/revue-de-presse-open-access-quelques-ressources-pour-entrer-dans-le-debat\/","url_meta":{"origin":317,"position":2},"title":"Revue de presse : Open Access &#8211; quelques ressources pour entrer dans le d\u00e9bat","author":"Lyonel Kaufmann","date":"23 mai 2013","format":false,"excerpt":"Pour un s\u00e9minaire doctoral en histoire, il a \u00e9t\u00e9 demand\u00e9 \u00e0 F. Heimburger de r\u00e9unir quelques ressources concernant l'Open Access - pour permettre \u00e0 ceux qui ne connaissent rien au d\u00e9bat de s'initier et pour servir de point de d\u00e9part pour une discussion sur les enjeux. Plut\u00f4t que de garder\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":12213,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/10\/24\/suisse-atelier-decriture-wikipedia-lhistoire-des-chemins-de-fer-wikionrails\/","url_meta":{"origin":317,"position":3},"title":"Suisse : Atelier d\u2019\u00e9criture Wikip\u00e9dia \u00ab L\u2019histoire des chemins de fer #Wikionrails","author":"Lyonel Kaufmann","date":"24 octobre 2016","format":false,"excerpt":"Samedi dernier 22 octobre, j'ai particip\u00e9 \u00e0 Berne \u00e0 l'atelier d'\u00e9criture Wikipedia, organis\u00e9 par les Documents Diplomatiques suisses (DDS, http:\/\/dodis.ch) aux Archives f\u00e9d\u00e9rales sur \u00ab L\u2019histoire des chemins de fer \u00bb. Dans ce premier article, je m'attacherai \u00e0 faire un bref compte rendu de cet atelier. Dans un prochain article,\u2026","rel":"","context":"Dans &quot;Histoire active&quot;","block_context":{"text":"Histoire active","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-active\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/10\/Image-24.10.16-00-01.jpeg?fit=1200%2C836&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/10\/Image-24.10.16-00-01.jpeg?fit=1200%2C836&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/10\/Image-24.10.16-00-01.jpeg?fit=1200%2C836&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/10\/Image-24.10.16-00-01.jpeg?fit=1200%2C836&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/10\/Image-24.10.16-00-01.jpeg?fit=1200%2C836&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":17231,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2020\/03\/27\/les-enseignants-peuvent-ils-faire-cours-sur-discord-pendant-le-confinement-liberation\/","url_meta":{"origin":317,"position":4},"title":"Les enseignants peuvent-ils faire cours sur Discord pendant le confinement\u00a0? &#8211; Lib\u00e9ration","author":"Lyonel Kaufmann","date":"27 mars 2020","format":false,"excerpt":"Ce logiciel am\u00e9ricain appr\u00e9ci\u00e9 des joueurs de jeux vid\u00e9o a \u00e9t\u00e9 utilis\u00e9 par de nombreux professeurs apr\u00e8s la fermeture des \u00e9tablissements. Sa conformit\u00e9 au RGPD fait d\u00e9bat.\u00a0Les CheckNews de Lib\u00e9ration font le point de la situation. \u00ab\u00a0 Qu\u2019en est-il\u00a0? Tout d\u2019abord, Discord explique recueillir automatiquement un certain nombre de donn\u00e9es\u2026","rel":"","context":"Dans &quot;Enseignement \u00e0 distance&quot;","block_context":{"text":"Enseignement \u00e0 distance","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/enseignement-a-distance\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/03\/allie-smith-newgpclgEZI-unsplash-e1678963810603.jpg?fit=720%2C480&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/03\/allie-smith-newgpclgEZI-unsplash-e1678963810603.jpg?fit=720%2C480&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/03\/allie-smith-newgpclgEZI-unsplash-e1678963810603.jpg?fit=720%2C480&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/03\/allie-smith-newgpclgEZI-unsplash-e1678963810603.jpg?fit=720%2C480&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2866,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/06\/02\/revue-de-presse-du-2-june-2010\/","url_meta":{"origin":317,"position":5},"title":"Revue de presse du 2 juin 2010","author":"Lyonel Kaufmann","date":"2 juin 2010","format":false,"excerpt":"Revue de presse hebdomadaire de mes lectures trouv\u00e9es sur la to\u00eele, comment\u00e9es et conserv\u00e9es sur Delicious. Shared Katyn : Entre histoire et m\u00e9moire. \u00abLe sang de la for\u00eat de Katy\u0144 r\u00e9clame une vengeance impitoyable, sans merci. Nous ne pouvons pas oublier, jamais, la mort terrible de nos fr\u00e8res, pouss\u00e9s dans\u2026","rel":"","context":"Dans &quot;sur le web&quot;","block_context":{"text":"sur le web","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/sur-le-web\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=317"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/317\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/9896"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}