{"id":3240,"date":"2010-09-29T12:41:27","date_gmt":"2010-09-29T11:41:27","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/?p=3240"},"modified":"2010-09-29T12:41:27","modified_gmt":"2010-09-29T11:41:27","slug":"rwanda-de-la-guerre-au-genocide","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/09\/29\/rwanda-de-la-guerre-au-genocide\/","title":{"rendered":"Rwanda : de la guerre au g\u00e9nocide"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"http:\/\/www.laviedesidees.fr\/Rwanda-la-marche-au-genocide.html\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/\/2010\/09\/arton1170-1362a.jpg\" alt=\"\" \/><\/a><\/p>\n<div style=\"font-family: Georgia, 'Bitstream Charter', serif; color: #444444; line-height: 18px; background-image: initial; background-attachment: initial; background-origin: initial; background-clip: initial; background-color: #ffffff; font-size: 12px; font: normal normal normal 13px\/19px Georgia, 'Times New Roman', 'Bitstream Charter', Times, serif; max-width: 640px; padding: 0.6em; margin: 0px;\">\n<p style=\"font-family: Georgia, 'Bitstream Charter', serif; color: #444444; line-height: 1.5; font-size: 16px; margin-bottom: 24px;\"><strong>Comment, le 7 avril 1994, une faction a-t-elle d\u00e9cid\u00e9 et engag\u00e9 le g\u00e9nocide tutsi\u00a0? Le livre d\u2019Andr\u00e9 Guichaoua enqu\u00eate sur les strat\u00e9gies \u00e9tatiques g\u00e9nocidaires mises en \u0153uvre par un gouvernement extr\u00e9miste apr\u00e8s qu\u2019il eut \u00e9limin\u00e9 les autorit\u00e9s l\u00e9gitimes.<\/strong><\/p>\n<p style=\"font-family: Georgia, 'Bitstream Charter', serif; color: #444444; line-height: 1.5; font-size: 16px; margin-bottom: 24px;\">Andr\u00e9 Guichaoua,\u00a0<em>Rwanda, de la guerre au g\u00e9nocide. Les politiques criminelles au Rwanda (1990-1994)<\/em>, Paris, La D\u00e9couverte, 2010, 622 p., 29 \u20ac.<\/p>\n<p style=\"font-family: Georgia, 'Bitstream Charter', serif; color: #444444; line-height: 1.5; font-size: 16px; margin-bottom: 24px;\">L\u2019ouvrage qu\u2019Andr\u00e9 Guichaoua consacre au g\u00e9nocide tutsi, perp\u00e9tr\u00e9 en 1994, est l\u2019aboutissement de quinze ann\u00e9es d\u2019enqu\u00eates, men\u00e9es notamment au Rwanda dans le cadre du Tribunal p\u00e9nal international pour le Rwanda (TPIR). Le principal m\u00e9rite de cette somme est d\u2019avoir \u00e9tabli comment le g\u00e9nocide a \u00e9t\u00e9 d\u00e9cid\u00e9 et organis\u00e9, en quelques jours, par une faction d\u2019autorit\u00e9s politiques et militaires qui s\u2019\u00e9tait empar\u00e9e du pouvoir.<\/p>\n<p style=\"font-family: Georgia, 'Bitstream Charter', serif; color: #444444; line-height: 1.5; font-size: 16px; margin-bottom: 24px;\">Le compte-rendu :\u00a0<a style=\"font-family: Georgia, 'Bitstream Charter', serif; color: #0066cc; line-height: 1.5;\" href=\"http:\/\/www.laviedesidees.fr\/Rwanda-la-marche-au-genocide.html\">Rwanda : la marche au g\u00e9nocide &#8211; La vie des id\u00e9es<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Comment, le 7 avril 1994, une faction a-t-elle d\u00e9cid\u00e9 et engag\u00e9 le g\u00e9nocide tutsi\u00a0? Le livre d\u2019Andr\u00e9 Guichaoua enqu\u00eate sur les strat\u00e9gies \u00e9tatiques g\u00e9nocidaires mises en \u0153uvre par un gouvernement extr\u00e9miste apr\u00e8s qu\u2019il eut \u00e9limin\u00e9 les autorit\u00e9s l\u00e9gitimes. Andr\u00e9 Guichaoua,\u00a0Rwanda, de la guerre au g\u00e9nocide. Les politiques criminelles au Rwanda (1990-1994), Paris, La D\u00e9couverte, 2010, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,11],"tags":[292,649],"class_list":["post-3240","post","type-post","status-publish","format-standard","has-post-thumbnail","category-histoire-savante","category-nouvelles-de-lhistoire","tag-genocide","tag-rwanda","entry"],"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?fit=658%2C184&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-Qg","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":4632,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2009\/04\/09\/tv5-org-webtv-il-y-a-15-ans-le-genocide-au-rwanda\/","url_meta":{"origin":3240,"position":0},"title":"TV5 revient via ce reportage sur le g\u00e9nocide perp\u00e9tr\u00e9 il y a quinze ans au Rwanda. D\u00e9j\u00e0 quinze ans\u2026","author":"Lyonel Kaufmann","date":"9 avril 2009","format":"link","excerpt":"TV5.org- WebTV - Il y a 15 ans, le g\u00e9nocide au Rwanda","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4486,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/09\/29\/comment-le-7-avril-1994-une-faction-a-t-elle\/","url_meta":{"origin":3240,"position":1},"title":"Comment, le 7 avril 1994, une faction a-t-elle d\u00e9cid\u00e9 et engag\u00e9 le g\u00e9nocide tutsi&#160;? Le livre d\u2019","author":"Lyonel Kaufmann","date":"29 septembre 2010","format":"image","excerpt":"Comment, le 7 avril 1994, une faction a-t-elle d\u00e9cid\u00e9 et engag\u00e9 le g\u00e9nocide tutsi\u00a0? Le livre d\u2019Andr\u00e9 Guichaoua enqu\u00eate sur les strat\u00e9gies \u00e9tatiques g\u00e9nocidaires mises en \u0153uvre par un gouvernement extr\u00e9miste apr\u00e8s qu\u2019il eut \u00e9limin\u00e9 les autorit\u00e9s l\u00e9gitimes. Andr\u00e9 Guichaoua,\u00a0Rwanda, de la guerre au g\u00e9nocide. Les politiques criminelles au Rwanda\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":12936,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2017\/03\/18\/et-soudain-le-genocide-vous-apparait-bien-en-face\/","url_meta":{"origin":3240,"position":2},"title":"Et soudain, le g\u00e9nocide vous appara\u00eet bien en face","author":"Lyonel Kaufmann","date":"18 mars 2017","format":false,"excerpt":"Pourquoi, \u00e0 une \u00e9poque o\u00f9 l\u2019histoire de la violence et des g\u00e9nocides suscite le plus vif int\u00e9r\u00eat du public, celui du Rwanda int\u00e9resse si peu? Il y a un quart de si\u00e8cle, pr\u00e8s d\u2019un million de personnes ont \u00e9t\u00e9 assassin\u00e9es en l\u2019espace de cent jours. L\u2019Afrique est-elle vraiment trop \u00abloin\u00bb\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/03\/img_1847.jpg?fit=1200%2C433&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/03\/img_1847.jpg?fit=1200%2C433&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/03\/img_1847.jpg?fit=1200%2C433&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/03\/img_1847.jpg?fit=1200%2C433&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/03\/img_1847.jpg?fit=1200%2C433&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1114,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2009\/02\/26\/les-genocides-dans-lhistoire-complements-documentaires-par-peggy-pierrot-et-olivier-pironet-le-monde-diplomatique\/","url_meta":{"origin":3240,"position":3},"title":"Les g\u00e9nocides dans l\u2019histoire : compl\u00e9ments documentaires, par Peggy Pierrot et Olivier Pironet (Le Monde diplomatique)","author":"Lyonel Kaufmann","date":"26 f\u00e9vrier 2009","format":false,"excerpt":"Les g\u00e9nocides dans l\u2019histoire : compl\u00e9ments documentaires, par Peggy Pierrot et Olivier Pironet (Le Monde diplomatique) \u00ab\u00a0Les g\u00e9nocides dans l\u2019histoire \u00bb,\u00a0Mani\u00e8re de voir, num\u00e9ro\u00a076, ao\u00fbt-septembre\u00a02004. M\u00e9moire, n\u00e9gation et oubli\u00a0: de la Shoah au g\u00e9nocide arm\u00e9nien, du pass\u00e9 colonial \u00e0 la folie des Khmers rouges. Voir aussi, les articles traitant de\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2012\/08\/arton11342-6494d1.jpg?fit=200%2C287&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":15684,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2019\/01\/29\/vincent-duclert-la-recherche-permet-de-fermer-la-porte-au-negationnisme-en-revelant-lentreprise-de-dissimulation-du-genocide-liberation\/","url_meta":{"origin":3240,"position":4},"title":"Vincent Duclert \u00abLa\u00a0recherche\u00a0permet de fermer la\u00a0porte au\u00a0n\u00e9gationnisme en\u00a0r\u00e9v\u00e9lant l\u2019entreprise de\u00a0dissimulation du\u00a0g\u00e9nocide\u00bb &#8211; Lib\u00e9ration","author":"Lyonel Kaufmann","date":"29 janvier 2019","format":false,"excerpt":"Alors que les\u00a0\u00e9tudes sur la\u00a0Shoah se\u00a0renouvellent, le\u00a0g\u00e9nocide cambodgien\u00a0reste un\u00a0angle mort de la\u00a0recherche, et les\u00a0massacres du\u00a0Rwanda sont\u00a0peu\u00a0enseign\u00e9s dans les\u00a0\u00e9coles. Sous\u00a0la\u00a0direction de l\u2019historien Vincent\u00a0Duclert, 65\u00a0chercheurs\u00a0ont\u00a0fait le\u00a0bilan des\u00a0connaissances sur ces\u00a0tueries de masse et sur\u00a0la\u00a0motivation de leurs\u00a0auteurs, qui\u00a0s\u2019inspirent les\u00a0uns des\u00a0autres. \u2014 \u00c0 lire sur www.liberation.fr\/debats\/2019\/01\/27\/vincent-duclert-la-recherche-permet-de-fermer-la-porte-au-negationnisme-en-revelant-l-entreprise-de-_1705742","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":239,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2007\/09\/26\/penser-la-destruction-des-juifs-deurope-le-courrier-25092007\/","url_meta":{"origin":3240,"position":5},"title":"Penser la destruction des juifs d&#039;Europe (Le Courrier 25.09.2007)","author":"Lyonel Kaufmann","date":"26 septembre 2007","format":false,"excerpt":"DR | L'historien am\u00e9ricain Raul Hilberg Dans son \u00e9dition du mardi 25 septembre 2007, le journal Le Courrier revient sur la disparition r\u00e9cente de Raoul Hilberg (d\u00e9c\u00e9d\u00e9 le 4 ao\u00fbt 2007) et propose une page enti\u00e8re au travail r\u00e9alis\u00e9 par cet historien relativement \u00e0 son ouvrage majeur et capital sur\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/3240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=3240"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/3240\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/9896"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=3240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=3240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=3240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}