{"id":3256,"date":"2010-10-13T07:10:03","date_gmt":"2010-10-13T06:10:03","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/?p=3256"},"modified":"2010-10-13T07:10:03","modified_gmt":"2010-10-13T06:10:03","slug":"les-mecanismes-de-la-creativite-internetactu-net","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/10\/13\/les-mecanismes-de-la-creativite-internetactu-net\/","title":{"rendered":"Les m\u00e9canismes de la cr\u00e9ativit\u00e9 &#124;  InternetActu.net"},"content":{"rendered":"<p><b>Wired a r\u00e9cemment publi\u00e9 les extraits d\u2019une conversation entre deux des penseurs les plus radicaux de la technologie contemporaine, Kevin Kelly et Steven Berlin Johnson. InternetActu en rend compte. En voici un extrait int\u00e9ressant \u00e0 la fois dans une perspective historique et p\u00e9dagogique.<\/b><\/p>\n<blockquote><p>Bonne nouvelle, non seulement l\u2019innovation est collective, mais en plus elle ne serait pas motiv\u00e9e par l\u2019app\u00e2t du gain ou les pressions \u00e9conomiques. Du moins selon Johnson : \u201cJ\u2019ai essay\u00e9 d\u2019analyser le ph\u00e9nom\u00e8ne de mani\u00e8re syst\u00e9matique, explique-t-il. J\u2019ai pris environ 200 innovations cruciales apparues depuis Gutenberg, et j\u2019ai regard\u00e9 combien d\u2019entre elles provenaient d\u2019entrepreneurs individuels ou de compagnies priv\u00e9es, et combien de r\u00e9seaux collaboratifs fonctionnant hors du march\u00e9. Il s\u2019av\u00e8re que l\u2019entrepreneur g\u00e9nial et solitaire a toujours \u00e9t\u00e9 une raret\u00e9. Il existe bien plus d\u2019innovations provenant de r\u00e9seaux ouverts et non marchands que nous le soup\u00e7onnons.\u201d<\/p>\n<p>Une autre condition est indispensable \u00e0 la cr\u00e9ativit\u00e9 : le droit \u00e0 l\u2019erreur, et m\u00eame \u00e0 celui de faire n\u2019importe quoi. Cela suppose un environnement g\u00e9n\u00e9reux en ressources. Ce qui rejoint l\u2019une des marottes de Johnson, sa r\u00e9\u00e9valuation de la pop culture, et m\u00eame de la culture \u201ctrash\u201d. Un point de vue largement partag\u00e9 par Kelly : \u201cIl y a dix ans j\u2019ai affirm\u00e9 que le probl\u00e8me principal de la TV tenait au fait qu\u2019il n\u2019existait pas suffisamment de mauvaise TV. C\u2019\u00e9tait si cher de faire de la t\u00e9l\u00e9 que les financiers ne pouvaient permettre qu\u2019on r\u00e9alise des \u00e9missions vraiment nulles \u2013 ou vraiment g\u00e9niales. Donc tout \u00e9tait m\u00e9diocre. C\u2019\u00e9tait avant YouTube. Maintenant, il y a de la t\u00e9l\u00e9 vraiment g\u00e9niale. Pour cr\u00e9er quelque chose de grand, vous devez avoir les moyens de produire beaucoup de d\u00e9chets.\u201d<\/p>\n<\/blockquote>\n<p>via<a href='http:\/\/www.internetactu.net\/2010\/10\/13\/les-mecanismes-de-la-creativite\/?utm_source=feedburner&#038;utm_medium=feed&#038;utm_campaign=Feed%3A+internetactu%2FbcmJ+%28InternetActu.net%29'>Les m\u00e9canismes de la cr\u00e9ativit\u00e9 \u00ab  InternetActu.net<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wired a r\u00e9cemment publi\u00e9 les extraits d\u2019une conversation entre deux des penseurs les plus radicaux de la technologie contemporaine, Kevin Kelly et Steven Berlin Johnson. InternetActu en rend compte. En voici un extrait int\u00e9ressant \u00e0 la fois dans une perspective historique et p\u00e9dagogique. Bonne nouvelle, non seulement l\u2019innovation est collective, mais en plus elle ne [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11],"tags":[173],"class_list":{"0":"post-3256","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nouvelles-de-lhistoire","8":"tag-creativite-invention","9":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?fit=658%2C184&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-Qw","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":7740,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2014\/01\/03\/inoovation-pedagogie-et-numerique\/","url_meta":{"origin":3256,"position":0},"title":"Innovation, p\u00e9dagogie et num\u00e9rique","author":"Lyonel Kaufmann","date":"3 janvier 2014","format":false,"excerpt":"Quelques ressources issues de ma veille \u00e9ducative et technologique, histoire de lancer la nouvelle ann\u00e9e \u00e9ducative\u2026 Cela prolonge \u00e9galement l'infographie pr\u00e9c\u00e9dente consacr\u00e9e \u00e0 l'histoire des technologies scolaires (Infographie : Histoire des technologies scolaires) L'innovation p\u00e9dagogique en 10 points | Thot Cursus Depuis 2012, l'Open University britannique publie \u00e0 l'automne un\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/cycle-gartner.png?fit=400%2C231&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":14161,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2018\/05\/07\/linnovation-pour-un-retour-a-la-pedagogie\/","url_meta":{"origin":3256,"position":1},"title":"L&rsquo;innovation pour un retour \u00e0 la p\u00e9dagogie","author":"Lyonel Kaufmann","date":"7 mai 2018","format":false,"excerpt":"Qu'est ce que l'innovation p\u00e9dagogique et \u00e0 quoi sert-elle ? La question a re\u00e7u bien des d\u00e9finitions. Souvent , et particuli\u00e8rement pour l'Education nationale, elle est pr\u00e9sent\u00e9e sous l'angle des \"bonnes pratiques\" recens\u00e9es officiellement pour duplication et g\u00e9n\u00e9ralisation. Ce n'est pas le point de vue de l'OCDE qui publie un\u2026","rel":"","context":"Dans &quot;Didactique&quot;","block_context":{"text":"Didactique","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/05\/img_0914.jpg?fit=1200%2C910&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/05\/img_0914.jpg?fit=1200%2C910&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/05\/img_0914.jpg?fit=1200%2C910&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/05\/img_0914.jpg?fit=1200%2C910&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/05\/img_0914.jpg?fit=1200%2C910&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":8856,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2015\/02\/10\/ces-evolutions-majeures-qui-pourraient-faire-changer-le-monde-de-leducation-lopinion\/","url_meta":{"origin":3256,"position":2},"title":"Ces \u00e9volutions majeures qui pourraient faire changer le monde de l\u2019\u00e9ducation &#124; L&#039;Opinion","author":"Lyonel Kaufmann","date":"10 f\u00e9vrier 2015","format":false,"excerpt":"Les faits - Polytechnicien, biologiste, directeur de recherches \u00e0 l\u2019Inserm, Fran\u00e7ois Tadd\u00e9i est \u00e0 la t\u00eate du Centre de recherches inter-disciplinaires, h\u00e9berg\u00e9 \u00e0 l\u2019Universit\u00e9 Paris-Descartes. Membre du Haut conseil de l\u2019Education nationale, ses recherches portent notamment sur l\u2019innovation dans l\u2019\u00e9ducation. Bouillonnant, il ne travaille \u00ab\u202fqu\u2019avec des gens qui ont envie\u202f\u00bb\u2026","rel":"","context":"Dans &quot;Opinions&amp;R\u00e9flexions&quot;","block_context":{"text":"Opinions&amp;R\u00e9flexions","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/opinionsreflexions\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":7674,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2013\/11\/06\/reinventons-lecole-les-meilleures-conferences-ted\/","url_meta":{"origin":3256,"position":3},"title":"&quot;R\u00e9inventons l&#039;\u00e9cole&quot; : les meilleures conf\u00e9rences TED","author":"Lyonel Kaufmann","date":"6 novembre 2013","format":false,"excerpt":"Faire conna\u00eetre \"les id\u00e9es qui valent la peine d'\u00eatre diffus\u00e9es\" : telle est la devise des conf\u00e9rences TED (Technology, entertainment and design), lanc\u00e9es il y a pr\u00e8s de 30 ans par une association \u00e0 but non lucratif, la Sapling foundation. Parmi les th\u00e9matiques abord\u00e9es : l'\u00e9ducation, et plus particuli\u00e8rement l'innovation\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":20593,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2026\/03\/16\/ludoviach-ch-21-22-04-2026-deux-jours-pour-repenser-lapprentissage-a-lere-de-lia-et-de-linnovation\/","url_meta":{"origin":3256,"position":4},"title":"Ludovia#CH (21-22-04.2026) : deux jours pour repenser l\u2019apprentissage \u00e0 l\u2019\u00e8re de l\u2019IA et de l\u2019innovation","author":"Lyonel Kaufmann","date":"16 mars 2026","format":false,"excerpt":"Les 21et 22 avril 2026, la sixi\u00e8me \u00e9dition de LUDOVIA#CH revient \u00e0 Yverdon-les-Bains. Organis\u00e9 conjointement par la\u00a0Haute \u00e9cole p\u00e9dagogique du canton de Vaud\u00a0et de la\u00a0Haute \u00e9cole d\u2019ing\u00e9nierie et de gestion du canton de Vaud et le soutien du D\u00e9partement de l\u2019enseignement et de la formation professionnelle, l\u2019\u00e9v\u00e9nement proposera conf\u00e9rences, ateliers,\u2026","rel":"","context":"Dans &quot;EdNum&quot;","block_context":{"text":"EdNum","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/humanites-digitales\/ednum\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2026\/03\/HEP_Vaud_Affiches_A1_Ludovia_2026_06.03.2026_web.jpg?fit=847%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2026\/03\/HEP_Vaud_Affiches_A1_Ludovia_2026_06.03.2026_web.jpg?fit=847%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2026\/03\/HEP_Vaud_Affiches_A1_Ludovia_2026_06.03.2026_web.jpg?fit=847%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2026\/03\/HEP_Vaud_Affiches_A1_Ludovia_2026_06.03.2026_web.jpg?fit=847%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2871,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/06\/06\/lenseignant-un-chercheur-entre-conservatisme-et-futurisme\/","url_meta":{"origin":3256,"position":5},"title":"L&#039;enseignant, un chercheur entre conservatisme et futurisme","author":"Lyonel Kaufmann","date":"6 juin 2010","format":false,"excerpt":"Le point de d\u00e9part de Philippe Dumas A l\u2019un des extre\u0302mes, le conservatisme se fonde non seulement sur le refus d\u2019entrer dans le monde digital, mais encore plus sur la croyance que l\u2019apprentissage, vu qu\u2019il est sempiternellement a\u0300 l\u2019ordre du jour, obe\u0301it a\u0300 des lois immuables. En France, par exemple,\u2026","rel":"","context":"Dans &quot;Didactique&quot;","block_context":{"text":"Didactique","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/3256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=3256"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/3256\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/9896"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=3256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=3256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=3256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}