{"id":326,"date":"2008-06-06T10:25:21","date_gmt":"2008-06-06T09:25:21","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/?p=460"},"modified":"2008-06-06T10:25:21","modified_gmt":"2008-06-06T09:25:21","slug":"andre-zucca-la-couleur-revee","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2008\/06\/06\/andre-zucca-la-couleur-revee\/","title":{"rendered":"Andr\u00e9 Zucca, la couleur r\u00eav\u00e9e"},"content":{"rendered":"<ol class=\"posts\">\n<li class=\"post\">\n<h4 class=\"desc\"><a rel=\"nofollow\" href=\"http:\/\/www.arhv.lhivic.org\/index.php\/2008\/05\/18\/713-andre-zucca-la-couleur-revee\">Andr\u00e9 Zucca, la couleur r\u00eav\u00e9e<\/a>\u00a0<\/h4>\n<p class=\"notes\">L&rsquo;exposition \u00ab\u00a0Les\/des Parisiens sous l&rsquo;Occupation\u00a0\u00bbsuscite une importante pol\u00e9mique: pr\u00e9sente-t-elle une galerie d&rsquo;images de propagande ou la vision d&rsquo;un photographe ou un \u00e9tat historique de la capitale collaborationniste? Cet article fait le point.<\/p>\n<div class=\"meta\"><a class=\"tag\" href=\"http:\/\/del.icio.us\/histoirehep\/Histoire\">Histoire<\/a>\u00a0<a class=\"tag\" href=\"http:\/\/del.icio.us\/histoirehep\/39-45\">39-45<\/a>\u00a0<a class=\"tag\" href=\"http:\/\/del.icio.us\/histoirehep\/Propagande\">Propagande<\/a>\u00a0<a class=\"tag\" href=\"http:\/\/del.icio.us\/histoirehep\/Photographies\">Photographies<\/a>\u00a0&#8230; (19 mai 2008)<\/div>\n<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Andr\u00e9 Zucca, la couleur r\u00eav\u00e9e\u00a0 L&rsquo;exposition \u00ab\u00a0Les\/des Parisiens sous l&rsquo;Occupation\u00a0\u00bbsuscite une importante pol\u00e9mique: pr\u00e9sente-t-elle une galerie d&rsquo;images de propagande ou la vision d&rsquo;un photographe ou un \u00e9tat historique de la capitale collaborationniste? Cet article fait le point. Histoire\u00a039-45\u00a0Propagande\u00a0Photographies\u00a0&#8230; (19 mai 2008)<\/p>\n","protected":false},"author":1,"featured_media":9896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[18],"tags":[],"class_list":{"0":"post-326","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-annuaire-de-sites","8":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?fit=658%2C184&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-5g","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":322,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2008\/05\/07\/links-for-2008-05-07\/","url_meta":{"origin":326,"position":0},"title":"Les archives oubli\u00e9es de la Wehrmacht (Le Figaro)","author":"Lyonel Kaufmann","date":"7 mai 2008","format":false,"excerpt":"Les archives oubli\u00e9es de la Wehrmacht (Le Figaro) Environ 350000 clich\u00e9s de la propagande de l\u2019arm\u00e9e allemande sont conserv\u00e9s au fort d\u2019Ivry depuis 1947. Des images in\u00e9dites qui constituent une mine documentaire d\u2019une qualit\u00e9 exceptionnelle. (tags: 39-45 WWII photographies arm\u00e9e allemande occupation propagande histoire)","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":18749,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2022\/02\/26\/enquete-sur-une-photographie\/","url_meta":{"origin":326,"position":1},"title":"Enqu\u00eate sur une photographie","author":"Lyonel Kaufmann","date":"26 f\u00e9vrier 2022","format":false,"excerpt":"A l'\u00e9t\u00e9 2009 l'historienne am\u00e9ricaine Wendy Lower travaillait aux archives du mus\u00e9e-m\u00e9morial de l'Holocauste \u00e0 Washington DC (\u00c9tats-Unis) lorsqu'elle fit connaissance avec deux jeunes journalistes venus de Prague. Ils lui confi\u00e8rent une photographie du front de l'Est pour l'expertiser. Si la documentation photographique de la Shoah est particuli\u00e8rement importante, peu\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"holocaust memorial","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/02\/pexels-photo-220783-e1678961646932.jpeg?fit=720%2C480&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/02\/pexels-photo-220783-e1678961646932.jpeg?fit=720%2C480&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/02\/pexels-photo-220783-e1678961646932.jpeg?fit=720%2C480&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/02\/pexels-photo-220783-e1678961646932.jpeg?fit=720%2C480&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":24,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2005\/08\/09\/the-russian-photography-collection-1917-1945\/","url_meta":{"origin":326,"position":2},"title":"The Russian Photography Collection (1917-1945)","author":"Lyonel Kaufmann","date":"9 ao\u00fbt 2005","format":false,"excerpt":"The Russian Photography Collection (1917-1945) est compos\u00e9e d'approximativement 7.000 photographies prises par les principaux photographes et photojournalistes travaillant en Russie sovi\u00e9tique entre les deux guerres mondiales. Con\u00e7ue comme une histoire de la photographie du XXe si\u00e8cle en Union sovi\u00e9tique, la collection se concentre principalement sur les cat\u00e9gories: Constructivism\/Avant-Garde, propagande, photo\u2026","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":468,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2008\/11\/03\/links-for-2008-11-03\/","url_meta":{"origin":326,"position":3},"title":"Serge Bernstein revient sur la crise &#124; Obama et le r\u00eave am\u00e9ricain","author":"Lyonel Kaufmann","date":"3 novembre 2008","format":false,"excerpt":"Crise : attention \u00e0 la tentation de rechercher un \u00absauveur\u00bb Le c\u00e9l\u00e8bre historien Serge Berstein retrace pour Marianne2 les cons\u00e9quences de la crise de 29 dans l'Allemagne de l'entre-deux-guerres. Dans cette deuxi\u00e8me partie, il explique comment le peuple allemand sacrifia la d\u00e9mocratie en pensant sauver l'\u00e9conomie. (tags: Histoire Crise1929 CriseEconomique\u2026","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":17519,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2020\/06\/25\/au-bresil-la-redecouverte-des-grandes-figures-noires-qui-avaient-ete-blanchies\/","url_meta":{"origin":326,"position":4},"title":"Au Br\u00e9sil, la red\u00e9couverte des grandes figures noires qui avaient \u00e9t\u00e9 \u00ab blanchies \u00bb","author":"Lyonel Kaufmann","date":"25 juin 2020","format":false,"excerpt":"Le portrait volontairement \u00ab blanchi \u00bb de l'\u00e9crivain Joaquim Maria Machado de Assis, r\u00e9alis\u00e9 vers 1896. WIKIMEDIA COMMONS C'est \u00e0 l'\u00e9poque du baccalaur\u00e9at, vers 17-18 ans, qu'Andr\u00e9 Tadao Kameda a d\u00e9couvert que le plus grand \u00e9crivain de son pays \u00e9tait noir. \u00ab Jusque-l\u00e0 ce n'\u00e9tait pas tr\u00e8s clair, se souvient\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/06\/D5f-tldW0AIEy9N.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/06\/D5f-tldW0AIEy9N.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/06\/D5f-tldW0AIEy9N.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/06\/D5f-tldW0AIEy9N.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/06\/D5f-tldW0AIEy9N.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":3090,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/08\/06\/une-image-pour-la-guerre-latelier-des-icones\/","url_meta":{"origin":326,"position":5},"title":"Une image pour la guerre &#124; L&#039;Atelier des ic\u00f4nes","author":"Lyonel Kaufmann","date":"6 ao\u00fbt 2010","format":false,"excerpt":"Dans un court et brillant article, Andr\u00e9 Gunthert porte son regard et son analyse sur la derni\u00e8re couverture du Time. Le portrait d'une jeune afghane Aisha actuellement aux Etats-Unis pour une op\u00e9ration de reconstruction faciale. Andr\u00e9 Gunthert l'a met notamment en relation avec un autre portrait d'une Afghane d\u00e9sormais c\u00e9l\u00e8bre\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/timeaisha2-374x500.jpg?fit=374%2C500&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=326"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/326\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/9896"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}