{"id":3579,"date":"2011-02-24T00:54:42","date_gmt":"2011-02-23T23:54:42","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/?p=3579"},"modified":"2011-02-24T00:54:42","modified_gmt":"2011-02-23T23:54:42","slug":"200-pays-sur-200-ans-en-4-minutes","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/02\/24\/200-pays-sur-200-ans-en-4-minutes\/","title":{"rendered":"200 pays sur 200 ans en 4 minutes"},"content":{"rendered":"<p><object width=\"520\" height=\"340\"><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/jbkSRLYSojo?version=3\" \/><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowScriptAccess\" value=\"always\" \/><\/object><\/p>\n<p>Hans Rosling est l&rsquo;inventeur de l&rsquo;outil de visualisation\u00a0<a href=\"http:\/\/www.gapminder.org\/\">Gapminder<\/a>, qui autorise tous les croisements possibles et imaginables de donn\u00e9es publiques \u00e0 l&rsquo;\u00e9chelle mondiale, dans des graphiques dynamiques qui permettent de voir leur \u00e9volution dans le temps.<\/p>\n<p>Ici, il nous pr\u00e9sente l&rsquo;\u00e9volution de l&rsquo;esp\u00e9rance de vie et son \u00e9cart entre pays riches et pays pauvres sur 200 ans de 200 pays. Le tout en 4 minutes chrono.<\/p>\n<p>Bluffant\u2026<\/p>\n<p><a href=\"http:\/\/www.gapminder.org\/videos\/200-years-that-changed-the-world-bbc\/\">200 Countries, 200 Years, 4 Minutes &#8211; Gapminder.org<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hans Rosling est l&rsquo;inventeur de l&rsquo;outil de visualisation\u00a0Gapminder, qui autorise tous les croisements possibles et imaginables de donn\u00e9es publiques \u00e0 l&rsquo;\u00e9chelle mondiale, dans des graphiques dynamiques qui permettent de voir leur \u00e9volution dans le temps. Ici, il nous pr\u00e9sente l&rsquo;\u00e9volution de l&rsquo;esp\u00e9rance de vie et son \u00e9cart entre pays riches et pays pauvres sur 200 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10229,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8,11,17],"tags":[],"class_list":{"0":"post-3579","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-medias-et-technologies","8":"category-nouvelles-de-lhistoire","9":"category-sur-le-web","10":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/031.jpg?resize=480%2C360&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/031.jpg?resize=480%2C360&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/031.jpg?fit=480%2C360&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-VJ","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":4454,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/02\/24\/200-pays-sur-200-ans-et-en-4-minutes\/","url_meta":{"origin":3579,"position":0},"title":"200 pays sur 200 ans et en 4 minutes","author":"Lyonel Kaufmann","date":"24 f\u00e9vrier 2011","format":false,"excerpt":"[youtube http:\/\/www.youtube.com\/watch?v=jbkSRLYSojo&version=3] Hans Rosling est l\u2019inventeur de l\u2019outil de visualisation\u00a0Gapminder, qui autorise tous les croisements possibles et imaginables de donn\u00e9es publiques \u00e0 l\u2019\u00e9chelle mondiale, dans des graphiques dynamiques qui permettent de voir leur \u00e9volution dans le temps. Ici, il nous pr\u00e9sente l\u2019\u00e9volution de l\u2019esp\u00e9rance de vie et son \u00e9cart entre\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/032.jpg?fit=480%2C360&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3586,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/02\/26\/cafe-histoire-du-26-february-2011\/","url_meta":{"origin":3579,"position":1},"title":"Caf\u00e9 histoire du 26 February 2011","author":"Lyonel Kaufmann","date":"26 f\u00e9vrier 2011","format":false,"excerpt":"A publi\u00e9 Pourquoi parle-t-on de printemps des peuples arabes? | Slate. \u00abPrintemps \u00e9gyptien\u00bb, \u00abprintemps arabe\u00bb, \u00abprintemps des peuples arabes\u00bb\u2026 \u00e0 force d\u2019entendre ... A publi\u00e9 200 pays sur 200 ans et en 4 minutes. Hans Rosling est l\u2019inventeur de l\u2019outil de visualisation\u00a0Gapminder, qui autorise...","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":16577,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2019\/11\/04\/la-reine-marie-antoinette-nouvelle-icone-pop-le-monde\/","url_meta":{"origin":3579,"position":2},"title":"La reine Marie-Antoinette, nouvelle ic\u00f4ne pop | Le Monde","author":"Lyonel Kaufmann","date":"4 novembre 2019","format":false,"excerpt":"La souveraine guillotin\u00e9e conna\u00eet un regain de popularit\u00e9 aupr\u00e8s des artistes. Quelque 200 \u0153uvres que la reine a inspir\u00e9es sont expos\u00e9es jusqu\u2019en janvier 2020 \u00e0 Paris, \u00e0 la Conciergerie qui fut sa derni\u00e8re demeure. Il est peu de personnages historiques dont les l\u00e9gendes concurrentes, noire et dor\u00e9e, accusent un contraste\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/11\/ed768b8_OvHw6_u52FtH8lTNAhu9BX5y.5560f81072da4dd6abd794d02b31407c.jpg?fit=688%2C457&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/11\/ed768b8_OvHw6_u52FtH8lTNAhu9BX5y.5560f81072da4dd6abd794d02b31407c.jpg?fit=688%2C457&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/11\/ed768b8_OvHw6_u52FtH8lTNAhu9BX5y.5560f81072da4dd6abd794d02b31407c.jpg?fit=688%2C457&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":19473,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2023\/03\/07\/restitution-doeuvres-faut-il-vider-nos-musees-rts-ch\/","url_meta":{"origin":3579,"position":3},"title":"Restitution d&rsquo;oeuvres: faut-il vider nos mus\u00e9es? rts.ch","author":"Lyonel Kaufmann","date":"7 mars 2023","format":false,"excerpt":"A la suite des ind\u00e9pendances africaines dans les ann\u00e9es 1960, un mouvement en faveur du rapatriement des \u0153uvres du continent, conserv\u00e9es dans les mus\u00e9es europ\u00e9ens, a \u00e9t\u00e9 lanc\u00e9 par les \u00e9lites intellectuelles et politiques locales. Aujourd'hui, les demandes de rapatriement de biens ne faiblissent pas et opposent deux visions. L'invit\u00e9\/e\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"La Suisse a restitu\u00e9 \u00e0 l'ambassade du P\u00e9rou une sculpture de la culture Chav\u00edn, le 8 f\u00e9vrier 2023. [Keystone]","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2023\/03\/13828708.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2023\/03\/13828708.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2023\/03\/13828708.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2023\/03\/13828708.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2023\/03\/13828708.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":8888,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2015\/02\/20\/revue-de-presse-decouvrir-la-suisse-comme-un-touriste-du-xviiie-siecle\/","url_meta":{"origin":3579,"position":4},"title":"Revue de Presse : D\u00e9couvrir la Suisse comme un touriste du XVIIIe si\u00e8cle","author":"Lyonel Kaufmann","date":"20 f\u00e9vrier 2015","format":false,"excerpt":"Une collection de plus de 1000 oeuvres mises en ligne par la Biblioth\u00e8que nationale permet de se plonger dans les circuits du tourisme suisse des XVIIIe et XIXe si\u00e8cles. Je note: \u00abUne collection de plus de 1000 oeuvres mises en ligne par la Biblioth\u00e8que nationale permet de se plonger dans\u2026","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/6499521-image.jpeg.jpg?fit=880%2C495&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/6499521-image.jpeg.jpg?fit=880%2C495&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/6499521-image.jpeg.jpg?fit=880%2C495&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/6499521-image.jpeg.jpg?fit=880%2C495&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":9234,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2013\/02\/03\/la-bataille-de-stalingrad-en-infographie-ria-novosti-2\/","url_meta":{"origin":3579,"position":5},"title":"La Bataille de Stalingrad en infographie (Ria Novosti)","author":"Lyonel Kaufmann","date":"3 f\u00e9vrier 2013","format":false,"excerpt":"See on Scoop.it - histoire Description - commentaire: Une superbe infographie synth\u00e9tisant la bataille de Stalingrad (2 f\u00e9vrier 1943). Il y a donc 70 ans, le 2 f\u00e9vrier 1943, la bataille de Stalingrad prenait fin apr\u00e8s 200 jours de combats. Cette bataille est un tournant de la Deuxi\u00e8me guerre mondiale.\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/3579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=3579"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/3579\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/10229"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=3579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=3579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=3579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}