{"id":3592,"date":"2011-03-02T21:57:48","date_gmt":"2011-03-02T20:57:48","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/?p=3592"},"modified":"2011-03-02T21:57:48","modified_gmt":"2011-03-02T20:57:48","slug":"des-telephones-mobiles-a-lecole-enseignement-educa-ch","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/03\/02\/des-telephones-mobiles-a-lecole-enseignement-educa-ch\/","title":{"rendered":"Des t\u00e9l\u00e9phones mobiles \u00e0 l&#039;\u00e9cole ? &#124; educa.ch"},"content":{"rendered":"<figure id=\"attachment_3595\" aria-describedby=\"caption-attachment-3595\" style=\"width: 378px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2011\/03\/article_portable-iphone-illustre.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3595  \" title=\"article_portable-iphone-illustre\" src=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2011\/03\/article_portable-iphone-illustre.jpg?resize=378%2C250\" alt=\"\" width=\"378\" height=\"250\" \/><\/a><figcaption id=\"caption-attachment-3595\" class=\"wp-caption-text\">Illustration d&#39;un smartphone VALINCO \/ SIPA<\/figcaption><\/figure>\n<blockquote><p>Dans la plupart des \u00e9coles, l&rsquo;usage des mobiles et smartphones est interdit, car il perturbe la classe. Pourtant, aujourd&rsquo;hui, m\u00eame des membres sceptiques du corps enseignant ne sont plus contre le fait que les \u00e9l\u00e8ves cherchent rapidement une date historique dans Wikipedia, utilisent la calculatrice, traduisent des mots, consultent le dictionnaire ou fassent une dict\u00e9e au moyen de leur smartphone. On devra faire en sorte \u00e0 l&rsquo;avenir que les \u00e9l\u00e8ves puissent mettre \u00e0 profit en classe les m\u00e9dias dont ils disposent de toute fa\u00e7on.<\/p><\/blockquote>\n<p>Autrement dit, veut-on notamment interdire les calculatrices et les dictionnaires \u00e0 l&rsquo;\u00e9cole?\u00a0Une r\u00e9flexion introductive pleine de bon sens et un dossier \u00e0 lire pour les enseignant-e-s, n&rsquo;est-il pas?<\/p>\n<p>via\u00a0<a href=\"http:\/\/enseignement.educa.ch\/fr\/t\u00e9l\u00e9phones-mobiles-\u00e0-l\u00e9cole\">Des t\u00e9l\u00e9phones mobiles \u00e0 l&rsquo;\u00e9cole ? | enseignement.educa.ch<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans la plupart des \u00e9coles, l&rsquo;usage des mobiles et smartphones est interdit, car il perturbe la classe. Pourtant, aujourd&rsquo;hui, m\u00eame des membres sceptiques du corps enseignant ne sont plus contre le fait que les \u00e9l\u00e8ves cherchent rapidement une date historique dans Wikipedia, utilisent la calculatrice, traduisent des mots, consultent le dictionnaire ou fassent une dict\u00e9e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10228,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8,13,15,17],"tags":[],"class_list":{"0":"post-3592","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-medias-et-technologies","8":"category-opinionsreflexions","9":"category-outils-enseignement","10":"category-sur-le-web","11":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/article_portable-iphone-illustre.jpg?resize=590%2C390&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/article_portable-iphone-illustre.jpg?resize=590%2C390&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/article_portable-iphone-illustre.jpg?fit=590%2C390&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-VW","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":17221,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2020\/03\/26\/continuite-la-revanche-du-smartphone-cafe-pedagogique\/","url_meta":{"origin":3592,"position":0},"title":"Continuit\u00e9 : La revanche du smartphone | Caf\u00e9 p\u00e9dagogique","author":"Lyonel Kaufmann","date":"26 mars 2020","format":false,"excerpt":"Alors que les enseignants cherchent \u00e0 assurer, avec des outils souvent improvis\u00e9s, la \u00ab\u00a0continuit\u00e9 p\u00e9dagogique\u00a0\u00bb, leur pr\u00e9occupation premi\u00e8re devient le d\u00e9crochage. Isol\u00e9s de leurs camarades, face \u00e0 des modes d\u2019enseignement distanci\u00e9s, sans le soutien direct de l\u2019enseignant, de nombreux jeunes ont d\u00e9j\u00e0 disparu du radar de leur \u00e9tablissement. Et plus\u2026","rel":"","context":"Dans &quot;Enseignement \u00e0 distance&quot;","block_context":{"text":"Enseignement \u00e0 distance","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/enseignement-a-distance\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/03\/markus-spiske-zJDqiEGUCHY-unsplash-1-e1678963870303.jpg?fit=720%2C480&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/03\/markus-spiske-zJDqiEGUCHY-unsplash-1-e1678963870303.jpg?fit=720%2C480&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/03\/markus-spiske-zJDqiEGUCHY-unsplash-1-e1678963870303.jpg?fit=720%2C480&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2020\/03\/markus-spiske-zJDqiEGUCHY-unsplash-1-e1678963870303.jpg?fit=720%2C480&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":13033,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2017\/04\/17\/le-smartphone-devient-il-le-nouveau-crayon-livre-de-leleve-veille-et-analyse-tice\/","url_meta":{"origin":3592,"position":1},"title":"Le smartphone devient-il le nouveau \u00ab\u00a0crayon-livre\u00a0\u00bb de l\u2019\u00e9l\u00e8ve ? \u2013 Veille et Analyse TICE","author":"Lyonel Kaufmann","date":"17 avril 2017","format":false,"excerpt":"Un tr\u00e8s bon billet de Bruno Devauchelle sur la place, l'usage et la question des smartphones \u00e0 l'\u00e9cole. Extrait : \u00abRevenons alors \u00e0 la salle de classe. La fameuse \u00ab libert\u00e9 p\u00e9dagogique \u00bb doit-elle permettre cette \u00e9volution vers le \u00ab nouveau crayon-livre \u00bb ? Les tentatives d\u2019encadrement sont-elles vaines ?\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/04\/Image-17.04.17-08-42.9af89229e5d442f480fe27a3a7052bff.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/04\/Image-17.04.17-08-42.9af89229e5d442f480fe27a3a7052bff.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/04\/Image-17.04.17-08-42.9af89229e5d442f480fe27a3a7052bff.jpeg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/04\/Image-17.04.17-08-42.9af89229e5d442f480fe27a3a7052bff.jpeg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/04\/Image-17.04.17-08-42.9af89229e5d442f480fe27a3a7052bff.jpeg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":12920,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2017\/03\/09\/aux-etats-unis-le-smartphone-simpose-comme-outil-pedagogique-educpros\/","url_meta":{"origin":3592,"position":2},"title":"Aux \u00c9tats-Unis, le smartphone s&rsquo;impose comme outil p\u00e9dagogique &#8211; Educpros","author":"Lyonel Kaufmann","date":"9 mars 2017","format":false,"excerpt":"Pendant que le programme d'Emmanuel Macron propose d'interdire les smartphones \u00e0 l'\u00e9cole\u2026 ces derniers s'imposent comme outils p\u00e9dagogiques aux Etats-Unis en\u00a0augmentant l'interactivit\u00e9 en classe, en g\u00e9n\u00e9rant de l'enthousiasme, et surtout, en permettant aux \u00e9l\u00e8ves d'apprendre n'importe o\u00f9, avec ou sans connexion Internet. Allez comprendre Charles\u2026 Les t\u00e9l\u00e9phones portables des \u00e9l\u00e8ves\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/03\/1433009-p426m1143208-580x310.jpg?fit=580%2C310&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/03\/1433009-p426m1143208-580x310.jpg?fit=580%2C310&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/03\/1433009-p426m1143208-580x310.jpg?fit=580%2C310&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":6815,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2014\/09\/09\/quelle-place-pour-le-mobile-de-nos-eleves-en-classe\/","url_meta":{"origin":3592,"position":3},"title":"Quelle place pour le mobile de nos \u00e9l\u00e8ves en classe ?","author":"Lyonel Kaufmann","date":"9 septembre 2014","format":false,"excerpt":"Du 18 au 22 f\u00e9vrier, l'Unesco organise la semaine du mobile de l'UNESCO (18 - 22 f\u00e9vrier prochain) et s'interroge sur la place du t\u00e9l\u00e9phone dans l'enseignement. Comme le note Bruno Devauchelle, Paradoxe que celui d'une semaine qui est consacr\u00e9e \u00e0 l'apprendre \u00e0 l'aide des mobiles alors que dans le\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/04.jpg?fit=480%2C360&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":19544,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2023\/06\/16\/chatgpt-va-t-il-modifier-la-facon-dont-les-enseignants-enseignent\/","url_meta":{"origin":3592,"position":4},"title":"ChatGPT va-t-il modifier la fa\u00e7on dont les enseignants enseignent ?","author":"Lyonel Kaufmann","date":"16 juin 2023","format":false,"excerpt":"Sp\u00e9cialiste de l'histoire de l'\u00e9ducation, Larry Cuban revient dans son blog sur des discours et le tapage depuis huit mois autour de ChatGPT qui le pr\u00e9sente comme un outil transformant pour le meilleur ou le pire l'enseignement. Il en fournit un exemple issu d'une publication du M.I.T. : \u201c[C]hatbots could\u2026","rel":"","context":"Dans &quot;EdNum&quot;","block_context":{"text":"EdNum","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/humanites-digitales\/ednum\/"},"img":{"alt_text":"webpage of chatgpt a prototype ai chatbot is seen on the website of openai on iphone or smartphone","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2023\/06\/pexels-photo-16461434.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2023\/06\/pexels-photo-16461434.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2023\/06\/pexels-photo-16461434.jpeg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2023\/06\/pexels-photo-16461434.jpeg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2023\/06\/pexels-photo-16461434.jpeg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":19382,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2022\/12\/16\/les-jeux-mobiles-smartphones-et-le-monde-antique-paizomen\/","url_meta":{"origin":3592,"position":5},"title":"Les jeux mobiles (smartphones) et le monde antique | Paizomen","author":"Lyonel Kaufmann","date":"16 d\u00e9cembre 2022","format":false,"excerpt":"Le jeu mobile est maintenant le secteur de l'industrie du jeu le plus grand et \u00e0 la croissance la plus rapide. Cela n'est peut-\u00eatre pas surprenant compte tenu de son accessibilit\u00e9 : pour jouer \u00e0 des jeux mobiles, il suffit d'un smartphone, plut\u00f4t qu'un PC ou une console de jeux\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"Had\u00e8s prend la place d'Atlas dans les 12 Travaux d'Hercule.","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/12\/image-26.png?fit=940%2C423&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/12\/image-26.png?fit=940%2C423&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/12\/image-26.png?fit=940%2C423&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/12\/image-26.png?fit=940%2C423&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/3592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=3592"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/3592\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/10228"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=3592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=3592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=3592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}