{"id":4444,"date":"2011-03-10T19:53:06","date_gmt":"2011-03-10T18:53:06","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/03\/10\/femmes-et-revolutions-owni-digital-journalism\/"},"modified":"2011-03-10T19:53:06","modified_gmt":"2011-03-10T18:53:06","slug":"femmes-et-revolutions-owni-digital-journalism","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/03\/10\/femmes-et-revolutions-owni-digital-journalism\/","title":{"rendered":"Femmes et R\u00e9volutions &#124; OWNI, Digital Journalism"},"content":{"rendered":"<div class=\"posterous_autopost\">\n<div class=\"posterous_bookmarklet_entry\">\n<blockquote class=\"posterous_long_quote\">\n<p>Certaines formes de mobilisation f\u00e9minine du \u201cprintemps arabe\u201d semblent r\u00e9v\u00e9ler des invariants intemporels. Comme les Fran\u00e7aises des journ\u00e9es d\u2019Octobre 1789, une partie des femmes du Maghreb se sont mobilis\u00e9es contre le prix du pain. Comme les patriotes am\u00e9ricaines qui rejoignaient les campements de l\u2019arm\u00e9e r\u00e9volutionnaire pendant la Guerre d\u2019Ind\u00e9pendance entre 1775 et 1783, certaines Cairotes se sont employ\u00e9es \u00e0 soigner les bless\u00e9s de la place Tahrir.<br \/>  Aux yeux des hommes, ces actions sont rassurantes&#160;: les femmes de tout temps et de tout pays sont ainsi r\u00e9duites \u00e0 des vertus nourrici\u00e8res et curatives, associ\u00e9es \u00e0 l\u2019\u00a0\u00ab&#160;\u00e9ternelle&#160;\u00bb fonction maternelle.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter size-full wp-image-47113\" src=\"https:\/\/i0.wp.com\/owni.fr\/files\/2011\/02\/5410330220_e12e6e794a_b-e1297895592626.jpg?h=426\"  alt=\"\" \/><\/p>\n<\/blockquote>\n<div class=\"posterous_quote_citation\">via <a href=\"http:\/\/owni.fr\/2011\/03\/10\/femmes-et-revolutions\/\" target=\"_blank\">owni.fr<\/a><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Certaines formes de mobilisation f\u00e9minine du \u201cprintemps arabe\u201d semblent r\u00e9v\u00e9ler des invariants intemporels. Comme les Fran\u00e7aises des journ\u00e9es d\u2019Octobre 1789, une partie des femmes du Maghreb se sont mobilis\u00e9es contre le prix du pain. Comme les patriotes am\u00e9ricaines qui rejoignaient les campements de l\u2019arm\u00e9e r\u00e9volutionnaire pendant la Guerre d\u2019Ind\u00e9pendance entre 1775 et 1783, certaines Cairotes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10221,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11],"tags":[],"class_list":{"0":"post-4444","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nouvelles-de-lhistoire","8":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/5410330220_e12e6e794a_b-e1297895592626.jpg?resize=600%2C400&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/5410330220_e12e6e794a_b-e1297895592626.jpg?resize=600%2C426&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/5410330220_e12e6e794a_b-e1297895592626.jpg?fit=640%2C426&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-19G","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":13418,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2017\/10\/13\/isabella-bird-femme-exploratrice-une-immersion-enjouee-dans-le-japon-du-xixe-siecle\/","url_meta":{"origin":4444,"position":0},"title":"\u00ab\u00a0Isabella Bird, femme exploratrice\u00a0\u00bb\u00a0: une immersion enjou\u00e9e dans le Japon du XIXe si\u00e8cle","author":"Lyonel Kaufmann","date":"13 octobre 2017","format":false,"excerpt":"Les lettres que l\u2019aventuri\u00e8re britannique Isabella Bird (1831-1904) a envoy\u00e9es \u00e0 sa s\u0153ur lors de sa d\u00e9couverte du Japon ont servi de base \u00e0 ce manga tout public. \u00ab Isabella Bird \u00bb. \u00a9 TAIGA SASSA \u00ab J\u2019ai l\u2019impression d\u2019avoir pos\u00e9 le pied sur une autre plan\u00e8te ! \u00bb Si cette\u2026","rel":"","context":"Dans &quot;Publications&quot;","block_context":{"text":"Publications","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/publications\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/10\/Image-13.10.17-13-25.4aad86a13de94ae1a6326b20e9ea8f73.jpeg?fit=644%2C322&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/10\/Image-13.10.17-13-25.4aad86a13de94ae1a6326b20e9ea8f73.jpeg?fit=644%2C322&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/10\/Image-13.10.17-13-25.4aad86a13de94ae1a6326b20e9ea8f73.jpeg?fit=644%2C322&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":13295,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2017\/09\/07\/enseigner-avec-le-numerique-lhistoire-des-femmes\/","url_meta":{"origin":4444,"position":1},"title":"Enseigner avec le num\u00e9rique : l&rsquo;histoire des femmes","author":"Lyonel Kaufmann","date":"7 septembre 2017","format":false,"excerpt":"A l\u2019occasion de le rentr\u00e9e scolaire, le bulletin \u00c9du_Num Histoire-g\u00e9ographie, No 38 propose une certain nombre de ressources en ligne en relation avec les programmes du cycle 4 invitant \u00e0 enseigner une histoire mixte. Des ressources sont \u00e9galement propos\u00e9s pour les Lyc\u00e9es professionnels. Les programmes de cycle 4 invitent, en\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/09\/Image-07.09.17-12-22.38cc6a525e5549bcae8ae77e9cef5f2d.jpeg?fit=500%2C281&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":14649,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2018\/07\/24\/grande-guerre-et-revolution-russe-une-revolution-des-femmes-pour-les-femmes\/","url_meta":{"origin":4444,"position":2},"title":"Sac de plage : Grande Guerre et R\u00e9volution Russe : \u00ab\u00a0une r\u00e9volution\u00a0\u00bb des femmes, pour les femmes\u00a0?","author":"Lyonel Kaufmann","date":"24 juillet 2018","format":false,"excerpt":"1917, la Russie d\u00e9bute sa r\u00e9volution le jour de la c\u00e9l\u00e9bration de la Journ\u00e9e internationale des Femmes. \u00c0 la fin de la guerre, dans les plus hautes sph\u00e8res politiques d'un pays en pleine guerre civile, des femmes participent \u00e0 l'\u00e9laboration d'un nouvel \u00e9quilibre mondial - et attisent l'int\u00e9r\u00eat de la\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/07\/3DAC6A62-7367-4898-A6D1-F165035E1DF9.jpeg?fit=640%2C618&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/07\/3DAC6A62-7367-4898-A6D1-F165035E1DF9.jpeg?fit=640%2C618&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/07\/3DAC6A62-7367-4898-A6D1-F165035E1DF9.jpeg?fit=640%2C618&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":19366,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2022\/12\/13\/feminicide-la-tuerie-de-polytechnique-montreal-1989-2022\/","url_meta":{"origin":4444,"position":3},"title":"F\u00e9minicide : la tuerie de Polytechnique | Montr\u00e9al 1989-2022","author":"Lyonel Kaufmann","date":"13 d\u00e9cembre 2022","format":false,"excerpt":"Le 6 d\u00e9cembre 1989, un homme arm\u00e9 a fait irruption dans les locaux de Polytechnique \u00e0 Montr\u00e9al et y assassine 14 femmes et bless\u00e9 13 personnes. Dor\u00e9navant consid\u00e9r\u00e9e comme un attentat antif\u00e9ministe, la trag\u00e9die a \u00e9branl\u00e9 tout le pays. La lutte contre les violences faites aux femmes est un combat\u2026","rel":"","context":"Dans &quot;Histoire active&quot;","block_context":{"text":"Histoire active","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-active\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/12\/DSC06007.jpeg?fit=427%2C640&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":15781,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2019\/02\/20\/lhistoire-secrete-des-femmes-dans-le-codage-informatique-the-new-york-times\/","url_meta":{"origin":4444,"position":4},"title":"L\u2019histoire secr\u00e8te des femmes dans le codage informatique &#8211; The New York Times","author":"Lyonel Kaufmann","date":"20 f\u00e9vrier 2019","format":false,"excerpt":"Qui sait que d\u00e8s ann\u00e9es 1940 aux ann\u00e9es 1980, la place des femmes dans la programmation des ordinateurs \u00e9tait bien meilleure qu\u2019aujourd\u2019hui ? Qu\u2019est ce qui s\u2019est mal pass\u00e9 ? Le New York Times Magazine revient sur l\u2019histoire de ces femmes pionni\u00e8res de l\u2019informatique aux Etats-Unis et au Canada. Extraits.\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/02\/17mag-coders-pics-slide-BTTD-superJumbo-v3.70512e8e9b0e421ea146b704359cb8cc.png?fit=1200%2C731&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/02\/17mag-coders-pics-slide-BTTD-superJumbo-v3.70512e8e9b0e421ea146b704359cb8cc.png?fit=1200%2C731&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/02\/17mag-coders-pics-slide-BTTD-superJumbo-v3.70512e8e9b0e421ea146b704359cb8cc.png?fit=1200%2C731&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/02\/17mag-coders-pics-slide-BTTD-superJumbo-v3.70512e8e9b0e421ea146b704359cb8cc.png?fit=1200%2C731&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/02\/17mag-coders-pics-slide-BTTD-superJumbo-v3.70512e8e9b0e421ea146b704359cb8cc.png?fit=1200%2C731&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":14147,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2018\/05\/07\/suisse-1957-un-premier-vote-feminin-sous-les-huees-le-temps\/","url_meta":{"origin":4444,"position":5},"title":"Suisse 1957 : Un premier vote f\u00e9minin sous les hu\u00e9es | Le Temps","author":"Lyonel Kaufmann","date":"7 mai 2018","format":false,"excerpt":"En mars 1957, un petit village haut-valaisan fait sensation en autorisant les femmes \u00e0 glisser un bulletin dans l\u2019urne, quatorze ans avant le droit de vote au niveau f\u00e9d\u00e9ral. La fille de la premi\u00e8re votante de l\u2019histoire suisse raconte l\u2019\u00e9v\u00e9nement qui a marqu\u00e9 son village La main de Katharina Zenh\u00e4usern\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/05\/1B9E84EC-D8F1-49CD-9FEB-CFD30826EB9F.jpeg?fit=767%2C422&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/05\/1B9E84EC-D8F1-49CD-9FEB-CFD30826EB9F.jpeg?fit=767%2C422&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/05\/1B9E84EC-D8F1-49CD-9FEB-CFD30826EB9F.jpeg?fit=767%2C422&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/05\/1B9E84EC-D8F1-49CD-9FEB-CFD30826EB9F.jpeg?fit=767%2C422&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/4444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=4444"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/4444\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/10221"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=4444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=4444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=4444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}