{"id":4446,"date":"2011-03-03T13:45:28","date_gmt":"2011-03-03T12:45:28","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/03\/03\/jefftavernier-linnovation-pedagogique\/"},"modified":"2011-03-03T13:45:28","modified_gmt":"2011-03-03T12:45:28","slug":"jefftavernier-linnovation-pedagogique","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/03\/03\/jefftavernier-linnovation-pedagogique\/","title":{"rendered":"jefftavernier: L\u2019innovation p\u00e9dagogique passe-t-elle par la destruction de la salle de classe\u00a0?"},"content":{"rendered":"<figure id=\"attachment_4447\" aria-describedby=\"caption-attachment-4447\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.fastcodesign.com\/1662178\/wanna-improve-education-demolish-the-classrooms\" rel=\"attachment wp-att-4447\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-4447\" alt=\"\" src=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2011\/12\/tumblr_lheg9h3ihp1qatz47o1_1280.jpg?resize=600%2C800\" width=\"600\" height=\"800\" \/><\/a><figcaption id=\"caption-attachment-4447\" class=\"wp-caption-text\">jefftavernier: L\u2019innovation p\u00e9dagogique passe-t-elle par la destruction de la salle de classe\u00a0?<\/figcaption><\/figure>\n<p><a href=\"http:\/\/www.fastcodesign.com\/1662178\/wanna-improve-education-demolish-the-classrooms\" target=\"_blank\">L\u2019innovation p\u00e9dagogique passe-t-elle par la destruction de la salle de classe\u00a0?<\/a><\/p>\n<p>Pour le cabinet d\u2019architecture et de design 3XN bas\u00e9 \u00e0 Copenhague, pas de doute\u00a0: l\u2019\u00e9ducation du XXI\u00e8 si\u00e8cle passe par la fin des murs au sein de l\u2019\u00e9cole pour une v\u00e9ritable p\u00e9dagogie bas\u00e9e sur la collaboration. Les prises de vue sont captivantes et je me surprends \u00e0 m\u2019imaginer parcourir ces all\u00e9es, rencontrer un groupe d\u2019\u00e9l\u00e8ve au d\u00e9tour d\u2019un espace num\u00e9rique et pr\u00e9parer une s\u00e9ance au milieu de ces poufs orang\u00e9s\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019innovation p\u00e9dagogique passe-t-elle par la destruction de la salle de classe\u00a0? Pour le cabinet d\u2019architecture et de design 3XN bas\u00e9 \u00e0 Copenhague, pas de doute\u00a0: l\u2019\u00e9ducation du XXI\u00e8 si\u00e8cle passe par la fin des murs au sein de l\u2019\u00e9cole pour une v\u00e9ritable p\u00e9dagogie bas\u00e9e sur la collaboration. Les prises de vue sont captivantes et je [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11],"tags":[],"class_list":{"0":"post-4446","1":"post","2":"type-post","3":"status-publish","4":"format-image","5":"has-post-thumbnail","7":"category-nouvelles-de-lhistoire","8":"post_format-post-format-image","9":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/tumblr_lheg9h3ihp1qatz47o1_1280.jpg?resize=600%2C400&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/tumblr_lheg9h3ihp1qatz47o1_1280.jpg?resize=600%2C600&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/tumblr_lheg9h3ihp1qatz47o1_1280.jpg?fit=600%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-19I","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":14161,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2018\/05\/07\/linnovation-pour-un-retour-a-la-pedagogie\/","url_meta":{"origin":4446,"position":0},"title":"L&rsquo;innovation pour un retour \u00e0 la p\u00e9dagogie","author":"Lyonel Kaufmann","date":"7 mai 2018","format":false,"excerpt":"Qu'est ce que l'innovation p\u00e9dagogique et \u00e0 quoi sert-elle ? La question a re\u00e7u bien des d\u00e9finitions. Souvent , et particuli\u00e8rement pour l'Education nationale, elle est pr\u00e9sent\u00e9e sous l'angle des \"bonnes pratiques\" recens\u00e9es officiellement pour duplication et g\u00e9n\u00e9ralisation. Ce n'est pas le point de vue de l'OCDE qui publie un\u2026","rel":"","context":"Dans &quot;Didactique&quot;","block_context":{"text":"Didactique","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/05\/img_0914.jpg?fit=1200%2C910&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/05\/img_0914.jpg?fit=1200%2C910&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/05\/img_0914.jpg?fit=1200%2C910&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/05\/img_0914.jpg?fit=1200%2C910&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/05\/img_0914.jpg?fit=1200%2C910&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":16390,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2019\/09\/14\/debat-enseignement-superieur-replacons-la-salle-de-cours-au-cur-de-la-cite-innovation-pedagogique\/","url_meta":{"origin":4446,"position":1},"title":"D\u00e9bat : Enseignement sup\u00e9rieur, repla\u00e7ons la salle de cours au c\u0153ur de la cit\u00e9 !","author":"Lyonel Kaufmann","date":"14 septembre 2019","format":false,"excerpt":"Les infrastructures de l\u2019Internet ont fourni un support \u00e0 un r\u00eave d\u00e9j\u00e0 ancien, celui de diffuser la connaissance au plus grand nombre. Mais l\u2019ambition des sciences ouvertes ne se limite pas aux questions d\u2019acc\u00e8s que de nouveaux moyens techniques et juridiques facilitent un peu plus chaque jour. Si elles visent\u2026","rel":"","context":"Dans &quot;Didactique&quot;","block_context":{"text":"Didactique","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/09\/022D44EB-06A6-47EF-82EA-5A0BD8DEEE23.063d504319a24d15a17117ac05660c2c.jpeg?fit=1200%2C694&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/09\/022D44EB-06A6-47EF-82EA-5A0BD8DEEE23.063d504319a24d15a17117ac05660c2c.jpeg?fit=1200%2C694&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/09\/022D44EB-06A6-47EF-82EA-5A0BD8DEEE23.063d504319a24d15a17117ac05660c2c.jpeg?fit=1200%2C694&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/09\/022D44EB-06A6-47EF-82EA-5A0BD8DEEE23.063d504319a24d15a17117ac05660c2c.jpeg?fit=1200%2C694&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/09\/022D44EB-06A6-47EF-82EA-5A0BD8DEEE23.063d504319a24d15a17117ac05660c2c.jpeg?fit=1200%2C694&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":12145,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/10\/17\/faire-le-point-sur-la-classe-inversee-en-histoire-comme-ailleurs\/","url_meta":{"origin":4446,"position":2},"title":"Faire le point sur la Classe invers\u00e9e en histoire\u2026 comme ailleurs","author":"Lyonel Kaufmann","date":"17 octobre 2016","format":false,"excerpt":"Dans cet article, je reviens, dans un premier temps, sur deux articles publi\u00e9s ici qui ont fait le buzz relativement \u00e0 la classe invers\u00e9e. Dans un deuxi\u00e8me temps, \u00e0 l'aide du mod\u00e8le SAMR,\u00a0\u00a0je m'int\u00e9resse aux conditions \u00e0 partir desquelles un dispositif p\u00e9dagogique, telle la classe invers\u00e9e, recourant \u00e0 des outils\u2026","rel":"","context":"Dans &quot;Didactique&quot;","block_context":{"text":"Didactique","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/10\/0.jpg?fit=480%2C360&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12818,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2017\/02\/17\/faut-il-enseigner-linnovation-aux-etudiants\/","url_meta":{"origin":4446,"position":3},"title":"Faut-il enseigner l\u2019innovation aux \u00e9tudiants ?","author":"Lyonel Kaufmann","date":"17 f\u00e9vrier 2017","format":false,"excerpt":"Avec cet article int\u00e9ressant concernant la question de l'innovation dans les organisations, il est \u00e9galement possible de r\u00e9fl\u00e9chir \u00e0 la question de l'innovation dans l'enseignement. L'article donne ansi \u00e0 r\u00e9fl\u00e9chir par rapport \u00e0 la question du syst\u00e8me scolaire et de la formation des enseignants : \u00abFinalement l\u2019innovation n\u2019est-elle pas juste\u2026","rel":"","context":"Dans &quot;Humanit\u00e9s Digitales&quot;","block_context":{"text":"Humanit\u00e9s Digitales","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/humanites-digitales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/02\/Image-17.02.17-08-31.jpeg?fit=926%2C618&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/02\/Image-17.02.17-08-31.jpeg?fit=926%2C618&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/02\/Image-17.02.17-08-31.jpeg?fit=926%2C618&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/02\/Image-17.02.17-08-31.jpeg?fit=926%2C618&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3612,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/03\/05\/cafe-histoire-du-5-march-2011\/","url_meta":{"origin":4446,"position":4},"title":"Caf\u00e9 histoire du 5 March 2011","author":"Lyonel Kaufmann","date":"5 mars 2011","format":false,"excerpt":"A publi\u00e9 Pourquoi raconter des histoires ? | Performances. Pourquoi raconter des histoires ? | Performances: Le petit livre de Jerome Bruner donne des \u00e9l\u00e9ments... A publi\u00e9 \"L\u2019incr\u00e9dulit\u00e9 d\u2019une partie des Occidentaux, en particulier des Fran\u00e7ais, \u00e0 l\u2019\u00e9gard de la capacit\u00e9...\". \u201cL\u2019incr\u00e9dulit\u00e9 d\u2019une partie des Occidentaux, en particulier des Fran\u00e7ais,\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/tumblr_lheg9h3ihp1qatz47o1_500.jpg?fit=500%2C667&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9743,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2015\/05\/01\/le-byod-entre-perspectives-et-realites-pedagogiques\/","url_meta":{"origin":4446,"position":5},"title":"Le BYOD : entre perspectives et r\u00e9alit\u00e9s p\u00e9dagogiques","author":"Lyonel Kaufmann","date":"1 mai 2015","format":false,"excerpt":"Ces derni\u00e8res ann\u00e9es, nous voyons appara\u00eetre une nouvelle forme d\u2019int\u00e9gration des technologies en salle de classe : le \u00ab Bring Your Own Device (BYOD) \u00bb. Ce nouveau type de configuration r\u00e9pond \u00e0 des besoins financiers, mais \u00e9galement \u00e9ducatifs dans une soci\u00e9t\u00e9 o\u00f9 l\u2019enseignement est de plus en plus personnalis\u00e9 et\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/4446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=4446"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/4446\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/10226"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=4446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=4446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=4446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}