{"id":4459,"date":"2011-02-04T10:05:29","date_gmt":"2011-02-04T09:05:29","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/02\/04\/le-discours-dun-roi-confirme-a-quel-point-la\/"},"modified":"2011-02-04T10:05:29","modified_gmt":"2011-02-04T09:05:29","slug":"le-discours-dun-roi-confirme-a-quel-point-la","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/02\/04\/le-discours-dun-roi-confirme-a-quel-point-la\/","title":{"rendered":"Le Discours d&#8217;un roi&#160;: la voix royale"},"content":{"rendered":"<p>Le Discours d\u2019un roi confirme \u00e0 quel point la Seconde Guerre mondiale est devenue l\u2019histoire fondatrice de notre pays, pour ne pas dire son mythe fondateur. Les Fran\u00e7ais ont 1789, les Am\u00e9ricains 1776 et les Britanniques 1940&#160;: ce moment de gr\u00e2ce o\u00f9 nous sommes rest\u00e9s les seuls \u00e0 r\u00e9sister \u00e0 la barbarie nazie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Discours d\u2019un roi confirme \u00e0 quel point la Seconde Guerre mondiale est devenue l\u2019histoire fondatrice de notre pays, pour ne pas dire son mythe fondateur. Les Fran\u00e7ais ont 1789, les Am\u00e9ricains 1776 et les Britanniques 1940&#160;: ce moment de gr\u00e2ce o\u00f9 nous sommes rest\u00e9s les seuls \u00e0 r\u00e9sister \u00e0 la barbarie nazie.<\/p>\n","protected":false},"author":1,"featured_media":9896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"quote","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11],"tags":[],"class_list":{"0":"post-4459","1":"post","2":"type-post","3":"status-publish","4":"format-quote","5":"has-post-thumbnail","7":"category-nouvelles-de-lhistoire","8":"post_format-post-format-quote","9":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?fit=658%2C184&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-19V","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":3625,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/03\/10\/le-roi-et-le-photographe-sous-le-capteur-limage\/","url_meta":{"origin":4459,"position":0},"title":"Le roi et le photographe &#124; Sous le capteur l&#039;image","author":"Lyonel Kaufmann","date":"10 mars 2011","format":false,"excerpt":"Alors que la photographie du roi Georges VI pronon\u00e7ant son discours est une mise en sc\u00e8ne o\u00f9 le roi mime son discours et non pas une photographie prise dans le \u00abfeu de l'action\u00bb, Gr\u00e9gory Divoux nous pr\u00e9cise que cela n'est pas anodin. En effet, \u00ab en 1939, les conditions du\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/Photo-Georges-VI_Corbis.jpg?fit=640%2C475&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/Photo-Georges-VI_Corbis.jpg?fit=640%2C475&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/Photo-Georges-VI_Corbis.jpg?fit=640%2C475&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":3515,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/02\/10\/cafe-histoire-du-10-february-2011\/","url_meta":{"origin":4459,"position":1},"title":"Caf\u00e9 histoire du 10 February 2011","author":"Lyonel Kaufmann","date":"10 f\u00e9vrier 2011","format":false,"excerpt":"A publi\u00e9 \"Non la Tunisie n\u2019est pas en 1789\u00a0! Par piti\u00e9 que l\u2019on cesse d\u2019instrumentaliser l\u2019Histoire en...\". \u201cNon la Tunisie n\u2019est pas en 1789\u00a0! Par piti\u00e9 que l\u2019on cesse d\u2019instrumentaliser... A publi\u00e9 \"Le Discours d\u2019un roi confirme \u00e0 quel point la Seconde Guerre mondiale est devenue l\u2019histoire...\". \u201cLe Discours d\u2019un\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1718,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2009\/12\/18\/links-for-2009-12-17\/","url_meta":{"origin":4459,"position":2},"title":"L&#039;\u00e9nigme du roi Arthur &#124; Sciences humaines","author":"Lyonel Kaufmann","date":"18 d\u00e9cembre 2009","format":false,"excerpt":"L'\u00e9nigme du roi Arthur | Sciences humaines Le roi Arthur a-t-il vraiment exist\u00e9 ou n'est-ce qu'un mythe? L'histoire de ce personnage n'est pas sans rapport et similitude avec celle de Guillaume Tell. Dans les deux cas, leur \u00abhistoire\u00bb constitue un t\u00e9moignage pr\u00e9cieux, non pas sur les temps o\u00f9 ils auraient\u2026","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":18835,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2022\/04\/05\/geographie-et-imperialisme-de-la-suisse-au-congo-entre-exploration-geographique-et-conquete-coloniale\/","url_meta":{"origin":4459,"position":3},"title":"G\u00e9ographie et imp\u00e9rialisme. De la Suisse au Congo entre exploration g\u00e9ographique et conqu\u00eate coloniale","author":"Lyonel Kaufmann","date":"5 avril 2022","format":false,"excerpt":"G\u00e9ographie coloniale et imp\u00e9rialisme suisse : une histoire transnationale. Au XIXe si\u00e8cle, les soci\u00e9t\u00e9s de g\u00e9ographie repr\u00e9sentaient, \u00e0 c\u00f4t\u00e9 d\u2019autres milieux, des c\u00e9nacles o\u00f9 se produisait un discours raciste accompagn\u00e9 d\u2019actions expansionnistes. Les fr\u00e9quentaient des repr\u00e9sentants de l\u2019\u00e9conomie capitaliste, de la politique f\u00e9d\u00e9rale ou encore du monde scientifique et culturel,\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/04\/img_2140.jpg?fit=832%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/04\/img_2140.jpg?fit=832%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/04\/img_2140.jpg?fit=832%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2022\/04\/img_2140.jpg?fit=832%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":11779,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/08\/13\/des-vestiges-royaux-decouverts-a-tintagel-lieu-de-naissance-du-roi-arthur-selon-la-legende\/","url_meta":{"origin":4459,"position":4},"title":"Des vestiges royaux d\u00e9couverts \u00e0 Tintagel, lieu de naissance du Roi Arthur selon la l\u00e9gende","author":"Lyonel Kaufmann","date":"13 ao\u00fbt 2016","format":false,"excerpt":"Les arch\u00e9ologues sont entrain d'investir une myst\u00e9rieuse implantation c\u00f4ti\u00e8re, dont ils pensent qu'elle aurait pu \u00eatre la maison de la royaut\u00e9 britannique post-romaine, \u00e0\u00a0Tintagel\u00a0dans les Cornouailles, lieu de naissance, selon la l\u00e9gende, du\u00a0Roi Arthur. Les chercheurs esp\u00e8rent d\u00e9couvrir si Tintagel \u00e9tait le site d'une implantation marchande ou d'un centre en\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/08\/Des2Bvestiges2Broyaux2Bd25C325A9couverts2B25C325A02BTintagel252C2Blieu2Bde2Bnaissance2Bdu2BRoi2BArthur2Bselon2Bla2Bl25C325A9gende.jpeg?fit=600%2C401&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/08\/Des2Bvestiges2Broyaux2Bd25C325A9couverts2B25C325A02BTintagel252C2Blieu2Bde2Bnaissance2Bdu2BRoi2BArthur2Bselon2Bla2Bl25C325A9gende.jpeg?fit=600%2C401&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/08\/Des2Bvestiges2Broyaux2Bd25C325A9couverts2B25C325A02BTintagel252C2Blieu2Bde2Bnaissance2Bdu2BRoi2BArthur2Bselon2Bla2Bl25C325A9gende.jpeg?fit=600%2C401&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":12413,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/11\/25\/publication-le-roi-arthur-un-mythe-contemporain\/","url_meta":{"origin":4459,"position":5},"title":"Publication : Le Roi Arthur, un mythe contemporain","author":"Lyonel Kaufmann","date":"25 novembre 2016","format":false,"excerpt":"Le Roi Arthur, un mythe contemporain de William Blanc est un ouvrage qui ne manquera pas d'int\u00e9resser les professeurs d'histoire. Il pr\u00e9sente la l\u00e9gende athurienne dans le monde d'aujourd'hui tout en retra\u00e7ant l'histoire de ce mythe du Moyen \u00c2ge \u00e0 ce d\u00e9but du 21e si\u00e8cle. Apr\u00e8s un passage \u00e0 vide\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/11\/Image-25.11.16-23-36.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/11\/Image-25.11.16-23-36.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/11\/Image-25.11.16-23-36.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/4459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=4459"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/4459\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/9896"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=4459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=4459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=4459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}