{"id":4473,"date":"2011-01-12T14:18:39","date_gmt":"2011-01-12T13:18:39","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/01\/12\/en-1989-la-chute-du-mur-de-berlin-a-cloture-le\/"},"modified":"2011-01-12T14:18:39","modified_gmt":"2011-01-12T13:18:39","slug":"en-1989-la-chute-du-mur-de-berlin-a-cloture-le","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/01\/12\/en-1989-la-chute-du-mur-de-berlin-a-cloture-le\/","title":{"rendered":"En 1989, la chute du mur de Berlin a cl\u00f4tur\u00e9 le XXe si\u00e8cle. Ce qui, jusqu\u2019\u00e0 la veille, palpitait dan"},"content":{"rendered":"<p>En 1989, la chute du mur de Berlin a cl\u00f4tur\u00e9 le XXe si\u00e8cle. Ce qui, jusqu\u2019\u00e0 la veille, palpitait dans le pr\u00e9sent, est soudainement apparu comme appartenant \u00e0 l\u2019histoire. Profond\u00e9ment affect\u00e9e par cette rupture, l\u2019historiographie a d\u00fb remettre en cause ses paradigmes, questionner ses m\u00e9thodes, red\u00e9finir ses domaines. La mani\u00e8re de penser et d\u2019\u00e9crire l\u2019histoire du monde contemporain s\u2019est modifi\u00e9e. Les clivages fig\u00e9s de la guerre froide ont laiss\u00e9 la place \u00e0 l\u2019histoire globale qui, au lieu d\u2019un si\u00e8cle divis\u00e9 en blocs, voit un r\u00e9seau d\u2019\u00e9changes \u00e9conomiques, de transferts d\u00e9mographiques, d\u2019hybridations culturelles \u00e0 l\u2019\u00e9chelle de la plan\u00e8te. (via <a href=\"http:\/\/blog.passion-histoire.net\/?p=8784\" target=\"_blank\">L\u2019histoire comme champ de bataille&#160;\u00bb Le blog de l&#8217;histoire &#8211; Toute l&#8217;actualit\u00e9 de l&#8217;histoire par Passion-Histoire.net<\/a>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 1989, la chute du mur de Berlin a cl\u00f4tur\u00e9 le XXe si\u00e8cle. Ce qui, jusqu\u2019\u00e0 la veille, palpitait dans le pr\u00e9sent, est soudainement apparu comme appartenant \u00e0 l\u2019histoire. Profond\u00e9ment affect\u00e9e par cette rupture, l\u2019historiographie a d\u00fb remettre en cause ses paradigmes, questionner ses m\u00e9thodes, red\u00e9finir ses domaines. La mani\u00e8re de penser et d\u2019\u00e9crire l\u2019histoire [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11],"tags":[],"class_list":{"0":"post-4473","1":"post","2":"type-post","3":"status-publish","4":"format-image","5":"has-post-thumbnail","7":"category-nouvelles-de-lhistoire","8":"post_format-post-format-image","9":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?fit=658%2C184&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-1a9","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":3402,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/01\/13\/cafe-histoire-du-13-january-2011\/","url_meta":{"origin":4473,"position":0},"title":"Caf\u00e9 histoire du 13 January 2011","author":"Lyonel Kaufmann","date":"13 janvier 2011","format":false,"excerpt":"A partag\u00e9 Les pogroms perp\u00e9tr\u00e9s en Pologne en.... A publi\u00e9 En 1989, la chute du mur de Berlin a cl\u00f4tur\u00e9 le XXe si\u00e8cle. Ce.... En 1989, la chute du mur de Berlin a ... A publi\u00e9 \"Dans un brillant chapitre consacr\u00e9 \u00e0 \u00ab\u00a0L\u2019invention de l\u2019Antiquit\u00e9\u00a0\u00bb, l\u2019auteur s\u2019attaque \u00e0...\". \u201cDans un\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":9073,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/08\/15\/une-histoire-de-lhistoire-a-berlin-capitale-du-xxe-siecle-2\/","url_meta":{"origin":4473,"position":1},"title":"Une \u00ab histoire de l\u2019Histoire \u00bb \u00e0 Berlin, capitale du XXe si\u00e8cle","author":"Lyonel Kaufmann","date":"15 ao\u00fbt 2011","format":"link","excerpt":"Une \u00ab\u00a0histoire de l\u2019Histoire\u00a0\u00bb \u00e0 Berlin, capitale du XXe si\u00e8cle Mouvements artistiques, Rosa Luxemburg, Deuxi\u00e8me Guerre mondiale, le Mur et sa chute : Berlin est-elle la \u00ab capitale \u00bb du XXe si\u00e8cle, pour le meilleur et pour le pire ?\u00a0La r\u00e9ponse est oui pour l'auteur de cet article sur Rue89.\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3926,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/08\/15\/une-histoire-de-lhistoire-a-berlin-capitale-du-xxe-siecle\/","url_meta":{"origin":4473,"position":2},"title":"Une \u00ab histoire de l\u2019Histoire \u00bb \u00e0 Berlin, capitale du XXe si\u00e8cle","author":"Lyonel Kaufmann","date":"15 ao\u00fbt 2011","format":"link","excerpt":"Une \u00ab\u00a0histoire de l\u2019Histoire\u00a0\u00bb \u00e0 Berlin, capitale du XXe si\u00e8cle Mouvements artistiques, Rosa Luxemburg, Deuxi\u00e8me Guerre mondiale, le Mur et sa chute : Berlin est-elle la \u00ab capitale \u00bb du XXe si\u00e8cle, pour le meilleur et pour le pire ?\u00a0La r\u00e9ponse est oui pour l'auteur de cet article sur Rue89.\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":16614,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2019\/11\/09\/berlin-1989-le-week-end-de-la-chute-liberation\/","url_meta":{"origin":4473,"position":3},"title":"Berlin 1989, le week-end de la chute &#8211; Lib\u00e9ration","author":"Lyonel Kaufmann","date":"9 novembre 2019","format":false,"excerpt":"Le 11 novembre, du c\u00f4t\u00e9 Ouest du Mur.\u00a0Photo Jean-Claude Coutausse Il y a trente ans, le photographe Jean-Claude Coutausse couvrait les \u00e9v\u00e9nements \u00e0 Berlin pour le journal \u00abLib\u00e9ration\u00bb. Arriv\u00e9 sur place le\u00a010\u00a0novembre au soir, il raconte qu'il a entendu le Mur avant de le voir\u00a0: des centaines de Berlinois frappaient\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/11\/1268296-jcc1147009.jpg?fit=1200%2C799&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/11\/1268296-jcc1147009.jpg?fit=1200%2C799&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/11\/1268296-jcc1147009.jpg?fit=1200%2C799&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/11\/1268296-jcc1147009.jpg?fit=1200%2C799&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2019\/11\/1268296-jcc1147009.jpg?fit=1200%2C799&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1543,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2009\/09\/10\/10-apres-sa-chute-chronique-du-mur-de-berlin\/","url_meta":{"origin":4473,"position":4},"title":"20 apr\u00e8s sa chute: Chronique du Mur de Berlin","author":"Lyonel Kaufmann","date":"10 septembre 2009","format":false,"excerpt":"Chronik der Mauer - Bau und Fall der Berliner Mauer La chronique du Mur de Berlin de 1961 \u00e0 1989 par la Bundesrentrale f\u00fcr politische Bildung, la Zentrume f\u00fcr Zeithistorische F\u00f6rschung et la Deutschlandradio. Un impressionnant dossier de sources et documents de la p\u00e9riode est offert en mati\u00e8re de films,\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1644,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2009\/10\/23\/links-for-2009-10-22\/","url_meta":{"origin":4473,"position":5},"title":"Th\u00e9matique : Les 20 ans de la chute du mur de Berlin &#124; Educasources","author":"Lyonel Kaufmann","date":"23 octobre 2009","format":false,"excerpt":"Th\u00e9matique : Les 20 ans de la chute du mur de Berlin | Educasources Important dossiers de ressources en lignes r\u00e9alis\u00e9 par Educasources en relation avec la chute du Mur de Berlin. Les ressources sont organis\u00e9es autour de 4 th\u00e9matiques: a) L'Allemagne coup\u00e9e en deux: avant la chute du mur\u2026","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/4473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=4473"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/4473\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/9896"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=4473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=4473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=4473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}