{"id":4487,"date":"2010-09-28T12:55:21","date_gmt":"2010-09-28T10:55:21","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/09\/28\/dans-le-monde-de-limprime-les-gens-ne-vont-pas\/"},"modified":"2010-09-28T12:55:21","modified_gmt":"2010-09-28T10:55:21","slug":"dans-le-monde-de-limprime-les-gens-ne-vont-pas","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/09\/28\/dans-le-monde-de-limprime-les-gens-ne-vont-pas\/","title":{"rendered":"\u00abDans le monde de l\u2019imprim\u00e9, les gens ne vont pas au magasin pour dire :\u00a0\u201cOh, excusez-moi, puis-je a"},"content":{"rendered":"<p><em>\u00abDans le monde de l\u2019imprim\u00e9, les gens ne vont pas au magasin pour dire :\u00a0\u201cOh, excusez-moi, puis-je acheter une carte de moi&#160;?\u201d\u00a0Au lieu de cela ils demandent une carte de New York ou d\u2019Amsterdam ou du m\u00e9tro. Vous et moi ne sommes pas visibles sur ces cartes. Les cartes sont des endroits dans lesquels il nous faut nous ins\u00e9rer. <\/em><\/p>\n<p><em>Mais le monde num\u00e9rique a chang\u00e9 cela. D\u00e9sormais, nous sommes toujours au centre de la carte, et c\u2019est un endroit tr\u00e8s puissant o\u00f9 \u00eatre.\u00bb<\/em><\/p>\n<p><a href=\"http:\/\/www.internetactu.net\/2010\/09\/28\/un-monde-de-technologies-centrees-sur-lutilisateur\/\" target=\"_blank\">Un monde de technologies centr\u00e9es sur l\u2019utilisateur \u00ab&#160;InternetActu.net<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abDans le monde de l\u2019imprim\u00e9, les gens ne vont pas au magasin pour dire :\u00a0\u201cOh, excusez-moi, puis-je acheter une carte de moi&#160;?\u201d\u00a0Au lieu de cela ils demandent une carte de New York ou d\u2019Amsterdam ou du m\u00e9tro. Vous et moi ne sommes pas visibles sur ces cartes. Les cartes sont des endroits dans lesquels il [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11],"tags":[],"class_list":{"0":"post-4487","1":"post","2":"type-post","3":"status-publish","4":"format-image","5":"has-post-thumbnail","7":"category-nouvelles-de-lhistoire","8":"post_format-post-format-image","9":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?fit=658%2C184&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-1an","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":11390,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/04\/24\/une-exposition-sur-la-cartographie-ou-le-miroir-du-monde-eduscol-hg\/","url_meta":{"origin":4487,"position":0},"title":"Une exposition sur la cartographie ou le miroir du monde\u00a0&#8211; \u00c9duscol HG","author":"Lyonel Kaufmann","date":"24 avril 2016","format":false,"excerpt":"G\u00e9rard Mercator et Abraham Ortelius sont consid\u00e9r\u00e9s comme les fondateurs de la g\u00e9ographie moderne. Tous deux originaires de Flandre, ils se rencontrent en 1554 et bien vite une amiti\u00e9 voit le jour. Leur travail va r\u00e9volutionner la cartographie. \u00c0 Mercator, on doit en 1569 la c\u00e9l\u00e8bre carte du monde :\u2026","rel":"","context":"Dans &quot;Opinions&amp;R\u00e9flexions&quot;","block_context":{"text":"Opinions&amp;R\u00e9flexions","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/opinionsreflexions\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/04\/eda27319-a4c4-484b-8c92-66f3befe075d.jpg?fit=600%2C519&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/04\/eda27319-a4c4-484b-8c92-66f3befe075d.jpg?fit=600%2C519&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/04\/eda27319-a4c4-484b-8c92-66f3befe075d.jpg?fit=600%2C519&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":3244,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/09\/30\/cafe-histoire-du-30-september-2010\/","url_meta":{"origin":4487,"position":1},"title":"Caf\u00e9 histoire du 30 September 2010","author":"Lyonel Kaufmann","date":"30 septembre 2010","format":false,"excerpt":"A publi\u00e9 Apr\u00e8s une introduction d\u00e9j\u00e0 lourde de sens, le r\u00e9cit d\u00e9bute par.... Apr\u00e8s une introduction d\u00e9j\u00e0 lourde de sens, le r\u00e9cit d\u00e9bute par la mise en images du massacre de ... A publi\u00e9 \"One cannot understand the history of education in the United States during the twentieth century...\". \u201cOne\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/tumblr_l9gdxci1MU1qztho4o1_500.jpg?fit=500%2C275&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12786,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2017\/02\/12\/des-incroyables-cartes-et-infographies-du-xixe-siecle\/","url_meta":{"origin":4487,"position":2},"title":"Des incroyables cartes et infographies du XIXe si\u00e8cle","author":"Lyonel Kaufmann","date":"12 f\u00e9vrier 2017","format":false,"excerpt":"Entre 1849 et 1851, l\u2019illustrateur topographique et graveur Emslie et l\u2019\u00e9diteur Reynolds con\u00e7urent des diagrammes scientifiques repr\u00e9sentant dans un grand livre de douze pages intitul\u00e9 Geological Diagrams. A l\u2019\u00e9poque, les illustrateurs et cartographes contribuaient beaucoup au d\u00e9veloppement de l\u2019accessibilit\u00e9 et de la visibilit\u00e9 de la recherche scientifique en cr\u00e9ant des\u2026","rel":"","context":"Dans &quot;Publications&quot;","block_context":{"text":"Publications","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/publications\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/02\/Image-12.02.17-20-42.82c82788fde043b7a3d2809a64fe2aa0.jpeg?fit=1090%2C898&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/02\/Image-12.02.17-20-42.82c82788fde043b7a3d2809a64fe2aa0.jpeg?fit=1090%2C898&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/02\/Image-12.02.17-20-42.82c82788fde043b7a3d2809a64fe2aa0.jpeg?fit=1090%2C898&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/02\/Image-12.02.17-20-42.82c82788fde043b7a3d2809a64fe2aa0.jpeg?fit=1090%2C898&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/02\/Image-12.02.17-20-42.82c82788fde043b7a3d2809a64fe2aa0.jpeg?fit=1090%2C898&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4584,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2009\/09\/09\/la-carte-du-monde-arthurien-arthurian-period-map\/","url_meta":{"origin":4487,"position":3},"title":"La carte du monde arthurien. Arthurian Period Map | King Arthur &amp; The Knights of the Round Table","author":"Lyonel Kaufmann","date":"9 septembre 2009","format":"image","excerpt":"La carte du monde arthurien. Arthurian Period Map | King Arthur & The Knights of the Round Table","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2009\/09\/084F3B39-A49E-4C61-975F-BB249AA61072.gif?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":9494,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2015\/03\/10\/revue-de-presse-comment-les-americains-voyaient-le-monde-en-1837\/","url_meta":{"origin":4487,"position":4},"title":"Revue de Presse : Comment les Am\u00e9ricains voyaient le monde en 1837","author":"Lyonel Kaufmann","date":"10 mars 2015","format":false,"excerpt":"Ce document qui repr\u00e9sente la situation g\u00e9opolitique du d\u00e9but du XIXe si\u00e8cle, nous donne aussi un aper\u00e7u de la vision qu\u2019avait de ce monde moral un am\u00e9ricain. Cette carte nous renseigne pr\u00e8s de deux si\u00e8cles plus tard sur les repr\u00e9sentations intellectuelles du XIXe si\u00e8cle. A voir \u00e9galement la carte dans\u2026","rel":"","context":"Dans &quot;Outils enseignement&quot;","block_context":{"text":"Outils enseignement","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/outils-enseignement\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/1NCZ9Ot.jpg?fit=640%2C400&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/1NCZ9Ot.jpg?fit=640%2C400&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/1NCZ9Ot.jpg?fit=640%2C400&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":532,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2008\/11\/20\/links-for-2008-11-20\/","url_meta":{"origin":4487,"position":5},"title":"Comm\u00e9morations 14-18 &#124;\u00a0Cartes heuristiques &#124;\u00a0WordPress","author":"Lyonel Kaufmann","date":"20 novembre 2008","format":false,"excerpt":"14-18: les photos de Life - Google Recherche d'images Une partie du fond photographiques du magasine Life est disponible sur Google Images. A titre d'exemple, les photographies relatives \u00e0 la Premi\u00e8re Guerre mondiale et parues dans le magasine. Vous pouvez faire une recherche par mots-cl\u00e9s, par d\u00e9cennie ou par photographe\u2026","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/4487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=4487"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/4487\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/9896"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=4487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=4487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=4487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}