{"id":90,"date":"2006-06-04T07:57:10","date_gmt":"2006-06-04T06:57:10","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/?p=154"},"modified":"2006-06-04T07:57:10","modified_gmt":"2006-06-04T06:57:10","slug":"cafe-pedagogique-liens-mai-2006","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2006\/06\/04\/cafe-pedagogique-liens-mai-2006\/","title":{"rendered":"Caf\u00e9 p\u00e9dagogique:: liens mai 2006"},"content":{"rendered":"<p>Le <strong><a href=\"http:\/\/www.cafepedagogique.net\">Caf\u00e9 p\u00e9dagogique<\/a><\/strong> propose tous les mois une s\u00e9lection de liens en rapport avec les diff\u00e9rentes disciplines scolaires.<br \/>\nVoici une partie des liens en rapport avec l\u2019histoire pr\u00e9sente dans son \u00e9dition du mois de mai.<br \/>\nAu sommaire :<\/p>\n<ol>\n<li>Le p\u00e9plum, utilisable en classe ?<\/li>\n<li>Cliophoto<\/li>\n<li>Historic Cities<\/li>\n<li>Le mythe d&rsquo;Osiris<\/li>\n<li>Affiche de propagande et hyperm\u00e9dia<\/li>\n<li>Congr\u00e8s : L&rsquo;image au Congr\u00e8s des soci\u00e9t\u00e9s historiques et scientifiques<\/li>\n<\/ol>\n<p><!-- technorati tags start --><\/p>\n<p style=\"text-align:right;font-size:10px;\">Technorati Tags: <a href=\"http:\/\/www.technorati.com\/tag\/histoire\" rel=\"tag\">histoire<\/a>, <a href=\"http:\/\/www.technorati.com\/tag\/Histoire&#038;M\u00e9dia\" rel=\"tag\">Histoire&#038;M\u00e9dia<\/a>, <a href=\"http:\/\/www.technorati.com\/tag\/Hyperm\u00e9dia\" rel=\"tag\">Hyperm\u00e9dia<\/a>, <a href=\"http:\/\/www.technorati.com\/tag\/Images&#038;Histoire\" rel=\"tag\">Images&#038;Histoire<\/a>, <a href=\"http:\/\/www.technorati.com\/tag\/MytheOsiris\" rel=\"tag\">MytheOsiris<\/a>, <a href=\"http:\/\/www.technorati.com\/tag\/P\u00e9plum\" rel=\"tag\">P\u00e9plum<\/a><\/p>\n<p><!-- technorati tags end --><br \/>\n<!--more--><br \/>\n<strong><em>&#8211; Le p\u00e9plum, utilisable en classe ?<\/em><\/strong><\/p>\n<p style=\"text-align:justify;\">\u201c Comment le cin\u00e9ma hollywoodien a-t-il m\u00eal\u00e9 avec plus ou moins de r\u00e9ussite le religieux et le politique ? Le p\u00e9plum est-il un outil utilisable en classe ? Faut-il \u00e9mettre des r\u00e9serves quant \u00e0 son usage ?\u201d Nicolas Smaghue ouvre le d\u00e9bat par une analyse fouill\u00e9e de quelques uns des innombrables p\u00e9plums cr\u00e9\u00e9s \u00e0 Hollywood. On pense bien s\u00fbr \u00e0 une utilisation en sixi\u00e8me pour l&rsquo;histoire gr\u00e9co \u2013 romaine, \u00e0 la seconde avec son chapitre sur le christianisme, mais N. Smaghue nous entra\u00eene plut\u00f4t vers la terminale o\u00f9 le p\u00e9plum peut nourrir une r\u00e9flexion sur la guerre froide et sur le lien entre cin\u00e9ma et politique. \u201c Dans le cin\u00e9ma am\u00e9ricain, la collusion entre politique et religion, la mystique du pouvoir et sa repr\u00e9sentation, nous surprennent toujours. Les p\u00e9plums plus actuels se revendiquent de plus en plus proches de la r\u00e9alit\u00e9 historique. Cette d\u00e9rive cin\u00e9matographique peut conduire, comme l&rsquo;exemple de Gladiator le prouve, \u00e0 de graves contresens historiques qui peuvent m\u00eame \u00eatre soup\u00e7onn\u00e9s de partis pris id\u00e9ologiques<\/p>\n<p><strong><a href=\"http:\/\/www4.ac-lille.fr\/~heg\/article.php3?id_article=182\">http:\/\/www4.ac-lille.fr\/~heg\/article.php3?id_article=182<\/a><\/strong><\/p>\n<p><strong><em>&#8211; Cliophoto<\/em><\/strong><\/p>\n<p style=\"text-align:justify;\">C&rsquo;est le dernier projet de l&rsquo;association des Clionautes : par la mutualisation, r\u00e9unir une vaste biblioth\u00e8que de photos utilisables librement dans le cadre des cours d&rsquo;histoire et g\u00e9ographie. Cliophoto est bien parti avec d\u00e9j\u00e0 plus de 500 images class\u00e9es et disponibles couvrant la g\u00e9ographie mais aussi l&rsquo;histoire.<\/p>\n<p><strong><a href=\"http:\/\/www.cliophoto.clionautes.org\/category.php?cat=434\">http:\/\/www.cliophoto.clionautes.org\/category.php?cat=434<\/a><\/strong><\/p>\n<p><strong><em>&#8211; Historic Cities<\/em><\/strong><\/p>\n<p style=\"text-align:justify;\">Le site Historic Cities offre une collection de cartes historiques unique. C&rsquo;est vraiment le lieu pour d\u00e9buter une recherche sur l&rsquo;histoire urbaine. Le Vieux Monde est mieux couvert que le Nouveau Monde. 16 cartes de villes suisses dont Berne, Gen\u00e8ve, Saint-Gall, Sion, Zurich, mais pas Lausanne.<\/p>\n<p><strong><a href=\"http:\/\/historic-cities.huji.ac.il\/historic_cities.html\">http:\/\/historic-cities.huji.ac.il\/historic_cities.html<\/a><\/strong><br \/>\n<em>Cartes de villes suisses :<\/em> <strong><a href=\"http:\/\/historic-cities.huji.ac.il\/central_europe\/central_europe.html\">http:\/\/historic-cities.huji.ac.il\/central_europe\/central_europe.html<\/a><\/strong><\/p>\n<p><strong><em>&#8211; Le mythe d&rsquo;Osiris<\/em><\/strong><\/p>\n<p style=\"text-align:justify;\">Comment en 4 ou 5 heures faire comprendre les grands piliers de la civilisation \u00e9gyptienne ? La revue acad\u00e9mique de Lille,\u00a0 Le Beffroi, propose des pistes : webographie mais aussi r\u00e9flexion sur l&rsquo;utilisation des documents patrimoniaux. Cette s\u00e9quence permet d&rsquo;articuler l&rsquo;utilisation d&rsquo;un mythe dans un cours d&rsquo;histoire<strong><br \/>\n<\/strong><\/p>\n<p><strong><a href=\"http:\/\/www4.ac-lille.fr\/~heg\/article.php3?id_article=196\">http:\/\/www4.ac-lille.fr\/~heg\/article.php3?id_article=196<\/a><\/strong><br \/>\n<strong><a href=\"http:\/\/www4.ac-lille.fr\/~heg\/article.php3?id_article=198\">http:\/\/www4.ac-lille.fr\/~heg\/article.php3?id_article=198<\/a><\/strong><\/p>\n<p><strong><em>&#8211; Affiche de propagande et hyperm\u00e9dia<\/em><\/strong><\/p>\n<p style=\"text-align:justify;\"><em>Vichy : La Maison France (affiche de propagande de la R\u00e9volution nationale)<br \/>\n<\/em><br \/>\nA la fois une analyse (partielle) d&rsquo;une affiche de propagande et \u00e0 la fois un exemple d&rsquo;utilisation et de cr\u00e9ation d&rsquo;un hyperm\u00e9dia (PowerPoint, OpenOffice, doc. html). Par ailleurs, des pistes documentaires sont fournies au professeur. Niveau : lyc\u00e9e fran\u00e7ais.<\/p>\n<p style=\"text-align:justify;\"><em>Mat\u00e9riel n\u00e9cessaire : <\/em>L&rsquo;affiche de propagande de R. Vachet, produite par le Centre de propagande de la R\u00e9volution Nationale d&rsquo;Avignon. (date pr\u00e9cise incertaine, entre 1940 et 1942, dimension : 59 cm x 80cm ). Des documents pour pr\u00e9parer la s\u00e9quence. Utiliser le vid\u00e9o-projecteur pour \u00e9tudier une affiche.<br \/>\n<em>Probl\u00e9matiques : <\/em>situer une affiche politique dans son contexte et l&rsquo;\u00e9tudier . La pr\u00e9senter dans l&rsquo;\u00e9volution de l&rsquo;histoire enseign\u00e9e de la p\u00e9riode.<br \/>\n<em>La d\u00e9marche mise en oeuvre :<\/em> moment de travail en classe d&rsquo;une heure en Premi\u00e8res ES. Les \u00e9l\u00e8ves ont le document dans leur manuel, une photocopie NB est le support de la prise de notes.<em><br \/>\nLes pr\u00e9-requis du professeur utilisateur :<\/em> savoir construire un hypermedia simple utilisant les zones sensibles d&rsquo;une image en utilisant un \u00e9diteur ou le module Document Html de OpenOffice.<\/p>\n<p><strong><a href=\"http:\/\/www.ac-nantes.fr:8080\/peda\/disc\/histgeo\/pedago\/vichy\/index.htm\">http:\/\/www.ac-nantes.fr:8080\/peda\/disc\/histgeo\/pedago\/vichy\/index.htm<\/a><\/strong><\/p>\n<p><strong><em>&#8211; Congr\u00e8s : L&rsquo;image au Congr\u00e8s des soci\u00e9t\u00e9s historiques et scientifiques<\/em><\/strong><\/p>\n<p style=\"text-align:justify;\">Du 16 au 23 avril 2007, Arles accueillera le 132\u00e8me congr\u00e8s national des soci\u00e9t\u00e9s historiques et scientifiques autour du th\u00e8me \u201dimages et imagerie\u201c. Le programme est maintenant disponible. Notons parmi les th\u00e8mes retenus : images et textes, le d\u00e9tournement d&rsquo;images, l&rsquo;imagerie populaire, les genres de la photographie, les technologies nouvelles d&rsquo;imagerie.<\/p>\n<p><strong><a href=\"http:\/\/www.cths.fr\/CONGRES\/co_acc.shtm\">http:\/\/www.cths.fr\/CONGRES\/co_acc.shtm<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Caf\u00e9 p\u00e9dagogique propose tous les mois une s\u00e9lection de liens en rapport avec les diff\u00e9rentes disciplines scolaires. Voici une partie des liens en rapport avec l\u2019histoire pr\u00e9sente dans son \u00e9dition du mois de mai. Au sommaire : Le p\u00e9plum, utilisable en classe ? Cliophoto Historic Cities Le mythe d&rsquo;Osiris Affiche de propagande et hyperm\u00e9dia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[18,8,11],"tags":[],"class_list":{"0":"post-90","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-annuaire-de-sites","8":"category-medias-et-technologies","9":"category-nouvelles-de-lhistoire","10":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?fit=658%2C184&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-1s","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":4423,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/06\/24\/le-manuel-dhistoire-franco-allemand-un-echec\/","url_meta":{"origin":90,"position":0},"title":"Comment expliquer, au moment de la parution du troisi\u00e8me volume du manuel d&#8217;histoire franco-allemand couvrant l&#8217;Antiquit\u00e9 \u00e0 la chute de Napol\u00e9on, le peu d&#8217;\u00e9cho rencontr\u00e9 par ces manuels aupr\u00e8s des enseignants&#160;? Est-ce seulement, comme l\u2019indique le journal Le Monde un symbole de l\u2019\u00e9volution des rapports franco-allemands&#160;?\nVous en saurez plus en lisant ma chronique du Caf\u00e9 p\u00e9dagogique dans le mensuel du mois de mai 2011.","author":"Lyonel Kaufmann","date":"24 juin 2011","format":"link","excerpt":"Le manuel d\u2019histoire franco-allemand : un \u00e9chec ? |\u00a0Caf\u00e9 p\u00e9dagogique","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":7824,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2014\/01\/29\/la-culture-du-passe-le-debat-et-lhistoire-en-classe-chronique-no-148\/","url_meta":{"origin":90,"position":1},"title":"\u00abLa culture du pass\u00e9\u00bb (Le D\u00e9bat) et l\u2019histoire en classe &#124;\u00a0Chronique no 148","author":"Lyonel Kaufmann","date":"29 janvier 2014","format":false,"excerpt":"Dans sa derni\u00e8re livraison, la revue \u00abLe D\u00e9bat\u00bb [1] s\u2019int\u00e9resse \u00e0 \u00abLa culture du pass\u00e9\u00bb et notamment aux usages m\u00e9diatiques de l\u2019histoire. Il ne manquera pas d\u2019int\u00e9resser les enseignants concernant le savoir historique m\u00e9diatis\u00e9 auquel leurs \u00e9l\u00e8ves ont acc\u00e8s et plus largement l\u2019enseignement de l\u2019histoire qu\u2019il convient de dispenser \u00e0\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":11783,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/08\/15\/apprendre-avec-les-serious-games-en-classe-dhistoire-publication-et-jeux\/","url_meta":{"origin":90,"position":2},"title":"Faire le point : Apprendre avec les serious games en classe d&rsquo;histoire ?","author":"Lyonel Kaufmann","date":"15 ao\u00fbt 2016","format":false,"excerpt":"Les jeux s\u00e9rieux ont-ils leur place dans la classe ? Et si oui \u00e0 quelles conditions et pour quoi faire ? Le petit livre de Julian Alvarez, Damien Djaouti et Olivier Rampnoux, vous dit tout, ou presque, sur les jeux s\u00e9rieux. C'est \u00e0 dire qu'il parle des apports mais aussi\u2026","rel":"","context":"Dans &quot;Histoire active&quot;","block_context":{"text":"Histoire active","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-active\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/08\/Image-15.08.16-13-51.jpeg?fit=350%2C491&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1460,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2009\/08\/07\/lectures-dete-preparer-sa-rentree-3\/","url_meta":{"origin":90,"position":3},"title":"Lectures d&#039;\u00e9t\u00e9: Pr\u00e9parer sa rentr\u00e9e (3)","author":"Lyonel Kaufmann","date":"7 ao\u00fbt 2009","format":false,"excerpt":"5 habilet\u00e9s pour bien g\u00e9rer une \u00e9quipe, virtuellement Certes une part importante du billet de Ze Cool figure dans le titre et, \u00e0 partir de l\u00e0, vous allez directement vous pr\u00e9cipitez pour lire l'ensemble de ce billet et vous aurez bien raison. N\u00e9anmoins je souligne et j'appuie les \u00e9l\u00e9ments de\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":49,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2006\/03\/29\/cafe-pedagogique-liens-mars-2006\/","url_meta":{"origin":90,"position":4},"title":"Caf\u00e9 p\u00e9dagogique:: liens mars 2006","author":"Lyonel Kaufmann","date":"29 mars 2006","format":false,"excerpt":"Le Caf\u00e9 p\u00e9dagogique propose tous les mois une s\u00e9lection de liens en rapport avec les diff\u00e9rentes disciplines scolaires. Voici une partie des liens en rapport avec l\u2019histoire pr\u00e9sente dans son \u00e9dition du mois de mars. - A la Une : Les femmes et l'histoire Quelle est la place des femmes\u2026","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4548,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/04\/30\/le-piege-du-numerique-cafe-pedagogique\/","url_meta":{"origin":90,"position":5},"title":"\u00abL\u2019urgent n\u2019est pas de former les enseignants aux nouvelles technologies, il est d\u2019abord de les former \u00e0 la p\u00e9dagogie.\u00bb Pour Pierre Frackowiak le num\u00e9rique ne r\u00e9soudra la crise de l&#8217;Ecole que s&#8217;il&#8230;","author":"Lyonel Kaufmann","date":"30 avril 2010","format":"link","excerpt":"Le pi\u00e8ge du num\u00e9rique |\u00a0Caf\u00e9 p\u00e9dagogique","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/90","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=90"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/90\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/9896"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=90"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=90"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=90"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}