{"id":9613,"date":"2015-04-03T16:14:54","date_gmt":"2015-04-03T15:14:54","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/?p=9613"},"modified":"2015-04-03T16:14:54","modified_gmt":"2015-04-03T15:14:54","slug":"revue-presse-lordinateur-detrone-par-la-tablette-chez-les-7-12-ans-et-concurrence-par-le-smartphone-chez-les-ados-graphique","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2015\/04\/03\/revue-presse-lordinateur-detrone-par-la-tablette-chez-les-7-12-ans-et-concurrence-par-le-smartphone-chez-les-ados-graphique\/","title":{"rendered":"Revue Presse : L&rsquo;ordinateur d\u00e9tr\u00f4n\u00e9 par la tablette chez les 7-12 ans et concurrenc\u00e9 par le smartphone chez les ados | Graphique"},"content":{"rendered":"<p><strong>[France]. La p\u00e9n\u00e9tration des tablettes dans les foyers avec enfants est devenue majoritaire : 62% versus 46% en 2013 et 22% en 2012. 29% des enfants de 1-6 ans sont \u00e9quip\u00e9s de tablettes pour enfants.<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.journaldunet.com\/ebusiness\/le-net\/usages-tablettes-et-smartphones.shtml\"><img data-recalc-dims=\"1\" src=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/04\/2568024-l-ordinateur-detrone-par-la-tablette-chez-les-7-12-ans-et-concurrence-par-le-smartphone-chez-les-ados.png\" alt='' \/><\/a><\/p>\n<p>Source :\u00a0<a href=\"http:\/\/www.journaldunet.com\/ebusiness\/le-net\/usages-tablettes-et-smartphones.shtml\">L&rsquo;ordinateur d\u00e9tr\u00f4n\u00e9 par la tablette chez les 7-12 ans et concurrenc\u00e9 par le smartphone chez les ados &#8211; JDN<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[France]. La p\u00e9n\u00e9tration des tablettes dans les foyers avec enfants est devenue majoritaire : 62% versus 46% en 2013 et 22% en 2012. 29% des enfants de 1-6 ans sont \u00e9quip\u00e9s de tablettes pour enfants. Source :\u00a0L&rsquo;ordinateur d\u00e9tr\u00f4n\u00e9 par la tablette chez les 7-12 ans et concurrenc\u00e9 par le smartphone chez les ados &#8211; JDN.<\/p>\n","protected":false},"author":1,"featured_media":9618,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8,17],"tags":[],"class_list":{"0":"post-9613","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-medias-et-technologies","8":"category-sur-le-web","9":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/04\/2568024-l-ordinateur-detrone-par-la-tablette-chez-les-7-12-ans-et-concurrence-par-le-smartphone-chez-les-ados.png?resize=595%2C400&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/04\/2568024-l-ordinateur-detrone-par-la-tablette-chez-les-7-12-ans-et-concurrence-par-le-smartphone-chez-les-ados.png?resize=595%2C446&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/04\/2568024-l-ordinateur-detrone-par-la-tablette-chez-les-7-12-ans-et-concurrence-par-le-smartphone-chez-les-ados.png?fit=595%2C446&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-2v3","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":4066,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/09\/06\/rentree-scolaire-2011-twitter-tablettes-et-smartphones\/","url_meta":{"origin":9613,"position":0},"title":"Rentr\u00e9e scolaire 2011 : twitter, tablettes et smartphones","author":"Lyonel Kaufmann","date":"6 septembre 2011","format":false,"excerpt":"Twitter, les tablettes et les smartphones sont en t\u00eate des pr\u00e9occupations ou des tendances num\u00e9riques de la rentr\u00e9e scolaire 2011. Ces quelques articles vous permettront de faire un premier tour de la question \"Ma\u00eetresse, quand est-ce qu'on tweete ?\" | LeMonde.fr Reportage sur des enseignants du primaire et du secondaire\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":11534,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/06\/01\/patrimoine-jeu-video-mystere-dans-ma-ville-limoges-sur-tablette-et-smartphone\/","url_meta":{"origin":9613,"position":1},"title":"Patrimoine : jeu vid\u00e9o \u00ab&nbsp;Myst\u00e8re dans ma ville Limoges&nbsp;\u00bb sur tablette et smartphone.","author":"Lyonel Kaufmann","date":"1 juin 2016","format":false,"excerpt":"Myst\u00e8re dans ma ville Limoges est un jeu vid\u00e9o grand public disponible gratuitement sur tablette, smartphones et sur les sites internet de la Ville de Limoges et de l\u2019Office de tourisme. L\u2019objectif du jeu est de d\u00e9couvrir le patrimoine et le territoire de la ville depuis son domicile. Lanc\u00e9 en\u2026","rel":"","context":"Dans &quot;Histoire active&quot;","block_context":{"text":"Histoire active","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-active\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/06\/Image-01.06.16-12-02-1.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/06\/Image-01.06.16-12-02-1.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/06\/Image-01.06.16-12-02-1.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/06\/Image-01.06.16-12-02-1.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/06\/Image-01.06.16-12-02-1.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4478,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/12\/20\/les-memes-qui-disent-que-lon-peut-apprendre-sans\/","url_meta":{"origin":9613,"position":2},"title":"Tablette&#160;: passif&#160;! Ordinateur&#160;: interactif&#160;? \u00ab&#160;Veille et Analyse TICE","author":"Lyonel Kaufmann","date":"20 d\u00e9cembre 2010","format":"quote","excerpt":"Les m\u00eames qui disent que l\u2019on peut apprendre sans agir (en \u00e9coutant et en m\u00e9morisant) d\u00e9plorent l\u2019effet des m\u00e9dias de masse sur les enfants, sorte de paradoxe \u00e9tonnant.","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":11759,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/07\/27\/gens-de-la-seine-une-balade-sonore-dans-le-paris-du-18e-siecle\/","url_meta":{"origin":9613,"position":3},"title":"\u00ab Gens de la Seine \u00bb : une balade sonore dans le Paris du 18e si\u00e8cle","author":"Lyonel Kaufmann","date":"27 juillet 2016","format":false,"excerpt":"Con\u00e7ue par des chercheurs du CNRS, \"Gens de la Seine\" est une balade sonore \u00e0 travers le Paris du 18e si\u00e8cle. Un audioguide 2.0 qui permet de voyager \u00e0 travers le temps. Jean-Auguste Gagnery. \u00ab Le port Saint-Nicolas \u00bb. Huile sur toile, 1834. Paris, mus\u00e9e Carnavalet. Des chercheurs du\u00a0CNRS vous\u2026","rel":"","context":"Dans &quot;Histoire active&quot;","block_context":{"text":"Histoire active","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-active\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/07\/img_1345-2.jpg?fit=768%2C537&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/07\/img_1345-2.jpg?fit=768%2C537&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/07\/img_1345-2.jpg?fit=768%2C537&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/07\/img_1345-2.jpg?fit=768%2C537&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":7432,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2013\/09\/01\/mon-bilan-de-ludovia2013\/","url_meta":{"origin":9613,"position":4},"title":"Mon bilan de #Ludovia2013","author":"Lyonel Kaufmann","date":"1 septembre 2013","format":false,"excerpt":"Ma deuxi\u00e8me participation en 2013 \u00e0 Ax-les-Thermes apr\u00e8s 2010 me permet de porter un regard comparatif sur ces deux \u00e9ditions. Au moment de faire le bilan, Eric Fourcaud indiquait 700 participants \u00e0 Ax-les-Thermes et un nombre comparable en ligne. A ce rythme, la participation online pourrait \u00eatre sup\u00e9rieure \u00e0 celle\u2026","rel":"","context":"Dans &quot;Ludovia&quot;","block_context":{"text":"Ludovia","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/ludovia-2010\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/20130901-101444.jpg?fit=600%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/20130901-101444.jpg?fit=600%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/20130901-101444.jpg?fit=600%2C800&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":6118,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2012\/08\/31\/ludovia2012-tablettes-en-classe-un-outil-a-integrer\/","url_meta":{"origin":9613,"position":5},"title":"#Ludovia2012 : Tablettes en classe : un outil \u00e0 int\u00e9grer","author":"Lyonel Kaufmann","date":"31 ao\u00fbt 2012","format":false,"excerpt":"A Ludovia,\u00a0Carole Lopez, enseignante en maternelle, a pr\u00e9sent\u00e9 un exemple tr\u00e8s convaincant d'utilisation d'une tablette num\u00e9rique en classe. Carole Lopez n'utilise pas la tablette pour la tablette, mais pour sa plus-value dans certaines activit\u00e9s d'apprentissage. Elle l'emploie \u00e9galement en compl\u00e9ment \u00e0 d'autres techniques et activit\u00e9s. La vid\u00e9o nous pr\u00e9sente une\u2026","rel":"","context":"Dans &quot;Ludovia&quot;","block_context":{"text":"Ludovia","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/ludovia-2010\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/019.jpg?fit=480%2C360&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/9613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=9613"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/9613\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/9618"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=9613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=9613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=9613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}