{"id":9633,"date":"2015-04-05T01:46:28","date_gmt":"2015-04-05T00:46:28","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/?p=9633"},"modified":"2015-04-05T01:46:28","modified_gmt":"2015-04-05T00:46:28","slug":"revue-de-presse-comment-ecrire-la-biographie-dun-poilu","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2015\/04\/05\/revue-de-presse-comment-ecrire-la-biographie-dun-poilu\/","title":{"rendered":"Revue de Presse Comment \u00e9crire la biographie d&rsquo;un poilu?"},"content":{"rendered":"<p><strong>Ce billet de blog ne s\u2019adresse pas aux enseignants souhaitant effectuer un travail de r\u00e9daction avec les \u00e9l\u00e8ves relativement \u00e0 l\u2019\u00e9criture de la vie d\u2019un poilu, mais il offre une synth\u00e8se notamment sur les diff\u00e9rentes sources \u00e0 dispositions pour le faire ainsi que des conseils de r\u00e9daction qui pourront \u00eatre adapt\u00e9s \u00e0 une d\u00e9marche p\u00e9dagogique.\u00a0<\/strong><\/p>\n<p><a href=\"http:\/\/www.helenesoula.fr\/ecrire-biographie-ancetre-poilu-guerre\/\">Comment \u00e9crire la biographie d&rsquo;un poilu? &gt; Ecrire l&rsquo;histoire de votre vie ou de votre famille<\/a>:<\/p>\n<blockquote><p>\nVous voulez <strong>\u00e9crire la biographie d\u2019un anc\u00eatre ayant particip\u00e9 \u00e0 la Grande Guerre de 14-18\u00a0<\/strong>?<\/p>\n<p>Quelles sont les <strong>sources<\/strong> disponibles pour <strong>retracer le parcours d\u2019un poilu<\/strong> et en savoir plus sur ce qu\u2019il a v\u00e9cu ?<\/p>\n<p>Quels sont les <strong>pr\u00e9cautions<\/strong> \u00e0 prendre, les <strong>\u00e9cueils<\/strong> \u00e0 \u00e9viter ?<\/p>\n<div id=\"attachment_914\" class=\"wp-caption aligncenter\" style=\"width: 474px;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"  wp-image-914\" src=\"https:\/\/i0.wp.com\/www.helenesoula.fr\/wp-content\/uploads\/2015\/03\/tranchee-poilus-14-18-300x199.jpg?resize=464%2C314\" alt=\"Soldats dans une tranch\u00e9e (dont un jouant du violon).\" width=\"464\" height=\"314\" \/><\/p>\n<p class=\"wp-caption-text\"><span style=\"font-size: 10pt;\"><a href=\"http:\/\/www.europeana1914-1918.eu\/fr\/contributions\/10329#prettyPhoto\">Soldats (dont un violoniste) dans une tranch\u00e9e.<\/a><\/span><\/p>\n<\/div>\n<p style=\"text-align: center;\">\u00a0<\/p>\n<p><strong>\u00ab 14-18 : \u00e9crire la biographie d\u2019une anc\u00eatre soldat\u00a0\u00bb<\/strong> \u00e9tait le sujet d\u2019une rencontre organis\u00e9e par l\u2019<a href=\"http:\/\/ecrivains-publics.fr\/spip.php?page=sommaire\">Acad\u00e9mie des \u00e9crivains publics de France,<\/a> ce samedi \u00e0 Paris. O\u00f9 l\u2019on a pu entendre avec grand int\u00e9r\u00eat\u00a0:<\/p>\n<ul>\n<li>les pistes de recherche de l\u2019\u00e9crivain public-biographe Sylvie Monteillet ;<\/li>\n<li>la mise en perspective de l\u2019historien Alexandre Lafon\u00a0;<\/li>\n<li>le t\u00e9moignage d\u2019un descendant ayant d\u00e9couvert la biographie de son grand-p\u00e8re ancien poilu.<\/li>\n<\/ul>\n<\/blockquote>\n<p>Lire la suite :\u00a0<a href=\"http:\/\/www.helenesoula.fr\">www.helenesoula.fr<\/a>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce billet de blog ne s\u2019adresse pas aux enseignants souhaitant effectuer un travail de r\u00e9daction avec les \u00e9l\u00e8ves relativement \u00e0 l\u2019\u00e9criture de la vie d\u2019un poilu, mais il offre une synth\u00e8se notamment sur les diff\u00e9rentes sources \u00e0 dispositions pour le faire ainsi que des conseils de r\u00e9daction qui pourront \u00eatre adapt\u00e9s \u00e0 une d\u00e9marche p\u00e9dagogique.\u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9910,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11,15,17],"tags":[],"class_list":{"0":"post-9633","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nouvelles-de-lhistoire","8":"category-outils-enseignement","9":"category-sur-le-web","10":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/tranchee-poilus-14-18-300x199.jpg?resize=300%2C199&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/tranchee-poilus-14-18-300x199.jpg?resize=300%2C199&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/tranchee-poilus-14-18-300x199.jpg?fit=300%2C199&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-2vn","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":282,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2008\/02\/06\/links-for-2008-02-06\/","url_meta":{"origin":9633,"position":0},"title":"Lazare Ponticelli, le dernier poilu (t\u00e9moignage)","author":"Lyonel Kaufmann","date":"6 f\u00e9vrier 2008","format":false,"excerpt":"Lib\u00e9ration Lib\u00e9Labo \u00bb Lazare Ponticelli, le dernier poilu D\u00e9sormais, Lazare Ponticelli est le dernier poilu en vie. Voici son t\u00e9moignage de 2005 pour Lib\u00e9, sous-titr\u00e9 pour plus de clart\u00e9, et mis en images avec le concours du service documentaire des arm\u00e9es en quatre \u00e9pisodes. (tags: Histoire 14-18 DernierPoilu Poilus T\u00e9moignage\u2026","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3743,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/05\/05\/premiere-guerre-mondiale-mort-du-dernier-poilu-tsrinfo-ch-2\/","url_meta":{"origin":9633,"position":1},"title":"Premi\u00e8re Guerre mondiale: mort du dernier &quot;poilu&quot; &#124; tsrinfo.ch","author":"Lyonel Kaufmann","date":"5 mai 2011","format":false,"excerpt":"Claude Choules \u00e9tait le dernier ancien combattant survivant de la Grande Guerre dans le monde, apr\u00e8s le d\u00e9c\u00e8s fin f\u00e9vrier \u00e0 110 ans de Franck Buckles, dernier v\u00e9t\u00e9ran am\u00e9ricain de la Premi\u00e8re Guerre mondiale, qui avait lui aussi menti sur son \u00e2ge pour pouvoir s'enr\u00f4ler en 1917. Le v\u00e9t\u00e9ran britannique\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/Claude_Choules.jpg?fit=480%2C270&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6903,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2013\/04\/09\/scenario-pedagogique-et-si-la-renaissance-avait-connu-twitter-ma-onzieme-annee-et-les-suivantes\/","url_meta":{"origin":9633,"position":2},"title":"Sc\u00e9nario p\u00e9dagogique: \u00ab\u00a0et si la Renaissance avait connu Twitter? \u00bb\u00a0 &#124; Ma onzi\u00e8me ann\u00e9e et les suivantes&#8230;","author":"Lyonel Kaufmann","date":"9 avril 2013","format":false,"excerpt":"Laurence Juin nous propose une nouvelle activit\u00e9 p\u00e9dagogique recourant aux technologies. Celle-ci a pour cadre l'\u00e9tude de la renaissance en lyc\u00e9e professionnel. Elle a \u00e9t\u00e9 r\u00e9alis\u00e9e en 4heures. Les disciplines convoqu\u00e9es sont l'histoire et le fran\u00e7ais. Comme elle l'indique elle-m\u00eame : Dans ce sc\u00e9nario, les activit\u00e9s demand\u00e9es aux \u00e9l\u00e8ves et\u2026","rel":"","context":"Dans &quot;Didactique&quot;","block_context":{"text":"Didactique","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/r9.png?fit=520%2C256&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":302,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2008\/03\/19\/links-for-2008-03-19\/","url_meta":{"origin":9633,"position":3},"title":"Dernier poilu (hommage) &#124; Grande d\u00e9pression : le retour? (liens)","author":"Lyonel Kaufmann","date":"19 mars 2008","format":false,"excerpt":"Hommage au dernier poilu: \u00abDe l\u2019\u00e9motion, oui, mais pas de sensiblerie\u00bb - 20Minutes.fr, information en continu. D\u00e9cryptage de la c\u00e9r\u00e9monie officielle en hommage \u00e0 Lazare Ponticelli, dernier poilu d\u00e9c\u00e9d\u00e9. (tags: Histoire 14-18 DernierPoilu NicolasSarkozy LazarePonticelli Comm\u00e9moration) La pens\u00e9e paralys\u00e9e (Dedefensa.org) Le vocabulaire et la psychologie de la Grande D\u00e9pression (Crise\u2026","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6926,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2013\/04\/12\/leon-vivien-la-vie-dun-poilu-sur-facebook\/","url_meta":{"origin":9633,"position":4},"title":"L\u00e9on Vivien : la vie d&#039;un poilu sur Facebook","author":"Lyonel Kaufmann","date":"12 avril 2013","format":false,"excerpt":"11 avril 1915 \u00abTu parles d'une arm\u00e9e : il n'y a pas deux types qui ont le m\u00eame uniforme. Avec le froid qu'il fait en ce moment, les gars se couvrent avec tout ce qu'ils trouvent. On dirait une troupe de chiffonniers... Le plus beau de tous, avec ses fourrures\u2026","rel":"","context":"Dans &quot;Histoire active&quot;","block_context":{"text":"Histoire active","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-active\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2013\/04\/486101_151097898383375_278849699_n.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4438,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2011\/05\/05\/premiere-guerre-mondiale-mort-du-dernier-poilu\/","url_meta":{"origin":9633,"position":5},"title":"Claude Choules \u00e9tait le dernier ancien combattant survivant de la Grande Guerre dans le monde, apr\u00e8s le d\u00e9c\u00e8s fin f\u00e9vrier \u00e0 110 ans de Franck Buckles, dernier v\u00e9t\u00e9ran am\u00e9ricain de la Premi\u00e8re Guerre mondiale, qui avait lui aussi menti sur son \u00e2ge pour pouvoir s&#8217;enr\u00f4ler en 1917.\nLe v\u00e9t\u00e9ran britannique Henry Allingham, qui \u00e9tait aussi doyen de l&#8217;humanit\u00e9, est d\u00e9c\u00e9d\u00e9 en 2009 \u00e0 113 ans. Le dernier soldat allemand, Erich K\u00e4stner, est d\u00e9c\u00e9d\u00e9 le 1er janvier 2008 \u00e0 l&#8217;\u00e2ge de 107 ans. Le dernier combattant fran\u00e7ais, Lazare Ponticelli, est mort le 12 mars 2008 \u00e0 110 ans. Delfino Borroni, dernier survivant italien, est d\u00e9c\u00e9d\u00e9 le 26 octobre 2008 \u00e0 110 ans.","author":"Lyonel Kaufmann","date":"5 mai 2011","format":"link","excerpt":"Premi\u00e8re Guerre mondiale: mort du dernier \"poilu\" | tsrinfo.ch","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/9633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=9633"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/9633\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/9910"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=9633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=9633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=9633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}