{"id":9636,"date":"2015-04-05T13:52:07","date_gmt":"2015-04-05T12:52:07","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/?p=9636"},"modified":"2015-04-05T13:52:40","modified_gmt":"2015-04-05T12:52:40","slug":"utiliser-des-ressources-numeriques-pour-enseigner-la-premiere-guerre-mondiale-vousnousils","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2015\/04\/05\/utiliser-des-ressources-numeriques-pour-enseigner-la-premiere-guerre-mondiale-vousnousils\/","title":{"rendered":"Utiliser des ressources num\u00e9riques pour enseigner la Premi\u00e8re Guerre mondiale | VousNousIls"},"content":{"rendered":"<p><a href=\"http:\/\/www.vousnousils.fr\/2015\/04\/02\/utiliser-des-ressources-numeriques-pour-enseigner-la-premiere-guerre-mondiale-566344\">Utiliser des ressources num\u00e9riques pour enseigner la Premi\u00e8re Guerre mondiale \u00bb VousNousIls<\/a>:<\/p>\n<blockquote>\n<p class=\"subtitle\">Pour traiter de la guerre 14-18, des professeurs de l&rsquo;acad\u00e9mie de Lille proposent d&rsquo;utiliser les ressources num\u00e9riques des Archives nationales australiennes, afin d&rsquo;incarner un soldat et de \u00ab\u00a0donner du sens aux apprentissages\u00a0\u00bb.<\/p>\n<div id=\"attachment_566349\" class=\"wp-caption alignleft\" style=\"width: 310px;\"><a href=\"https:\/\/i0.wp.com\/www.vousnousils.fr\/wp-content\/uploads\/2015\/04\/E00193.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-566349\" src=\"https:\/\/i0.wp.com\/www.vousnousils.fr\/wp-content\/uploads\/2015\/04\/E00193-300x218.jpg?resize=300%2C218\" alt=\"La tombe du capitaine Ivor Stephen Margetts, sur le champ de bataille de Pozieres, dans la Somme, en 1916.\" width=\"300\" height=\"218\" \/><\/a><\/p>\n<p class=\"wp-caption-text\">La tombe du capitaine Ivor Stephen Margetts, sur le champ de bataille de Pozieres, dans la Somme, en 1916.<\/p>\n<\/div>\n<p>Pour enseigner\u00a0la <strong>Grande Guerre<\/strong>, quatre professeurs d\u2019histoire-g\u00e9ographie de l\u2019acad\u00e9mie de Lille proposent de passer par le \u00ab\u00a0prisme australien\u00a0\u00bb, en utilisant les ressources <strong>num\u00e9riques<\/strong>\u00a0des\u00a0<a href=\"http:\/\/www.naa.gov.au\/\">Archives nationales australiennes<\/a>\u00a0(NAA).<\/p>\n<p>\u00ab\u00a0Les documents num\u00e9ris\u00e9s y sont tr\u00e8s riches et tr\u00e8s divers. Parmi eux, se trouvent notamment les<strong> dossiers militaires<\/strong> des combattants. Selon l\u2019itin\u00e9raire et les diff\u00e9rents \u00e9v\u00e9nements rencontr\u00e9s par chaque soldat, les dossiers sont plus ou moins fournis\u00a0\u00bb, \u00e9crivent les enseignants sur le <a href=\"http:\/\/histgeo.discipline.ac-lille.fr\/college\/travaux-du-groupe-college\/travaux-du-groupe-college-2013-2014\/prisme-australie\/utiliser-des-ressources-numeriques-pour-enseigner-la-premiere-guerre-mondiale\">site de leur acad\u00e9mie<\/a>.<\/p>\n<p id=\"parent-fieldname-description\">Le <strong>sc\u00e9nario p\u00e9dagogique<\/strong>\u00a0(relay\u00e9 par <a href=\"http:\/\/eduscol.education.fr\/bd\/urtic\/histgeo\/index.php?commande=aper&amp;id=10005335\">Eduscol<\/a>) que proposent les professeurs couvre les <strong>programmes\u00a0<\/strong>de <strong>troisi\u00e8me<\/strong> (l\u2019\u00e9tude du monde depuis 1914) et de <strong>premi\u00e8re<\/strong>.<\/p>\n<p>Les ressources\u00a0des NAA peuvent \u00eatre des <a href=\"http:\/\/recordsearch.naa.gov.au\/SearchNRetrieve\/Interface\/DetailsReports\/ItemDetail.aspx?Barcode=11559947&amp;isAv=N\">feuillets administratifs<\/a>, ou des <a href=\"http:\/\/recordsearch.naa.gov.au\/SearchNRetrieve\/Gallery151\/dist\/JGalleryViewer.aspx?B=11559947&amp;S=1&amp;N=67#\/SearchNRetrieve\/NAAMedia\/ShowImage.aspx?B=11559947&amp;T=P&amp;S=13\">lettres<\/a>, qui permettent \u00ab\u00a0d\u2019obtenir des informations sur l\u2019\u00e9tat-civil, l\u2019engagement, les embarquements et d\u00e9barquements, les combats ou les blessures et maladies des soldats.\u00a0\u00bb\n<\/p><\/blockquote>\n<p>Lire la suite :\u00a0<a href=\"http:\/\/www.vousnousils.fr\">www.vousnousils.fr<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Utiliser des ressources num\u00e9riques pour enseigner la Premi\u00e8re Guerre mondiale \u00bb VousNousIls: Pour traiter de la guerre 14-18, des professeurs de l&rsquo;acad\u00e9mie de Lille proposent d&rsquo;utiliser les ressources num\u00e9riques des Archives nationales australiennes, afin d&rsquo;incarner un soldat et de \u00ab\u00a0donner du sens aux apprentissages\u00a0\u00bb. La tombe du capitaine Ivor Stephen Margetts, sur le champ de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,8,11,15,17],"tags":[],"class_list":{"0":"post-9636","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-histoire-active","8":"category-medias-et-technologies","9":"category-nouvelles-de-lhistoire","10":"category-outils-enseignement","11":"category-sur-le-web","12":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?resize=600%2C184&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/signature_lk2.jpg?fit=658%2C184&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-2vq","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":3261,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/10\/14\/developpement-des-usages-des-ressources-numeriques-en-classe-ce-qui-coince\/","url_meta":{"origin":9636,"position":0},"title":"D\u00e9veloppement des usages des ressources num\u00e9riques en classe : ce qui coince &#8230;","author":"Lyonel Kaufmann","date":"14 octobre 2010","format":false,"excerpt":"Cet excellent article de synth\u00e8se du magazine \u00e9ducatif Ludovia est consacr\u00e9 \u00e0 l'usage des ressources num\u00e9riques en classe. Ainsi, si les offres des \u00e9diteurs de ressources et manuels num\u00e9riques foisonnent et que les Conseils g\u00e9n\u00e9raux et les \u00e9tablissements les ach\u00e8tent, leurs usages ne vont tr\u00e8s souvent pas de pair avec\u2026","rel":"","context":"Dans &quot;Ludovia&quot;","block_context":{"text":"Ludovia","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/ludovia-2010\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":11398,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/04\/24\/colloque-premiere-guerre-mondiale-et-enseignement\/","url_meta":{"origin":9636,"position":1},"title":"Colloque : Premi\u00e8re guerre mondiale et enseignement (27-29 avril 2016)","author":"Lyonel Kaufmann","date":"24 avril 2016","format":false,"excerpt":"Cette semaine, du mercredi 27 au vendredi 28 avril, j'ai le grand plaisir et le grand honneur de participer au colloque \u00abPremi\u00e8re guerre mondiale et enseignement\u00bb, organis\u00e9 au et par le Lyc\u00e9e professionnel Fran\u00e7ois Mansart \u00e0 Thizy-les-Bourgs (France). Ce colloque a re\u00e7u le label \u00abMission centenaire\u00bb. Concernant ce colloque, celui-ci\u2026","rel":"","context":"Dans &quot;Didactique&quot;","block_context":{"text":"Didactique","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6825,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2013\/02\/22\/enseigner-la-litteratie-historique\/","url_meta":{"origin":9636,"position":2},"title":"Enseigner la litt\u00e9ratie historique ?","author":"Lyonel Kaufmann","date":"22 f\u00e9vrier 2013","format":false,"excerpt":"St\u00e9phane L\u00e9vesque s'interroge et nous interroge concernant l'imp\u00e9ratif pour les \u00e9l\u00e8ves de savoir lire et comprendre l'information transmise par les m\u00e9dias sociaux sous forme de contenus num\u00e9riques textuelles et multim\u00e9dias. On peut associer ce travail \u00e0 d'autres \u00e9l\u00e9ments de l'histoire et de son enseignement \u00e0 l'\u00e8re digitale. Commun\u00e9ment appel\u00e9e \u00ablitt\u00e9racie\u00bb,\u2026","rel":"","context":"Dans &quot;Didactique&quot;","block_context":{"text":"Didactique","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":12213,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/10\/24\/suisse-atelier-decriture-wikipedia-lhistoire-des-chemins-de-fer-wikionrails\/","url_meta":{"origin":9636,"position":3},"title":"Suisse : Atelier d\u2019\u00e9criture Wikip\u00e9dia \u00ab L\u2019histoire des chemins de fer #Wikionrails","author":"Lyonel Kaufmann","date":"24 octobre 2016","format":false,"excerpt":"Samedi dernier 22 octobre, j'ai particip\u00e9 \u00e0 Berne \u00e0 l'atelier d'\u00e9criture Wikipedia, organis\u00e9 par les Documents Diplomatiques suisses (DDS, http:\/\/dodis.ch) aux Archives f\u00e9d\u00e9rales sur \u00ab L\u2019histoire des chemins de fer \u00bb. Dans ce premier article, je m'attacherai \u00e0 faire un bref compte rendu de cet atelier. Dans un prochain article,\u2026","rel":"","context":"Dans &quot;Histoire active&quot;","block_context":{"text":"Histoire active","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-active\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/10\/Image-24.10.16-00-01.jpeg?fit=1200%2C836&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/10\/Image-24.10.16-00-01.jpeg?fit=1200%2C836&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/10\/Image-24.10.16-00-01.jpeg?fit=1200%2C836&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/10\/Image-24.10.16-00-01.jpeg?fit=1200%2C836&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2016\/10\/Image-24.10.16-00-01.jpeg?fit=1200%2C836&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":13295,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2017\/09\/07\/enseigner-avec-le-numerique-lhistoire-des-femmes\/","url_meta":{"origin":9636,"position":4},"title":"Enseigner avec le num\u00e9rique : l&rsquo;histoire des femmes","author":"Lyonel Kaufmann","date":"7 septembre 2017","format":false,"excerpt":"A l\u2019occasion de le rentr\u00e9e scolaire, le bulletin \u00c9du_Num Histoire-g\u00e9ographie, No 38 propose une certain nombre de ressources en ligne en relation avec les programmes du cycle 4 invitant \u00e0 enseigner une histoire mixte. Des ressources sont \u00e9galement propos\u00e9s pour les Lyc\u00e9es professionnels. Les programmes de cycle 4 invitent, en\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/09\/Image-07.09.17-12-22.38cc6a525e5549bcae8ae77e9cef5f2d.jpeg?fit=500%2C281&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":15134,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2018\/11\/05\/colloque-scientifique-ludoviach-2019-des-ressources-numeriques-pour-ressourcer-la-pratique-du-16-au-18-avril-2019-yverdon-suisse\/","url_meta":{"origin":9636,"position":5},"title":"Colloque scientifique Ludovia#ch 2019 : Des ressources num\u00e9riques pour ressourcer la pratique du 16 au 18 avril 2019, Yverdon, Suisse","author":"Lyonel Kaufmann","date":"5 novembre 2018","format":false,"excerpt":"Apr\u00e8s une premi\u00e8re \u00e9dition r\u00e9ussie avec plus de 500 participant.e.s, Ludovia#CH revient en 2019 du 16 au 18 avril 2019 \u00e0 Yverdon-les-Bains. Vous trouverez ci-dessous l\u2019appel \u00e0 communication pour le colloque scientifique. L\u2019appel pour les ateliers est pr\u00e9vu pour fin novembre. L\u2019ouverture des inscriptions interviendra elle \u00e0 fin janvier 2019.\u2026","rel":"","context":"Dans &quot;Ludovia&quot;","block_context":{"text":"Ludovia","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/ludovia-2010\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/11\/DraggedImage.png?fit=1200%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/11\/DraggedImage.png?fit=1200%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/11\/DraggedImage.png?fit=1200%2C801&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/11\/DraggedImage.png?fit=1200%2C801&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/11\/DraggedImage.png?fit=1200%2C801&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/9636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=9636"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/9636\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/9896"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=9636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=9636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=9636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}