{"id":9771,"date":"2015-05-15T15:19:21","date_gmt":"2015-05-15T14:19:21","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/?p=9771"},"modified":"2015-05-15T15:19:21","modified_gmt":"2015-05-15T14:19:21","slug":"history-today-on-twitter","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2015\/05\/15\/history-today-on-twitter\/","title":{"rendered":"History Today on Twitter"},"content":{"rendered":"<p><a target='_blank' href='http:\/\/www.scoop.it\/t\/histoire\/p\/4043668297\/2015\/05\/15\/history-today-on-twitter'><img data-recalc-dims=\"1\" src=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/05\/0e93e75c-5363-47a5-b291-44fad8b41cbf.jpg\" class='alignleft' style='width: 100%'\/><\/a><\/p>\n<blockquote><p> Television has failed to embrace the latest research on the First World War. <a href=\"http:\/\/bit.ly\/1HfBj7E\" rel=\"nofollow\" target=\"_blank\">http:\/\/bit.ly\/1HfBj7E<\/a> pic.twitter.com\/r2XsuknszH<\/p><\/blockquote>\n<p>Source: <a target='_blank' href='https:\/\/twitter.com\/HistoryToday\/status\/598845691910291456'>twitter.com<\/a><\/p>\n<p>Article sur les comm&eacute;morations de 14-18 en Grande-Bretagne &nbsp;&agrave; la t&eacute;l&eacute;vision&nbsp;<\/p>\n<p>See on <a href='http:\/\/www.scoop.it\/t\/histoire\/p\/4043668297\/2015\/05\/15\/history-today-on-twitter'>Scoop.it<\/a> &#8211; <a href='http:\/\/www.scoop.it\/t\/histoire'>histoire<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Television has failed to embrace the latest research on the First World War. http:\/\/bit.ly\/1HfBj7E pic.twitter.com\/r2XsuknszH Source: twitter.com Article sur les comm&eacute;morations de 14-18 en Grande-Bretagne &nbsp;&agrave; la t&eacute;l&eacute;vision&nbsp; See on Scoop.it &#8211; histoire<\/p>\n","protected":false},"author":1,"featured_media":9770,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[13],"tags":[],"class_list":{"0":"post-9771","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-opinionsreflexions","8":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/05\/0e93e75c-5363-47a5-b291-44fad8b41cbf.jpg?resize=510%2C340&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/05\/0e93e75c-5363-47a5-b291-44fad8b41cbf.jpg?resize=510%2C340&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/05\/0e93e75c-5363-47a5-b291-44fad8b41cbf.jpg?fit=510%2C340&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-2xB","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":5266,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2012\/04\/10\/la-radio-et-la-television-en-suisse-histoire-de-la-societe-suisse-de-radiodiffusion-et-television-ssr-de-1983-a-2011-infoclio-ch\/","url_meta":{"origin":9771,"position":0},"title":"La radio et la t\u00e9l\u00e9vision en Suisse. Histoire de la Soci\u00e9t\u00e9 suisse de radiodiffusion et t\u00e9l\u00e9vision SSR de 1983 \u00e0 2011 &#124; infoclio.ch","author":"Lyonel Kaufmann","date":"10 avril 2012","format":false,"excerpt":"Via Scoop.it - histoireLes \u00e9ditions hier + jetzt annoncent la publication du troisi\u00e8me volume de l'Histoire de la Soci\u00e9t\u00e9 suisse de radiodiffusion, consacr\u00e9 \u00e0 la p\u00e9riode 1983 \u00e0 2011. Le troisi\u00e8me volume existe \u00e9galement sous forme d'une application Apple consultable sur iPhone et iPad, qui propose un acc\u00e8s interactif aux\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/07\/Ru6X4pDI4Pce3MCtWqiVjzl72eJkfbmt4t8yenImKBXEejxNn4ZJNZ2ss5Ku7Cxt.jpg?fit=203%2C308&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2983,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/07\/10\/revue-de-presse-du-july-10th\/","url_meta":{"origin":9771,"position":1},"title":"Revue de presse du July 10th","author":"Lyonel Kaufmann","date":"10 juillet 2010","format":false,"excerpt":"A partag\u00e9 Gallipoli and the Anzacs | Australians in war | World War 1. Site consacr\u00e9 au corps exp\u00e9ditionnaire australien \u00e0 la bataille de Galipoli A partag\u00e9 The Online Books Page : World War, 1914-1918. Une impressionnante collection d'ouvrages consultables en ligne, organis\u00e9e par sujet, et en anglais. Presque too\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3364,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2010\/12\/22\/images-du-siecle-des-lumieres-a-la-television-bernard-papin\/","url_meta":{"origin":9771,"position":2},"title":"Images du Si\u00e8cle des Lumi\u00e8res \u00e0 la t\u00e9l\u00e9vision &#124; Bernard Papin","author":"Lyonel Kaufmann","date":"22 d\u00e9cembre 2010","format":false,"excerpt":"Bernard Papin est Ma\u00eetre de conf\u00e9rences en sciences de l'information et de la communication, universit\u00e9 Paris Sud 11. Dans son activit\u00e9 scientifique, il s'int\u00e9resse \u00e0 la s\u00e9miologie et \u00e0 l'histoire de l'audiovisuel, plus particuli\u00e8rement \u00e0 la fiction t\u00e9l\u00e9visuelle (les genres du fictif , l'adaptation des \u0153uvres litt\u00e9raires \u00e0 la t\u00e9l\u00e9vision\u2026","rel":"","context":"Dans &quot;M\u00e9dias et technologies&quot;","block_context":{"text":"M\u00e9dias et technologies","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2010\/12\/Papin_Bernard_ImagesLumieresTV.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":18652,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2021\/12\/27\/living-book-about-history-pour-une-histoire-elargie-de-la-television\/","url_meta":{"origin":9771,"position":3},"title":"Living Book about History: Pour une histoire \u00e9largie de la t\u00e9l\u00e9vision","author":"Lyonel Kaufmann","date":"27 d\u00e9cembre 2021","format":false,"excerpt":"Dans le nouveau Living Book \u00ab Pour une histoire \u00e9largie de la t\u00e9l\u00e9vision \u00bb, Anne-Katrin Weber (Universit\u00e9 de B\u00e2le) et Fran\u00e7ois Vallotton (Universit\u00e9 de Lausanne) pr\u00e9sentent une perspective in\u00e9dite sur l'histoire de ce m\u00e9dium en constante \u00e9volution. Compos\u00e9 d'une introduction originale et d'une s\u00e9lection de ressources librement accessibles, le Living\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2021\/12\/377F7ED4-FAF4-465C-96A0-5EFD964A164B.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":210,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2007\/07\/25\/links-for-2007-07-25\/","url_meta":{"origin":9771,"position":4},"title":"Liens (25.07.2007)","author":"Lyonel Kaufmann","date":"25 juillet 2007","format":false,"excerpt":"TV5.org - Tour de France - m\u00e9moire du tour (1954-1997) TV5 a compil\u00e9 ses archives de la t\u00e9l\u00e9 publique concernant le Tour de France De 1954 \u00e0 1997. Il s\u2019agit de courtes s\u00e9quences de ce qui a \u00e9t\u00e9 diffus\u00e9 durant le journal t\u00e9l\u00e9vis\u00e9 \u00e0 diff\u00e9rentes \u00e9poques. Dans le contexte actuel\u2026","rel":"","context":"Dans &quot;Annuaire de sites&quot;","block_context":{"text":"Annuaire de sites","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/medias-et-technologies\/annuaire-de-sites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":7985,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2014\/04\/30\/le-petit-ecran-sinteresse-a-la-grande-guerre-france-info\/","url_meta":{"origin":9771,"position":5},"title":"Le petit \u00e9cran s&#039;int\u00e9resse \u00e0 la Grande Guerre &#8211; France Info","author":"Lyonel Kaufmann","date":"30 avril 2014","format":false,"excerpt":"See on Scoop.it - histoire La Grande Guerre n'a jamais vraiment eu les faveurs du petit \u00e9cran. Elle a \u00e9t\u00e9 \u00e9clips\u00e9e par le second conflit mondial qui a inspir\u00e9 nombre de films, d'ouvrages et de s\u00e9ries t\u00e9l\u00e9vis\u00e9e. On marque cette ann\u00e9e le centi\u00e8me anniversaire de ce qui reste dans l'histoire\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/9771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=9771"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/9771\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/9770"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=9771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=9771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=9771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}