{"id":9806,"date":"2015-06-14T17:49:18","date_gmt":"2015-06-14T16:49:18","guid":{"rendered":"https:\/\/lyonelkaufmann.ch\/histoire\/?p=9806"},"modified":"2015-06-25T01:49:34","modified_gmt":"2015-06-25T00:49:34","slug":"histoire-du-quebec-quand-philippe-couillard-joue-a-linstituteur-national","status":"publish","type":"post","link":"https:\/\/lyonelkaufmann.ch\/histoire\/2015\/06\/14\/histoire-du-quebec-quand-philippe-couillard-joue-a-linstituteur-national\/","title":{"rendered":"Histoire du Qu\u00e9bec : Quand Philippe Couillard joue \u00e0 l&rsquo;instituteur national"},"content":{"rendered":"<p><strong>Il est toujours particuli\u00e8rement int\u00e9ressant, voire fascinant, d\u2019observer que la vision historique, d\u00e9velopp\u00e9e par Philippe Couillard, chef du parti lib\u00e9ral qu\u00e9b\u00e9cois et actuel premier ministre de la Province du Qu\u00e9bec, trouve sa source dans un ouvrage aupr\u00e8s du premier manuel connu d\u2019histoire du Canada, r\u00e9dig\u00e9 par Joseph-Fran\u00e7ois Perrault en 1831\u2026 <\/strong><\/p>\n<p>Dans son \u00e9dition du 13 juin, Le journal <em>Le Devoir<\/em>, nous apprend que\u00a0devant quelque 1600 militants r\u00e9unis \u00e0 Montr\u00e9al pour le Congr\u00e8s du Parti lib\u00e9ral du Qu\u00e9bec, Philippe Couillard, premier ministre de la Province du Qu\u00e9bec, a livr\u00e9, samedi, un vibrant plaidoyer pour que les Qu\u00e9b\u00e9cois se r\u00e9approprient l\u2019histoire de leur pays, le Canada.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto;\" title=\"Philippe_Couillard_2014-11-11_E.jpg\" src=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/Philippe_Couillard_2014-11-11_E.jpg?resize=451%2C599\" alt=\"Philippe Couillard 2014 11 11 E\" width=\"451\" height=\"599\" border=\"0\" \/><\/p>\n<p style=\"text-align: center;\">Philippe Couillard, \u00e0 Qu\u00e9bec, lors de la c\u00e9r\u00e9monie du Jour du souvenir du 11 novembre 2014. Source : Wikipedia<\/p>\n<blockquote><p><em>\u00ab Nous ne renoncerons pas \u00e0 notre histoire ou notre avenir, \u00e0 un pays n\u00e9 de la collaboration et du d\u00e9sir d\u2019unit\u00e9. Une histoire qui a des moments si beaux qu\u2019il faudrait mieux les enseigner \u00e0 nos enfants. \u00bb<\/em><\/p>\n<p>La collaboration entre Louis-Hypolyte La Fontaine et Robert Bladwin inspire le chef lib\u00e9ral. <em>\u00ab Par exemple, cette histoire de Baldwin et de La Fontaine qui, ensemble, ont combattu pour le gouvernement responsable et d\u00e9mocratique, chacun de leur c\u00f4t\u00e9, mais ensemble \u00e9galement au point o\u00f9 un jour Baldwin a d\u00e9cid\u00e9 qu\u2019il allait \u00eatre candidat \u00e0 Rimouski et La Fontaine a d\u00e9cid\u00e9 d\u2019\u00eatre candidat \u00e0 Toronto parce qu\u2019ils portaient la d\u00e9mocratie et le gouvernement responsable. Ils ont \u00e9t\u00e9 \u00e9lus comme \u00e7a. \u00bb\u00a0<\/em><\/p>\n<p><em>\u00ab On voudrait nous faire oublier ces moments \u00bb, a poursuivi Philippe Couillard en visant ses adversaires ind\u00e9pendantistes. Le chef lib\u00e9ral a aussi parl\u00e9 des liens entre les Patriotes de Louis-Joseph Papineau et le mouvement de r\u00e9bellion du Haut-Canada, dirig\u00e9 par William Lyon Mackenzie, puis de l\u2019alliance entre John A. Macdonald et George-\u00c9tienne Cartier, qui a men\u00e9 \u00e0 la cr\u00e9ation de la f\u00e9d\u00e9ration canadienne en 1867. \u00ab On voudrait nous faire oublier cette histoire, renoncer \u00e0 l\u2019alliance entre Cartier et Macdonald qui a permis de jeter les bases de la f\u00e9d\u00e9ration, mais \u00e9galement de mettre en place des mesures qui assurent la promotion et la protection du caract\u00e8re fran\u00e7ais du Qu\u00e9bec. \u00bb<\/em><\/p>\n<p>(Source :\u00a0<a href=\"http:\/\/www.ledevoir.com\/politique\/quebec\/442722\/couillard-les-enfants-quebecois-devraient-mieux-connaitre-l-histoire-de-leur-pays-le-canada\">Couillard: les enfants qu\u00e9b\u00e9cois devraient mieux conna\u00eetre l&rsquo;histoire de leur pays, le Canada | Le Devoir<\/a>)<\/p><\/blockquote>\n<p>Cette d\u00e9claration de Philippe Couillard intervient alors que je lis l&rsquo;ouvrage <em>L\u2019Histoire nationale \u00e0 l\u2019\u00e9cole qu\u00e9b\u00e9coise. Regards sur deux si\u00e8cle d\u2019enseignement.<\/em> ((Bouvier, F., Allard, M., Aubin, P., &amp; Larouche, M.-C. (sous la direction de). (2012). <em>L\u2019Histoire nationale \u00e0 l\u2019\u00e9cole qu\u00e9b\u00e9coise. Regards sur deux si\u00e8cles d\u2019enseignement.<\/em> Qu\u00e9bec: Septentrion.)) Je ne peux que rapprocher ces d\u00e9clarations du premier manuel connu d\u2019histoire du Canada, r\u00e9dig\u00e9 par <a href=\"http:\/\/www.biographi.ca\/fr\/bio\/perrault_joseph_francois_7F.html\">Joseph-Fran\u00e7ois Perrault<\/a> en 1831 et observer que sa conception de l\u2019histoire traverse toujours les d\u00e9bats politiques qu\u00e9b\u00e9cois.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto;\" title=\"91koeQMZIBL._SL1500_.jpg\" src=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/91koeQMZIBL._SL1500_.jpg?resize=400%2C600\" alt=\"L'histoire nationale \u00e0 l'\u00e9cole qu\u00e9b\u00e9coise\" width=\"400\" height=\"600\" border=\"0\" \/><\/p>\n<p>Par ailleurs, il est fascinant d\u2019observer que, pour une partie de son r\u00e9cit, Perrault prend mod\u00e8le pour la p\u00e9riode du R\u00e9gime fran\u00e7ais (c. 1743-1763) sur un r\u00e9cit ant\u00e9rieur d\u2019un j\u00e9suite, Pierre-Fran\u00e7ois-Xavier Charlevoix, datant de 1744. Pour, le d\u00e9but du R\u00e9gime anglais (1763-1791), son mod\u00e8le est celui de l\u2019historien d\u2019origine britannique William Smith et de son <em>History of Canada : from its first descovery to the year 1791<\/em>\u00a0publi\u00e9 en 1815.<\/p>\n<p>Dans la pr\u00e9face \u00e0 sa deuxi\u00e8me partie de son Histoire du Canada, paru en 1832 ((Perrault, J-F. (1832). <em>Abr\u00e9g\u00e9 de l\u2019histoire du Canada. Deuxi\u00e8me partie : Depuis sa conqu\u00eate par les Anglais en 1759 et 1760 jusqu\u2019\u00e0 l\u2019\u00e9tablissement d\u2019une Chambre d\u2019assembl\u00e9e en 1792.<\/em> Qu\u00e9bec : P. &amp; W. Ruthven.)), il fournit son interpr\u00e9tation de son histoire du Canada. Aujourd\u2019hui encore, on y trouve son \u00e9cho dans les propos tenus par Philippe Couillard.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto;\" title=\"Perrault.png\" src=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/Perrault.png?resize=398%2C600\" alt=\"Perrault\" width=\"398\" height=\"600\" border=\"0\" \/><\/p>\n<blockquote><p><em>\u00abIl semble que la Providence m\u2019a pr\u00e9serv\u00e9 presque seul, de toute la g\u00e9n\u00e9ration existante lors de la Conqu\u00eate du Canada, pour rendre hommage aux Anglais de la conduite sage et judicieuse qu\u2019ils ont tenue envers les Canadiens; des gr\u00e2ces et faveurs que leur Rois leur ont accord\u00e9es, et des avantages qui sont r\u00e9sult\u00e9s aux uns et autres. <\/em><\/p>\n<p><em>Puisse ce petit ouvrage imprimer ces bienfaits dans le coeur de leurs Enfan[t]s, leur faire aimer et soutenir l\u2019int\u00e9r\u00eat d\u2019une Nation qui les a, en toutes occasions, bravement prot\u00e9g\u00e9, d\u00e9fendu, et n\u2019a cess\u00e9 d\u2019accumuler des faveurs sur le Pays.\u00bb<\/em><\/p>\n<p>(Perrault 1832 : pr\u00e9face)<\/p><\/blockquote>\n<p>Concernant l\u2019enseignement de l\u2019histoire au Qu\u00e9bec, cet ouvrage de Perrault est capital, car il va servir de mod\u00e8le \u00e0 de nombreux auteurs de manuels. Il en forme le mod\u00e8le dominant. Pour Michel Allard\u00a0((Allard, M. (2012). L\u2019enseignement de l\u2019histoire nationale (1831-1873). Du premier manuel au premier programme. In F. Bouvier, M. Allard, P. Aubin, &amp; M.-C. Larouche (sous la direction de),\u00a0<em>L\u2019Histoire nationale \u00e0 l\u2019\u00e9cole qu\u00e9b\u00e9coise. Regards sur deux si\u00e8cles d\u2019enseignement<\/em>\u00a0(pp. 23-70). Qu\u00e9bec: Septentrion, p. 32))<\/p>\n<blockquote><p><em>\u00abEn s\u2019inspirant d\u2019un historien britannique, il est \u00e0 l\u2019origine d\u2019une interpr\u00e9tation de l\u2019histoire nationale minimisant les cons\u00e9quences n\u00e9gatives et maximisant les effets positifs de la Conqu\u00eate britannique. Cette interpr\u00e9tation circule encore tant dans la soci\u00e9t\u00e9 qu\u00e9b\u00e9coise que dans les programmes d\u2019\u00e9tudes\u2026\u00bb<\/em><\/p><\/blockquote>\n<p>Et j\u2019ajouterai dans les discours de Philippe Couillard.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto;\" title=\"6580021-L.jpg\" src=\"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/6580021-L.jpg?resize=340%2C500\" alt=\"6580021 L\" width=\"340\" height=\"500\" border=\"0\" \/><\/p>\n<p>A cette interpr\u00e9tation de la Conqu\u00eate bonne-ententiste, l\u2019historien <a href=\"http:\/\/www.biographi.ca\/fr\/bio\/garneau_francois_xavier_9F.html\">Fran\u00e7ois-Xavier Garneau<\/a> opposera, au cours des ann\u00e9es 1850, une interpr\u00e9tation plus nationaliste au sens canadien-fran\u00e7ais. Cette histoire offre la deuxi\u00e8me trame interpr\u00e9tative majeure de l\u2019histoire du Canada fran\u00e7ais qui se d\u00e9veloppera du c\u00f4t\u00e9 des Ind\u00e9pendantistes qu\u00e9b\u00e9cois. ((Garneau, F.-X. (1856). <em>Abr\u00e9g\u00e9 de l\u2019histoire du Canada depuis sa d\u00e9couverte jusqu\u2019\u00e0 1840, \u00e0 l\u2019usage des maisons d\u2019\u00e9ducation<\/em>. Qu\u00e9bec: A. C\u00f4t\u00e9.))<\/p>\n<blockquote><p><em>\u00abLe premier grand nom \u00e0 retenir de ce XIXe si\u00e8cle tumultueux, apr\u00e8s celui de Papineau en qui s&rsquo;incarna l&rsquo;espoir de lib\u00e9ration politique, est celui de l&rsquo;historien Garneau en qui s&rsquo;incarna l&rsquo;\u00e9merveillement du pass\u00e9 fran\u00e7ais. Son Histoire du Canada, publi\u00e9e de 1845 \u00e0 1848, fut pour le Canada fran\u00e7ais l&rsquo;\u00e9quivalent de ce qu&rsquo;a \u00e9t\u00e9 le G\u00e9nie du christianisme pour le catholicisme fran\u00e7ais du XIXe si\u00e8cle. (&#8230;) L&rsquo;Histoire de Garneau fut \u00e0 la fois un plaidoyer et un acte de foi. L&rsquo;insucc\u00e8s de la r\u00e9volte de 1837-38 et sa dure r\u00e9pression avaient laiss\u00e9 toutes les classes de la population dans un profond d\u00e9senchantement. Les propositions du Rapport de Lord Durham visant \u00e0 l&rsquo;union des deux Canadas et \u00e0 une assimilation progressive de la population fran\u00e7aise par une massive immigration britannique semblaient compromettre irr\u00e9vocablement le destin de la nation canadienne-fran\u00e7aise. Pour contrecarrer l&rsquo;esprit de d\u00e9faitisme, Garneau entreprend de rappeler aux Canadiens fran\u00e7ais qu&rsquo;ils ont un pass\u00e9 et que ce pass\u00e9 est glorieux.\u00bb<\/em><\/p>\n<p>Falardeau, J.-C. (1964).\u00a0Un annonciateur de grandeur: Fran\u00e7ois-Xavier Garneau (1809-1866). In\u00a0<em>L&rsquo;essor des sciences sociales au Canada fran\u00e7ais.<\/em>\u00a0Qu\u00e9bec: Minist\u00e8re des Affaires culturelles, p. 14-15. Cit\u00e9 par <em>Encyclop\u00e9die de L\u2019Agora<\/em> (<a href=\"http:\/\/agora.qc.ca\/Dossiers\/Francois-Xavier_Garneau\">http:\/\/agora.qc.ca\/Dossiers\/Francois-Xavier_Garneau<\/a>)<\/p><\/blockquote>\n<p>Pour Garneau, la Conqu\u00eate ne produit pas que des bienfaits. Si la paix r\u00e8gne dans tout le pays apr\u00e8s 1760 lorsque les armes sont d\u00e9pos\u00e9es, ce calme est d\u00fb non \u00e0 l\u2019attitude des vainqueurs, mais, pour Garneau, au fait que <em>\u00ables habitants ruin\u00e9s, d\u00e9cim\u00e9s par le feu sur tant de champs de bataille, ne song\u00e8rent plus qu\u2019\u00e0 se renfermer dans leurs terres pour r\u00e9parer leurs pertes\u00bb<\/em> (Garneau 1856: 178).<\/p>\n<p>L\u2019ambition de Garneau est clairement affirm\u00e9e dans son <em>Discours pr\u00e9liminaire<\/em> de son ouvrage <em>Histoire du Canada depuis sa d\u00e9couverte jusqu\u2019\u00e0 nos jours<\/em>\u00a0((Garneau, F.-X. (1852).\u00a0<em>Histoire du Canada depuis sa d\u00e9couverte jusqu\u2019\u00e0 nos jours. <\/em>Qu\u00e9bec:\u00a0Imprim\u00e9 par J. Lovell.)):<\/p>\n<blockquote><p><em>\u00abSi l&rsquo;on envisage l&rsquo;histoire du Canada dans son ensemble, depuis Champlain jusqu&rsquo;\u00e0 nos jours, en voit qu&rsquo;elle se partage en deux grandes phases que divise le passage de cette colonie de la domination fran\u00e7aise \u00e0 la domination anglaise, et que signalent la premi\u00e8re, les guerres avec les Sauvages et les provinces qui forment aujourd&rsquo;hui les Etats-Unis; la seconde, la lutte politique et parlementaire des Canadiens <\/em>((dans le sens canadien-fran\u00e7ais))<em> pour leur conservation nationale. La diff\u00e9rence des armes, entre ces deux \u00e9poques, nous les montre sous deux points de vue distincts; mais c&rsquo;est sous le dernier qu&rsquo;ils m&rsquo;int\u00e9ressent davantage. Il y a quelque chose de touchant et de noble tout \u00e0 la fois \u00e0 d\u00e9fendre la nationalit\u00e9 de ses p\u00e8res, cet h\u00e9ritage sacr\u00e9 qu&rsquo;aucun peuple, quelque d\u00e9grad\u00e9 qu&rsquo;il f\u00fbt, n&rsquo;a jamais \u00f4s\u00ea r\u00e9pudier publiquement. Jamais cause plus grande et plus sainte n&rsquo;a inspir\u00e9 un c\u0153ur haut plac\u00e9, et m\u00e9rit\u00e9 la sympathie des hommes g\u00e9n\u00e9reux.<\/em><\/p>\n<p><em>[\u2026] \u00a0le Canada a \u00e9t\u00e9 soumis \u00e0 de grandes vicissitudes, qui ne sont pas de son fait, mais qui tiennent \u00e0 la nature de sa d\u00e9pendance coloniale, les progr\u00e8s n&rsquo;y marchent qu&rsquo;\u00e0 travers les obstacles, les secousses sociales, et une complication qu&rsquo;augmentent de nos jours la diff\u00e9rence des races mises en regard par la m\u00e9tropole; les haines, les pr\u00e9jug\u00e9s, l&rsquo;ignorance et les \u00e9carts des gouvernans et quelquefois des gouvern\u00e9s. Les auteurs de l&rsquo;union des deux provinces du Canada, projet\u00e9e en 1822 et ex\u00e9cut\u00e9e en 1840, ont \u00e9tay\u00e9 cette mesure de diverses raisons sp\u00e9cieuses pour couvrir d&rsquo;un voile l\u00e9gal une grande injustice. L&rsquo;Angleterre, qui ne veut voir dans les Canadiens fran\u00e7ais que des colons turbulens, des \u00e9trangers mal affectionn\u00e9s, feint de prendre pour des tentatives r\u00e9publicaines leur inqui\u00e9tude, leur attachement \u00e0 leurs institutions et \u00e0 leurs usages menac\u00e9s, artifice indigne d&rsquo;un grand peuple. L&rsquo;abolition de leur langue, et la restriction de leur franchise \u00e9lectorale pour les tenir, malgr\u00e9 leur nombre, dans la minorit\u00e9 et la suj\u00e9tion, ne prouvent que trop qu&rsquo;elle ne croit rien de ce qu&rsquo;elle dit, et que ni les trait\u00e9s, ni les actes publics les plus solennels, n&rsquo;ont pu l&#8217;emp\u00eacher de violer des droits d&rsquo;autant plus sacr\u00e9s qu&rsquo;ils servaient d&rsquo;\u00e9gide au faible contre le fort.<\/em><\/p>\n<p><em>Mais quoiqu&rsquo;on fasse, la destruction d&rsquo;un peuple n&rsquo;est pas chose aussi facile qu&rsquo;on pourrait se l&rsquo;imaginer. <\/em><\/p>\n<p><em>Nous sommes loin de croire que notre nationalit\u00e9 soit \u00e0 l&rsquo;abri de tout danger. Comme bien d&rsquo;autres nous avons eu nos illusions \u00e0 cet \u00e9gard, illusions qui s&rsquo;envolent chaque jour devant les intrigues, et la corruption qui rappellent certaines \u00e9poques de l&rsquo;histoire de l&rsquo;Irlande.<\/em><\/p>\n<p><em>Mais, dans le vrai, l&rsquo;existence du peuple canadien n&rsquo;est pas plus douteuse aujourd&rsquo;hui, qu&rsquo;elle ne l&rsquo;\u00e9tait il y a un demi si\u00e8cle. Notre destin\u00e9e est de lutter sans cesse, tant\u00f4t contre les barbares qui couvrent l&rsquo;Am\u00e9rique, tant\u00f4t contre une autre race qui, jet\u00e9e en plus grand nombre que nous dans ce continent, y a acquis depuis longtemps une pr\u00e9pond\u00e9rance, qui n&rsquo;a plus rien \u00e0 craindre. Nous ne comptions que 60,000 \u00e2mes en 1760 et nous d\u00e9passons aujourd&rsquo;hui 700,000.\u00bb<\/em><\/p><\/blockquote>\n<p>Les termes du d\u00e9bat sont ainsi pos\u00e9s d\u00e8s le 19e si\u00e8cle et il se poursuit aujourd\u2019hui. Philippe Couillard a fait le choix\u00a0de la Conqu\u00eate bonne-ententiste alors que d\u2019autres pr\u00e9sentent la Conqu\u00eate de 1760 <em>\u00abcomme une d\u00e9faite militaire fondamentale ayant entrav\u00e9 toute la suite de l\u2019histoire du Qu\u00e9bec par ses cons\u00e9quences politiques, sociales et \u00e9conomiques. Seule l\u2019ind\u00e9pendance du Qu\u00e9bec pourrait pallier \u00e9ventuellement cet \u00e9tat de fait\u00bb<\/em> ((<em>L\u2019Histoire nationale \u00e0 l\u2019\u00e9cole qu\u00e9b\u00e9coise<\/em> : 12)). Dans les deux camps, l\u2019histoire est instrumentalis\u00e9 pour appuyer sa vision politique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il est toujours particuli\u00e8rement int\u00e9ressant, voire fascinant, d\u2019observer que la vision historique, d\u00e9velopp\u00e9e par Philippe Couillard, chef du parti lib\u00e9ral qu\u00e9b\u00e9cois et actuel premier ministre de la Province du Qu\u00e9bec, trouve sa source dans un ouvrage aupr\u00e8s du premier manuel connu d\u2019histoire du Canada, r\u00e9dig\u00e9 par Joseph-Fran\u00e7ois Perrault en 1831\u2026 Dans son \u00e9dition du 13 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9803,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,11,13],"tags":[],"class_list":{"0":"post-9806","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-didactique","8":"category-nouvelles-de-lhistoire","9":"category-opinionsreflexions","10":"entry"},"jetpack_publicize_connections":[],"featured_image_src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/91koeQMZIBL._SL1500_.jpg?resize=400%2C400&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/91koeQMZIBL._SL1500_.jpg?resize=400%2C600&ssl=1","author_info":{"display_name":"Lyonel Kaufmann","author_link":"https:\/\/lyonelkaufmann.ch\/histoire\/author\/lyonelk\/"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2015\/06\/91koeQMZIBL._SL1500_.jpg?fit=400%2C600&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1rJVM-2ya","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":15157,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2018\/11\/07\/lantisemitisme-et-lhospitalite-canadienne-et-quebecoise-histoireengageeca\/","url_meta":{"origin":9806,"position":0},"title":"L\u2019antis\u00e9mitisme et l\u2019hospitalit\u00e9 canadienne et qu\u00e9b\u00e9coise \u2013 HistoireEngag\u00e9e.ca","author":"Lyonel Kaufmann","date":"7 novembre 2018","format":false,"excerpt":"Par Christine Chevalier-Caron, candidate au doctorat en histoire \u00e0 l\u2019Universit\u00e9 du Qu\u00e9bec \u00e0 Montr\u00e9al et Philippe N\u00e9m\u00e9h-Nombr\u00e9, candidat au doctorat en sociologie \u00e0 l\u2019Universit\u00e9 de Montr\u00e9al \u00ab\u00a0Suite \u00e0 l\u2019attentat qui a eu lieu \u00e0 la synagogue Tree of life de Pittsburgh samedi dernier, et alors que le premier ministre Justin\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/11\/3E33AD5E-7C2E-419D-8471-B70952A18753.4907c756bca64e70ae6a8c00fe41a84e.jpeg?fit=900%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/11\/3E33AD5E-7C2E-419D-8471-B70952A18753.4907c756bca64e70ae6a8c00fe41a84e.jpeg?fit=900%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/11\/3E33AD5E-7C2E-419D-8471-B70952A18753.4907c756bca64e70ae6a8c00fe41a84e.jpeg?fit=900%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2018\/11\/3E33AD5E-7C2E-419D-8471-B70952A18753.4907c756bca64e70ae6a8c00fe41a84e.jpeg?fit=900%2C600&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":6460,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2012\/11\/27\/toute-commemoration-est-elle-une-question-sociale-vive-chronique-no-137\/","url_meta":{"origin":9806,"position":1},"title":"Toute comm\u00e9moration est-elle une question sociale vive? &#124; Chronique no 137","author":"Lyonel Kaufmann","date":"27 novembre 2012","format":false,"excerpt":"Que ce soit en France ou au Qu\u00e9bec les derni\u00e8res ou prochaines comm\u00e9morations sont l'objet de controverses.\u00a0\u00a0Un peu partout nous sommes en pr\u00e9sence de la concurrence des m\u00e9moires.\u00a0Avec en filigrane deux questions : toute comm\u00e9moration est-elle une question sociale vive? Comment les aborder d\u00e8s lors en classe?\u00a0 Au mois d'octobre,\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2012\/11\/image3.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11427,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2016\/05\/13\/revue-de-presse-enseignement-de-lhistoire-au-secondaire-la-reforme-est-reportee-giuseppe-valiante-education\/","url_meta":{"origin":9806,"position":2},"title":"Qu\u00e9bec : Enseignement de l&rsquo;histoire au secondaire: la r\u00e9forme est report\u00e9e","author":"Lyonel Kaufmann","date":"13 mai 2016","format":false,"excerpt":"La r\u00e9forme de l'enseignement de l'histoire du Qu\u00e9bec et du Canada au secondaire n'aura pas lieu \u00e0 l'automne prochain comme pr\u00e9vu, a confirm\u00e9 le minist\u00e8re de l'\u00c9ducation, jeudi. Au lieu de cela, le minist\u00e8re effectuera des changements au programme pour qu'il refl\u00e8te mieux les minorit\u00e9s culturelles et linguistiques de la\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":12729,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2017\/01\/27\/quebec-les-heritages-de-la-revolution-tranquille-histoire-engagee\/","url_meta":{"origin":9806,"position":3},"title":"Qu\u00e9bec : Les h\u00e9ritages de la R\u00e9volution tranquille | Histoire Engag\u00e9e","author":"Lyonel Kaufmann","date":"27 janvier 2017","format":false,"excerpt":"Le mercredi 14 septembre, le site qu\u00e9b\u00e9cois Histoire Engag\u00e9e a d\u00e9but\u00e9 la publication d\u2019un dossier sous la direction de Marie-Andr\u00e9e Bergeron et Vincent Lambert portant sur\u00a0les h\u00e9ritages de la R\u00e9volution tranquille\u00a0au Qu\u00e9bec. Voici l\u2019introduction au dossier r\u00e9dig\u00e9e par Vincent Lambert. \u00ab\u00a0L\u2019h\u00e9ritage de la R\u00e9volution tranquille n\u2019a peut-\u00eatre jamais \u00e9t\u00e9 si\u2026","rel":"","context":"Dans &quot;Histoire savante&quot;","block_context":{"text":"Histoire savante","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/didactique\/histoire-savante\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/01\/Image-27.01.17-18-23.jpeg?fit=1200%2C480&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/01\/Image-27.01.17-18-23.jpeg?fit=1200%2C480&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/01\/Image-27.01.17-18-23.jpeg?fit=1200%2C480&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/01\/Image-27.01.17-18-23.jpeg?fit=1200%2C480&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/lyonelkaufmann.ch\/histoire\/wp-content\/uploads\/2017\/01\/Image-27.01.17-18-23.jpeg?fit=1200%2C480&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6474,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2012\/11\/28\/revue-de-presse-lhistoire-du-quebec-racontee-par-les-eleves-du-secondaire-chaire-de-recherche-du-canada-en-histoire-et-economie-politique-du-quebec-contemporain\/","url_meta":{"origin":9806,"position":4},"title":"Revue de presse : L\u2019histoire du Qu\u00e9bec racont\u00e9e par les \u00e9l\u00e8ves du secondaire &#124; Chaire de recherche du Canada en histoire et \u00e9conomie politique du Qu\u00e9bec contemporain","author":"Lyonel Kaufmann","date":"28 novembre 2012","format":false,"excerpt":"Les jeunes, que l\u2019on dit amn\u00e9siques et d\u00e9ficitaires sur le plan de la culture historique, ne sont pas sans poss\u00e9der une certaine vision de l\u2019histoire du Qu\u00e9bec. Quelle est cette vision ? Est-elle diff\u00e9rente selon que l\u2019on est francophone, anglophone ou allophone ? \u00c9volue-t-elle apr\u00e8s que les jeunes aient suivi\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":18551,"url":"https:\/\/lyonelkaufmann.ch\/histoire\/2021\/12\/01\/quebec-vers-une-meilleure-place-pour-les-autochtones-dans\/","url_meta":{"origin":9806,"position":5},"title":"Qu\u00e9bec &#8211; Vers une meilleure place pour les Autochtones dans l&rsquo;enseignement","author":"Lyonel Kaufmann","date":"1 d\u00e9cembre 2021","format":false,"excerpt":"Le gouvernement du Qu\u00e9bec va revoir l\u2019enseignement primaire et secondaire pour faire une plus grande place \u00e0 l\u2019histoire et aux traditions autochtones. Selon le ministre de l\u2019\u00c9ducation, Jean-Fran\u00e7ois Roberge, cette r\u00e9vision de l\u2019ensemble des programmes p\u00e9dagogiques va faire en sorte \u00abque les jeunes autochtones s\u2019\u00e9panouissent, qu\u2019ils prennent leur place dans\u2026","rel":"","context":"Dans &quot;Nouvelles de l'histoire&quot;","block_context":{"text":"Nouvelles de l'histoire","link":"https:\/\/lyonelkaufmann.ch\/histoire\/category\/nouvelles-de-lhistoire\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/9806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/comments?post=9806"}],"version-history":[{"count":0,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/posts\/9806\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media\/9803"}],"wp:attachment":[{"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/media?parent=9806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/categories?post=9806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonelkaufmann.ch\/histoire\/wp-json\/wp\/v2\/tags?post=9806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}